{"id":5912,"date":"2017-06-15T15:09:53","date_gmt":"2017-06-15T15:09:53","guid":{"rendered":"http:\/\/vr-room.ch\/?p=5912"},"modified":"2017-06-15T15:09:53","modified_gmt":"2017-06-15T15:09:53","slug":"space-junkies-vr-arcade-shooter-mit-jetpack-action","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/","title":{"rendered":"Space Junkies: sparatutto arcade in VR con azione jetpack"},"content":{"rendered":"<p><a href=\"https:\/\/www.ubisoft.com\/en-US\/company\/overview.aspx\">Ubisoft<\/a> annunciato al <a href=\"http:\/\/www.e3expo.com\/takeover\">E3 2017<\/a> in Los Angeles &#8222;Space Junkies&#8220; an. Das ist ein Arcade-Shooter mit Jetpack-Action, der exklusiv f\u00fcr die Virtual Reality entwickelt wird. Das Spiel bietet laut Ubisoft einen intuitiven und rasanten Multiplayer-Spass in dreidimensionalen, orbitalen Arenen. Zudem wird eine volle VR-K\u00f6rpersteuerung unterst\u00fctzt, wodurch die Spieler in intensive und schwerelose K\u00e4mpfe eintauchen sollen. &#8222;Space Junkies&#8220; wird im Fr\u00fchjahr 2018 f\u00fcr Oculus Rift mit Touch und HTC Vive erscheinen.<\/p>\n<p>&#8222;Space Junkies&#8220; wird von Ubisoft Montpellier entwickelt und die Macher stellen 1-vs.-1- und 2-vs.-2-Gefechte im &#8222;Dirty Bowl&#8220; in Aussicht.\u00a0 Das ist eine Sammlung von Weltraumarenen, die dynamisch auf die Aktionen der Spieler reagieren und ihnen erlauben, sich in jede Richtung zu bewegen und anzugreifen. Das Spiel beinhaltet zudem ein Arsenal an ausgefallenen Waffen, mit denen Angriffe variiert werden k\u00f6nnen, um Gegner effektiv auszuschalten. &#8222;Space Junkies&#8220; nutzt eine firmeneigene Virtual Reality-Engine namens &#8222;Brigitte&#8220;. Die Technik wurde so konzipiert, dass sie sich weiterentwickeln und an die neuen Anforderungen bei der Erschaffung von VR-Welten anpassen kann.<\/p>\n<p>&#8222;Space Junkies richtet sich an VR-Spieler, die nach etwas Neuem und Verr\u00fccktem suchen und wird ihren Kampfgeist anregen,&#8220; sagt Adrian Lacey, Producer bei Ubisoft Montpellier. &#8222;Wir erschaffen einen kompetitiven, adrenalingeladenen Multiplayer-Shooter, der nicht von dieser Welt ist, und der den Spielern die Freiheit gew\u00e4hrt, die Fortschritte bei den Spieler-Maschine-Schnittstellen voll auszunutzen, so wie es nur in Virtual Reality m\u00f6glich ist.&#8220;<\/p>\n<p>Fonte: Comunicato stampa<\/p>","protected":false},"excerpt":{"rendered":"Ubisoft k\u00fcndigte auf der E3 2017 in Los Angeles &#8222;Space Junkies&#8220; an. Das ist ein Arcade-Shooter mit Jetpack-Action,&hellip;","protected":false},"author":11,"featured_media":5914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-5912","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Ubisoft k\u00fcndigte auf der E3 2017 in Los Angeles &#8222;Space Junkies&#8220; an. Das ist ein Arcade-Shooter mit Jetpack-Action,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-15T15:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1887\" \/>\n\t<meta property=\"og:image:height\" content=\"1047\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action\",\"datePublished\":\"2017-06-15T15:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/\"},\"wordCount\":244,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Spacejunkies.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/\",\"name\":\"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Spacejunkies.jpg\",\"datePublished\":\"2017-06-15T15:09:53+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Spacejunkies.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Spacejunkies.jpg\",\"width\":1887,\"height\":1047},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/space-junkies-vr-arcade-shooter-mit-jetpack-action\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/","og_locale":"it_IT","og_type":"article","og_title":"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News","og_description":"Ubisoft k\u00fcndigte auf der E3 2017 in Los Angeles &#8222;Space Junkies&#8220; an. Das ist ein Arcade-Shooter mit Jetpack-Action,&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-06-15T15:09:53+00:00","og_image":[{"width":1887,"height":1047,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michael","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action","datePublished":"2017-06-15T15:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/"},"wordCount":244,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg","articleSection":["Games"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/","url":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/","name":"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg","datePublished":"2017-06-15T15:09:53+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/06\/Spacejunkies.jpg","width":1887,"height":1047},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/fr\/2017\/06\/15\/space-junkies-vr-arcade-shooter-mit-jetpack-action\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Space Junkies: VR-Arcade-Shooter mit Jetpack-Action"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/it\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/5912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=5912"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/5912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/5914"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=5912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=5912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=5912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}