{"id":3018,"date":"2016-10-28T13:43:18","date_gmt":"2016-10-28T13:43:18","guid":{"rendered":"http:\/\/vr-room.ch\/?p=3018"},"modified":"2017-01-12T16:05:00","modified_gmt":"2017-01-12T16:05:00","slug":"leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/","title":{"rendered":"Attenzione ai topi di biblioteca! Vivere le storie attraverso la realt\u00e0 virtuale"},"content":{"rendered":"[g1_lead]\n<p>Mit E-Readern, Buch-Apps f\u00fcr Handys und B\u00fcchern in <a href=\"http:\/\/vr-room.ch\/virtual-reality-glossar\/\">Augmented Reality<\/a> wurden bereits vor vielen Jahren erste Schritte in Richtung virtuelles Lesevergn\u00fcgen gemacht. Wird bei manchen alternativen Lesem\u00f6glichkeiten das Lesen eines Buches so gut wie m\u00f6glich nachempfunden, so sch\u00f6pfen andere Methoden das Potential der Ger\u00e4te aus, um f\u00fcr den Leser ein neues Erlebnis zu kreieren. Sich ganz in ein Buch zu vertiefen, das einen in fremde Welten entf\u00fchrt, passt sehr gut zu den Erfahrungen, die Virtual Reality bietet. Kein Wunder also, dass jetzt einiges in diesem Bereich l\u00e4uft.<\/p>\n[\/g1_lead]\n<p>Eintauchen in die Szenerie eines Buches kann man zum Beispiel mit Spielen wie <a href=\"http:\/\/store.steampowered.com\/app\/457660\/\">Andromedum<\/a>. Der Leser findet sich in einer Welt wieder, die genau zu der Stelle im Buch passt und erlebt somit die Handlung hautnah. In Vivepaper, einer App f\u00fcr das HTC Vive, die sich mehr auf virtuelle Magazine konzentriert, ist es sogar m\u00f6glich, sich ein Bild aus der aktuellen Lekt\u00fcre in den Hintergrund zu holen und zu bewegen, um es sich genauer anzusehn. Um das Abenteuer zu beginnen, muss anfangs lediglich ein passender QR-Code gescannt werden. Wer jetzt gleich loslegen will, muss leider noch etwas warten, da HTC die App zun\u00e4chst im chinesischen Viveport-Store erh\u00e4ltlich ist.<\/p>\n<p>Wer es allerdings lieber etwas interaktiver hat, kommt nat\u00fcrlich auch auf seine Kosten. 2014 verriet John Carmack, CTO bei Oculus VR, er arbeite an einem Comicbuchladen, der komplett nur im virutellen Bereich existiere. W\u00e4hrend dieses Projekt ungl\u00fccklicherweise im Sand verlief, haben inzwischen andere Entwickler die Idee weitergedacht und ganze Graphic Novels in VR inszeniert. Ein Beispiel daf\u00fcr sind <a href=\"http:\/\/sens-vr.com\/\">SENS VR<\/a> und <a href=\"http:\/\/virtualnovelgame.com\/\">Virtual Novel<\/a>. SENS VR ist ein Spiel basierend auf der gleichnamigen Graphic Novel S.E.N.S. von Marc-Antoine Mathieu. Der Spieler bewegt sich in einem Labyrinth aus abstrakten Pfeilen und muss sich seinen Weg bahnen. Virtual Novel hingegen greift mit seinem Konzept die ber\u00fchmten japanischen spielbaren Visual Novels auf, und l\u00e4sst den Spieler mit anderen Charakteren interagieren, um in der Geschichte voran zu kommen.<\/p>\n<p>Genauso unterschiedlich wie die Herangehensweisen an das Thema, so verschieden sind auch die Erfahrungen, die mit virtuellen B\u00fcchern gemacht werden k\u00f6nnen. Doch wie in so vielen Bereichen rund um Virtual Reality steckt auch hier noch alles in den Kinderschuhen. Wir freuen uns auf alles was noch kommt.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3018-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=i8iLCuqx4wk&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=i8iLCuqx4wk\">https:\/\/www.youtube.com\/watch?v=i8iLCuqx4wk<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>Quellen: Imbanova Entertainment Inc., VR focus, Virtual Novel, HTC, Steam<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"[g1_lead] Mit E-Readern, Buch-Apps f\u00fcr Handys und B\u00fcchern in Augmented Reality wurden bereits vor vielen Jahren erste Schritte&hellip;\n","protected":false},"author":4,"featured_media":3846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-3018","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"[g1_lead] Mit E-Readern, Buch-Apps f\u00fcr Handys und B\u00fcchern in Augmented Reality wurden bereits vor vielen Jahren erste Schritte&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-28T13:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-12T16:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/\"},\"author\":{\"name\":\"Celina\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/25ce425e1dadbba02720307df84e8eef\"},\"headline\":\"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality\",\"datePublished\":\"2016-10-28T13:43:18+00:00\",\"dateModified\":\"2017-01-12T16:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/\"},\"wordCount\":428,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/vrroomandromedum-scaled.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/\",\"name\":\"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/vrroomandromedum-scaled.jpg\",\"datePublished\":\"2016-10-28T13:43:18+00:00\",\"dateModified\":\"2017-01-12T16:05:00+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/25ce425e1dadbba02720307df84e8eef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/vrroomandromedum-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/vrroomandromedum-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2016\\\/10\\\/28\\\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/25ce425e1dadbba02720307df84e8eef\",\"name\":\"Celina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Celina_Avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Celina_Avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Celina_Avatar-96x96.jpg\",\"caption\":\"Celina\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/celina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/","og_locale":"it_IT","og_type":"article","og_title":"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News","og_description":"[g1_lead] Mit E-Readern, Buch-Apps f\u00fcr Handys und B\u00fcchern in Augmented Reality wurden bereits vor vielen Jahren erste Schritte&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2016-10-28T13:43:18+00:00","article_modified_time":"2017-01-12T16:05:00+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg","type":"image\/jpeg"}],"author":"Celina","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Celina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/"},"author":{"name":"Celina","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/25ce425e1dadbba02720307df84e8eef"},"headline":"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality","datePublished":"2016-10-28T13:43:18+00:00","dateModified":"2017-01-12T16:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/"},"wordCount":428,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg","articleSection":["Entertainment"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/","url":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/","name":"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg","datePublished":"2016-10-28T13:43:18+00:00","dateModified":"2017-01-12T16:05:00+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/25ce425e1dadbba02720307df84e8eef"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/vrroomandromedum-scaled.jpg","width":2560,"height":1810},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2016\/10\/28\/leseratten-aufgepasst-geschichten-erleben-durch-virtual-reality\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Leseratten aufgepasst! Geschichten erleben durch Virtual Reality"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/25ce425e1dadbba02720307df84e8eef","name":"Celina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Celina_Avatar-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Celina_Avatar-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Celina_Avatar-96x96.jpg","caption":"Celina"},"url":"https:\/\/vr-room.ch\/it\/author\/celina\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/3018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=3018"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/3018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/3846"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=3018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=3018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=3018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}