{"id":16212,"date":"2020-01-21T09:02:03","date_gmt":"2020-01-21T09:02:03","guid":{"rendered":"https:\/\/vr-room.ch\/?p=16212"},"modified":"2020-01-17T09:23:02","modified_gmt":"2020-01-17T09:23:02","slug":"im-landesmuseum-die-gaming-geschichte-erleben","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","title":{"rendered":"Scoprite la storia del gioco al Landesmuseum"},"content":{"rendered":"<h3 id=\"eine-neue-ausstellung-im-landesmuseum-zeigt-vom-17-01-bis-13-04-2020-die-geschichte-der-videogames-waehrend-der-letzten-50-jahre-die-besucher-koennen-mitspielen-und-auch-vr-kann-ausprobiert-we\">Una nuova mostra al Landesmuseum illustra la storia dei videogiochi negli ultimi 50 anni dal 17.01. al 13.04.2020. I visitatori potranno giocare e provare anche la VR.<\/h3>\n<p><!--more--><\/p>\n<p>Solo qualche decennio fa, i videogiochi erano considerati un espediente scientifico. Oggi, il gioco \u00e8 diventato una delle attivit\u00e0 di svago pi\u00f9 popolari. Tra il 2016 e il 2019, il fatturato di questa industria ancora giovane \u00e8 aumentato di circa 22 miliardi, raggiungendo quasi 123 miliardi di dollari, un successo superiore a quello dell'industria cinematografica di Hollywood, ad esempio. Il Landesmuseum di Zurigo dedica una mostra a questo straordinario fenomeno.<\/p>\n<h3 id=\"vom-tennis-fuer-2-ueber-grosse-arcaden\">Dal tennis per 2 alle grandi sale giochi....<\/h3>\n<p>Oggi circa 2,5 miliardi di persone giocano. Si tratta di un terzo della popolazione mondiale. Il fascino dei videogiochi \u00e8 iniziato negli anni '50 negli Stati Uniti. William Higinbotham rese possibile a tutti coloro che non amavano lo sport di giocare a tennis comodamente seduti sul divano. Il \"Tennis for Two\" del fisico fu il secondo videogioco al mondo e il vero inizio dello sviluppo. Al pi\u00f9 tardi negli anni '70, i giochi erano diventati un serio fattore economico.<\/p>\n<p>I giochi elettronici sono entrati nel salotto di casa e sono stati commercializzati come attivit\u00e0 per la famiglia. Allo stesso tempo, i videogiochi si affermarono anche negli spazi pubblici. Nelle sale giochi, divennero una seria concorrenza per i flipper che erano stati popolari fino a quel momento. Stava nascendo un'epoca d'oro: L'era dei giochi arcade. Nei ristoranti, nei centri commerciali o negli aeroporti si poteva giocare a giochi come \"Pac-Man\" o \"Space Invaders\" e molti contemporanei si giocavano tutti i soldi della paghetta con le popolari scatole.<\/p>\n<h3 id=\"zu-partys-und-schlussendlich-vr\">... alle feste e infine alla VR<\/h3>\n<p>Un decennio dopo, si tennero i primi LAN party. I giocatori si incontravano e collegavano i loro computer tramite una rete locale per giocare insieme. A volte questi gruppi riempivano intere sale. Allo stesso tempo, l'industria informatica svilupp\u00f2 dispositivi mobili, rendendo possibile giocare in movimento e online. Nel nuovo millennio, i videogiochi sono stati finalmente combinati con la realt\u00e0 virtuale. L'immersione completa nei mondi di gioco era un'esperienza completamente nuova.<\/p>\n<p>\"La selezione degli oggetti esposti per gli anni 2010 \u00e8 stata pi\u00f9 difficile\", afferma il co-curatore Michael Kempf. \"Alla fine abbiamo deciso per una sala di pura realt\u00e0 virtuale, perch\u00e9 molti dei nostri visitatori probabilmente non hanno le cuffie VR a casa e possono provarle qui\".<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-16214\" src=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-300x200.jpg\" alt=\"\" width=\"465\" height=\"310\" srcset=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-300x200.jpg 300w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-768x512.jpg 768w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-1024x683.jpg 1024w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-1110x740.jpg 1110w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-730x487.jpg 730w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-539x359.jpg 539w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-350x233.jpg 350w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-254x169.jpg 254w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-125x83.jpg 125w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/p>\n<p>Ruppert ha sviluppato un videogioco appositamente per la mostra, che si basa sull'opera <a href=\"https:\/\/www.landesmuseum.ch\/games\" target=\"_blank\" rel=\"noopener noreferrer\">Sito web del Museo Nazionale<\/a> pu\u00f2 essere giocato. \"Volevamo testare come le persone reagiscono alla pubblicit\u00e0 attraverso un gioco\", spiega la game designer svizzera Alice Ruppert.<\/p>\n<h3 id=\"kritischer-blick\">Visione critica<\/h3>\n<p>\"Quando abbiamo progettato la mostra, avevamo in mente un pubblico giovane, ad esempio le scolaresche, per le quali \u00e8 molto interessante grazie alla sua interattivit\u00e0\", afferma Stuber. Ma \u00e8 interessante anche per un pubblico pi\u00f9 adulto, e non solo per il fattore nostalgia. \"I nonni possono visitare la mostra con i loro nipoti e lasciare che i bambini spieghino loro le cose\", dice Michael Kempf.<\/p>\n<p>Ma la mostra getta anche uno sguardo critico sullo sviluppo dei giochi nel corso degli anni. Sui numerosi schermi distribuiti nelle sale, la categoria \"tossico\" affronta temi come la dipendenza dal gioco o la violenza nei videogiochi.<\/p>\n<p>Le postazioni di gioco invitano i visitatori a immergersi in mondi virtuali e a provare i giochi stessi. L'ingresso \u00e8 gratuito per i giovani fino a 16 anni e costa 10 franchi svizzeri per gli adulti. Con queste premesse, giochiamo!<\/p>\n<p>Fonte: Museo Nazionale, 20 minuti<\/p>","protected":false},"excerpt":{"rendered":"Una nuova mostra al Museo di Stato, dal 17 gennaio al 13 aprile 2020, illustrer\u00e0 la storia dei videogiochi negli ultimi 50...","protected":false},"author":12,"featured_media":16213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-16212","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Eine neue Ausstellung im Landesmuseum zeigt vom 17.01. bis\u00a0 13.04.2020 die Geschichte der Videogames w\u00e4hrend der letzten 50&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T09:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Im Landesmuseum die Gaming-Geschichte erleben\",\"datePublished\":\"2020-01-21T09:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"},\"wordCount\":553,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\",\"name\":\"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"datePublished\":\"2020-01-21T09:02:03+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Landesmuseum die Gaming-Geschichte erleben\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","og_locale":"it_IT","og_type":"article","og_title":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","og_description":"Eine neue Ausstellung im Landesmuseum zeigt vom 17.01. bis\u00a0 13.04.2020 die Geschichte der Videogames w\u00e4hrend der letzten 50&hellip;","og_url":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-01-21T09:02:03+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Im Landesmuseum die Gaming-Geschichte erleben","datePublished":"2020-01-21T09:02:03+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"},"wordCount":553,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","articleSection":["Schweiz"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","url":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","name":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","datePublished":"2020-01-21T09:02:03+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Im Landesmuseum die Gaming-Geschichte erleben"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/16212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=16212"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/16212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/16213"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=16212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=16212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=16212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}