{"id":12970,"date":"2019-02-28T09:00:20","date_gmt":"2019-02-28T09:00:20","guid":{"rendered":"http:\/\/vr-room.ch\/?p=12970"},"modified":"2019-02-28T09:00:20","modified_gmt":"2019-02-28T09:00:20","slug":"kingdom-hearts-vr-experience-erschienen","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/","title":{"rendered":"L'esperienza VR di Kingdom Hearts \u00e8 disponibile"},"content":{"rendered":"<p>Purtroppo ci sono stati uno o due rinvii, ma ora \u00e8 finalmente arrivato il momento: Square Enix ha rilasciato la versione gratuita del gioco. <a href=\"http:\/\/vr-room.ch\/it\/2018\/12\/10\/termin-kingdom-hearts-vr-experience\/\">&#8222;Kingdom Hearts VR Experience&#8220;<\/a> in esclusiva per PlayStation VR.<\/p>\n<p>Der kostenlose Download der &#8222;Kingdom Hearts VR Experience&#8220; ist 3,25 GB gross und im <a href=\"https:\/\/store.playstation.com\/\">PlayStation Store<\/a> erh\u00e4ltlich. Die &#8222;Kingdom Hearts: VR Experience&#8220; ist ein 10 Minuten langes und interaktives Virtual Reality-Musikvideo, das auf die Geschichte der beliebten &#8222;Kingdom Hearts&#8220;-Serie zur\u00fcckblickt.<\/p>\n<p>Die offizielle Beschreibung der neuen VR-Erfahrung lautet so: &#8222;Erlebe die Geschichte der Kingdom Hearts-Reihe erneut durch eine neue Art Musikvideo f\u00fcr PlayStation VR. Geniesse ein fesselndes Erlebnis in bekannten und nostalgischen Welten, w\u00e4hrend sich denkw\u00fcrdige Szenen durch Projektionsmapping entfalten.&#8220;<\/p>\n<p>Fonte: <a href=\"https:\/\/twitter.com\/PlayStation\/status\/1100875863309123584\">Twitter<\/a><\/p>","protected":false},"excerpt":{"rendered":"Purtroppo ci sono stati uno o due rinvii, ma ora \u00e8 finalmente arrivato il momento: Square Enix ha...","protected":false},"author":11,"featured_media":12971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-12970","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Es gab leider die eine oder andere Verschiebung, aber nun ist es endlich soweit: Square Enix hat die&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-28T09:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Kingdom Hearts VR Experience verf\u00fcgbar\",\"datePublished\":\"2019-02-28T09:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/\"},\"wordCount\":123,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/KingdomHeartsVR.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/\",\"name\":\"Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/KingdomHeartsVR.jpg\",\"datePublished\":\"2019-02-28T09:00:20+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/KingdomHeartsVR.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/KingdomHeartsVR.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/28\\\/kingdom-hearts-vr-experience-erschienen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kingdom Hearts VR Experience verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/","og_locale":"it_IT","og_type":"article","og_title":"Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News","og_description":"Es gab leider die eine oder andere Verschiebung, aber nun ist es endlich soweit: Square Enix hat die&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2019-02-28T09:00:20+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michael","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Kingdom Hearts VR Experience verf\u00fcgbar","datePublished":"2019-02-28T09:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/"},"wordCount":123,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg","articleSection":["Entertainment"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/","url":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/","name":"Kingdom Hearts VR Experience verf\u00fcgbar - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg","datePublished":"2019-02-28T09:00:20+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/KingdomHeartsVR.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2019\/02\/28\/kingdom-hearts-vr-experience-erschienen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Kingdom Hearts VR Experience verf\u00fcgbar"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/it\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/12970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=12970"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/12970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/12971"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=12970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=12970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=12970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}