{"id":12690,"date":"2019-02-06T08:16:05","date_gmt":"2019-02-06T08:16:05","guid":{"rendered":"http:\/\/vr-room.ch\/?p=12690"},"modified":"2019-01-24T08:56:52","modified_gmt":"2019-01-24T08:56:52","slug":"oesterrreichisches-hotel-bietet-virtual-reality-room","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/","title":{"rendered":"Un hotel austriaco offre una stanza per la realt\u00e0 virtuale"},"content":{"rendered":"<h3 id=\"im-leading-family-hotel-resort-dachsteinkoenig-in-gosau-bei-salzburg-koennen-gaeste-ab-sofort-in-virtuelle-welten-abtauchen-die-programme-sind-speziell-auf-familien-zugeschnitten\">Al Leading Family Hotel &amp; Resort Dachsteink\u00f6nig di Gosau, vicino a Salisburgo, gli ospiti possono ora immergersi in mondi virtuali. I programmi sono appositamente studiati per le famiglie.<!--more--><\/h3>\n<p>Il leader <a href=\"https:\/\/www.dachsteinkoenig.at\/?pk_campaign=AdWords-SEOC-Search-Dachsteinkoenig-AT_AD38&amp;pk_kwd=dachsteink\u00f6nig&amp;gclid=EAIaIQobChMIjOKVyYSG4AIVCImyCh1ShQGvEAAYASAAEgLxz_D_BwE\">Hotel &amp; Resort per famiglie Dachsteink\u00f6nig<\/a>\u00a0di Gosau, vicino a Salisburgo, in Austria, si concentra ora sui giochi di realt\u00e0 virtuale. Il direttore dell'hotel Florian Mayer ha sviluppato una stanza speciale dotata di sistemi di realt\u00e0 virtuale HTC Vive Pro e Ocolus GO. I sistemi sono progettati per un massimo di quattro giocatori, ma possono essere utilizzati anche singolarmente.<\/p>\n<h3 id=\"familienurlaub-wird-ploetzlich-wieder-spannend\">Le vacanze in famiglia tornano improvvisamente ad essere emozionanti<\/h3>\n<p>Die Auswahl der Anwendungen wurde auf\u00a0Familien\u00a0zugeschnitten. Kinder ab zehn Jahre d\u00fcrfen den Virtual-Reality-Room in Begleitung eines Erwachsenen nutzen, f\u00fcr Teenager ab 14 Jahren ist das Angebot frei zug\u00e4nglich. Genau f\u00fcr letztere soll auch der Familienurlaub, wenn er so langsam &#8222;uncool&#8220; wird, wieder spannend gemacht werden.<\/p>\n<p>Il motto dell'offerta \u00e8 giochi, sport e divertimento: questo include esperienze creative, giochi di conoscenza, sport e molti giochi diversi che ampliano i confini che conosciamo della realt\u00e0. Un'alternativa unica per le serate e quando il tempo non \u00e8 clemente, secondo il sito web dell'hotel.<\/p>\n<h3 id=\"brettspiele-neben-virtual-reality-games-beides-hat-platz\">Giochi da tavolo e giochi di realt\u00e0 virtuale: c'\u00e8 spazio per entrambi<\/h3>\n<p>Hoteldirektor Florian Mayer ist f\u00fcr technologischen Fortschritt offen. Brettspiele habe der Dachsteink\u00f6nig zwar nach wie vor im Repertoire, aber digitale Anwendungen, Apps und\u00a0Virtual Reality\u00a0liegen seiner Meinung nach im Trend. Mayer: &#8222;Wir gehen mit der Zeit und gerade Tourismusbetriebe k\u00f6nnten ohne Technologien gar nicht mehr existieren. Die Grenze zur digitalen Welt ziehe ich dort, wo sie sich mit gelebter Gastfreundschaft schneiden.&#8220;<\/p>\n<p>In den virtuellen Welten k\u00f6nnen die Spieler sich auf Klettertour ohne Seil und Haken begeben, den menschlichen K\u00f6rper als U-Boot im Blutkreislauf erkunden oder sich ihren Traum, als Astronaut ins Weltall zu fliegen, erf\u00fcllen. Ein Highlight sind die eigens f\u00fcr die Anwendung inszenierten &#8222;Cirque du Soleil&#8220;-Darbietungen, die interaktiv in 360 Grad und in erste Reihe erlebbar sind.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=ZkAYK2FlHN8&#038;feature=youtu.be<\/p>\n<p>Fonte: ahgz<\/p>","protected":false},"excerpt":{"rendered":"Al Leading Family Hotel &amp; Resort Dachsteink\u00f6nig di Gosau, vicino a Salisburgo, gli ospiti possono ora entrare in...","protected":false},"author":12,"featured_media":12691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-12690","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Im Leading Family Hotel &amp; Resort Dachsteink\u00f6nig in Gosau bei Salzburg k\u00f6nnen G\u00e4ste ab sofort in virtuelle Welten&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-06T08:16:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room\",\"datePublished\":\"2019-02-06T08:16:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/\"},\"wordCount\":346,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stellt-sein-neues-virtual-reality-angebot-vor.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/\",\"name\":\"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stellt-sein-neues-virtual-reality-angebot-vor.jpg\",\"datePublished\":\"2019-02-06T08:16:05+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stellt-sein-neues-virtual-reality-angebot-vor.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stellt-sein-neues-virtual-reality-angebot-vor.jpg\",\"width\":980,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2019\\\/02\\\/06\\\/oesterrreichisches-hotel-bietet-virtual-reality-room\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/","og_locale":"it_IT","og_type":"article","og_title":"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News","og_description":"Im Leading Family Hotel &amp; Resort Dachsteink\u00f6nig in Gosau bei Salzburg k\u00f6nnen G\u00e4ste ab sofort in virtuelle Welten&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2019-02-06T08:16:05+00:00","og_image":[{"width":980,"height":490,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room","datePublished":"2019-02-06T08:16:05+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/"},"wordCount":346,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg","articleSection":["Entertainment"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/","url":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/","name":"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg","datePublished":"2019-02-06T08:16:05+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stellt-sein-neues-virtual-reality-angebot-vor.jpg","width":980,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2019\/02\/06\/oesterrreichisches-hotel-bietet-virtual-reality-room\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"\u00d6sterrreichisches Hotel bietet Virtual-Reality-Room"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/12690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=12690"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/12690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/12691"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=12690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=12690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=12690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}