{"id":11697,"date":"2018-10-31T10:03:16","date_gmt":"2018-10-31T10:03:16","guid":{"rendered":"http:\/\/vr-room.ch\/?p=11697"},"modified":"2018-10-31T10:03:16","modified_gmt":"2018-10-31T10:03:16","slug":"kobold-vr-halloween-horror","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2018\/10\/31\/kobold-vr-halloween-horror\/","title":{"rendered":"Esperienza horror Goblin VR adatta ad Halloween"},"content":{"rendered":"<p>Das passt doch prima zu Halloween: &#8222;Kobold&#8220; ist eine neue Art von Horrorerfahrung, die die Grenze zwischen Kino und VR-Gaming verwischen soll. Das Ganze war als beste interaktive, narrative VR-Erfahrung beim Raindance Film Festival 2018 in London nominiert und ist als beste Virtual Reality-Erfahrung beim Filmfestival 2018 in Venedig ausgezeichnet worden.<\/p>\n<p>Die deutsche Medienproduktion &#8222;Kobold&#8220; liefert eine Erfahrung, bei der man zuerst einen Film anschaut und dann den Schauplatz in der virtuellen Realit\u00e4t betritt. Daf\u00fcr wurde eine 3D-Rekonstruktion eines real existierenden Ortes erstellt und in die VR-Erfahrung \u00fcbertragen. &#8222;Kobold: Chapter I&#8220; ist bereits im <a href=\"https:\/\/www.oculus.com\/experiences\/rift\/2124641230881553\/\" target=\"_blank\" rel=\"noopener noreferrer\">Negozio Oculus<\/a> per Oculus Rift e per <a href=\"https:\/\/www.viveport.com\/apps\/b0a4ccf0-2638-45bb-b86d-fc15b9b63e07\/KOBOLD:_CHAPTER_I\/\" target=\"_blank\" rel=\"noopener noreferrer\">Viveport<\/a> per HTC Vive, ma manca ancora il filmato di accompagnamento. Il filmato dovrebbe essere disponibile gratuitamente nelle prossime settimane tramite il sito web <a href=\"https:\/\/koboldhorror.com\/\">sito ufficiale<\/a> essere resi disponibili.<\/p>\n<p>Zu &#8222;Kobold VR&#8220; heisst es: &#8222;Trete in die Fussstapfen eines Stadtforschers, der den mysteri\u00f6sen Fall eines vermissten Jungen untersucht. Nimm die Taschenlampe und entdecke die Geheimnisse einer verlassenen Villa inmitten eines dunklen Waldes in Deutschland. Tauche ein in den wahren, filmischen Realismus, erkunde ein interaktives Universum, sammle Hinweise und dringe tiefer in eine mystische Welt, in der jede Handlung schwerwiegende Folgen haben kann.&#8220;<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-11697-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=nCFuFsf80nw&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=nCFuFsf80nw\">https:\/\/www.youtube.com\/watch?v=nCFuFsf80nw<\/a><\/video><\/div>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-11697-2\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=4bncaA6L_kw&#038;_=2\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=4bncaA6L_kw\">https:\/\/www.youtube.com\/watch?v=4bncaA6L_kw<\/a><\/video><\/div>\n<p>Fonte: VRODO, comunicato stampa<\/p>","protected":false},"excerpt":{"rendered":"Das passt doch prima zu Halloween: &#8222;Kobold&#8220; ist eine neue Art von Horrorerfahrung, die die Grenze zwischen Kino&hellip;","protected":false},"author":11,"featured_media":11698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-11697","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/it\/2018\/10\/31\/kobold-vr-halloween-horror\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Das passt doch prima zu Halloween: &#8222;Kobold&#8220; ist eine neue Art von Horrorerfahrung, die die Grenze zwischen Kino&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/it\/2018\/10\/31\/kobold-vr-halloween-horror\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-31T10:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1918\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Horrorerfahrung Kobold VR passt zu Halloween\",\"datePublished\":\"2018-10-31T10:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/\"},\"wordCount\":233,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/KOBOLD.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/\",\"name\":\"Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/KOBOLD.jpg\",\"datePublished\":\"2018-10-31T10:03:16+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/KOBOLD.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/KOBOLD.jpg\",\"width\":1918,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2018\\\/10\\\/31\\\/kobold-vr-halloween-horror\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horrorerfahrung Kobold VR passt zu Halloween\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/it\/2018\/10\/31\/kobold-vr-halloween-horror\/","og_locale":"it_IT","og_type":"article","og_title":"Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News","og_description":"Das passt doch prima zu Halloween: &#8222;Kobold&#8220; ist eine neue Art von Horrorerfahrung, die die Grenze zwischen Kino&hellip;","og_url":"http:\/\/vr-room.ch\/it\/2018\/10\/31\/kobold-vr-halloween-horror\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-10-31T10:03:16+00:00","og_image":[{"width":1918,"height":1274,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Michael","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Horrorerfahrung Kobold VR passt zu Halloween","datePublished":"2018-10-31T10:03:16+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/"},"wordCount":233,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg","articleSection":["Entertainment"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/","url":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/","name":"Horrorerfahrung Kobold VR passt zu Halloween - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg","datePublished":"2018-10-31T10:03:16+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/KOBOLD.jpg","width":1918,"height":1274},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/fr\/2018\/10\/31\/kobold-vr-halloween-horror\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Horrorerfahrung Kobold VR passt zu Halloween"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/it\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/11697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=11697"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/11697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/11698"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=11697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=11697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=11697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}