{"id":11465,"date":"2018-10-06T06:33:14","date_gmt":"2018-10-06T06:33:14","guid":{"rendered":"http:\/\/vr-room.ch\/?p=11465"},"modified":"2018-10-05T14:44:29","modified_gmt":"2018-10-05T14:44:29","slug":"abheben-in-den-entertainment-himmel","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/it\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","title":{"rendered":"Decollare verso il paradiso dell'intrattenimento"},"content":{"rendered":"<div class=\"row\">\n<div id=\"articletop\" class=\"col-md-9 col-md-offset-1 articletop mb50\">\n<h3 id=\"zusammen-mit-staay-interactive-hat-die-agentur-jeff-ein-virtual-reality-erlebnis-namens-ab-in-den-entertainment-himmel-fuer-upc-kreiert-in-einem-fliegenden-tv-sessel-gehen-die-besucher-am\" class=\"articlelead\">Insieme a Staay Interactive, l'agenzia Jeff ha creato un'esperienza di realt\u00e0 virtuale chiamata \"Off to Entertainment Heaven\" per UPC. I visitatori del Festival del Cinema di Zurigo partecipano a un viaggio interattivo a bordo di una poltrona TV volante.<\/h3>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div id=\"socheight\" class=\"row\">\n<div class=\"col-md-6 articletext sublineImage\">\n<p>Quest'anno i visitatori dello Zurich Film Festival potranno vivere un'esperienza speciale di realt\u00e0 virtuale: all'insegna del motto \"Off to Entertainment Heaven\", avranno l'opportunit\u00e0 di sperimentare da vicino la nuova esperienza televisiva di UPC, come scrive Jeff in un comunicato stampa. Non appena il visitatore si siede sulla sedia del simulatore, viene catapultato fuori dal salotto virtuale e nel cielo.<\/p>\n<p>Una volta l\u00ec, prende il controllo con il nuovo telecomando di UPC TV e vola verso enormi schermi televisivi fluttuanti che mostrano gli ultimi film di UPC TV. Quando il soggetto guarda in basso, la vista a volo d'uccello della citt\u00e0 di Zurigo \u00e8 affascinante.<\/p>\n<p>La particolarit\u00e0 \u00e8 che anche la poltrona TV \"sta al gioco\". La poltrona mobile, prodotta appositamente per l'esperienza, si solleva in aria all'inizio, in modo che i piedi perdano il contatto con il suolo e il visitatore si immerga completamente nel mondo virtuale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11466\" src=\"http:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-225x300.jpg\" alt=\"\" width=\"357\" height=\"476\" srcset=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-225x300.jpg 225w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-768x1024.jpg 768w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-833x1110.jpg 833w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-1110x1480.jpg 1110w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-730x973.jpg 730w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-539x719.jpg 539w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-350x467.jpg 350w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-254x339.jpg 254w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-125x167.jpg 125w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie.jpg 3024w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/p>\n<h3 id=\"gewinnspiel-als-zusaetzliche-massnahme\">Lotteria come misura aggiuntiva<\/h3>\n<p>Se il visitatore vuole vincere un premio oltre all'esperienza di volo, deve abbinare tutti i film alla locandina corretta su un'applicazione per tablet. \u00c8 necessaria la concentrazione, poich\u00e9 i jumbo jet rombanti o gli aquiloni che passano cercano di distrarre l'attenzione audiovisiva. Ogni giorno si possono vincere occhiali VR e il premio principale \u00e8 un anno di \"Happy Home\" gratuito con la nuova UPC TV.<\/p>\n<p>Il concetto, la narrazione interattiva e la realizzazione sono stati sviluppati da Jeff e dallo studio di gioco <a href=\"https:\/\/staay.io\/de\/\">Staay <\/a>Interactive (vincitore del Best of Swiss Apps 2017 nelle categorie Best Game e Best Campaign). Gli interessati possono ancora provare Entertainment Heaven allo Zurich Film Festival fino a domenica 7 ottobre.<\/p>\n<p><iframe loading=\"lazy\" title=\"3 esperienza di realt\u00e0 virtuale immersiva\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/pKmCmTrFDXQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Si spera per i visitatori che il volo sia un po' pi\u00f9 agevole rispetto all'esperienza da capogiro vissuta durante la promozione con Samsung e UPC pi\u00f9 di un anno e mezzo fa, da cui abbiamo tratto un'esperienza di questo tipo. <a href=\"http:\/\/vr-room.ch\/it\/2017\/01\/17\/kopfueber-bei-samsung-upc\/\">segnalato<\/a>.<\/p>\n<p>Fonte: Personale<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Insieme a Staay Interactive, l'agenzia Jeff ha creato un'esperienza di realt\u00e0 virtuale chiamata \"Off to Entertainment Heaven\" per UPC....","protected":false},"author":12,"featured_media":11467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-11465","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Zusammen mit Staay Interactive hat die Agentur Jeff ein Virtual-Reality-Erlebnis namens \u00abAb in den Entertainment-Himmel\u00bb f\u00fcr UPC kreiert.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-06T06:33:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm-1024x542.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Abheben in den Entertainment-Himmel\",\"datePublished\":\"2018-10-06T06:33:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"},\"wordCount\":334,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\",\"name\":\"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"datePublished\":\"2018-10-06T06:33:14+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"width\":1920,\"height\":1017},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abheben in den Entertainment-Himmel\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","og_locale":"it_IT","og_type":"article","og_title":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","og_description":"Zusammen mit Staay Interactive hat die Agentur Jeff ein Virtual-Reality-Erlebnis namens \u00abAb in den Entertainment-Himmel\u00bb f\u00fcr UPC kreiert.&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-10-06T06:33:14+00:00","og_image":[{"width":1024,"height":542,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm-1024x542.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Abheben in den Entertainment-Himmel","datePublished":"2018-10-06T06:33:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"},"wordCount":334,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","articleSection":["Schweiz"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","url":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","name":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","datePublished":"2018-10-06T06:33:14+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","width":1920,"height":1017},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Abheben in den Entertainment-Himmel"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/11465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=11465"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/11465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/11467"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=11465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=11465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=11465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}