{"id":8078,"date":"2017-11-01T06:56:31","date_gmt":"2017-11-01T06:56:31","guid":{"rendered":"http:\/\/vr-room.ch\/?p=8078"},"modified":"2017-10-27T14:10:06","modified_gmt":"2017-10-27T14:10:06","slug":"vr-konferenz-expanding-immersive-design","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/","title":{"rendered":"Conf\u00e9rence VR \"Expanding Immersive Design\" (en anglais)"},"content":{"rendered":"<h3 id=\"zum-zweiten-mal-findet-am-21-november-2017-die-konferenz-expanding-immersive-design-an-der-zuercher-hochschule-der-kuenste-zhdk-statt-die-diesjaehrige-ausgabe-laeuft-unter-dem-titel-storytel\">Pour la deuxi\u00e8me fois, la conf\u00e9rence Expanding Immersive Design aura lieu le 21 novembre 2017 \u00e0 la Haute \u00e9cole des arts de Zurich (ZHdK). L'\u00e9dition de cette ann\u00e9e s'intitule \"Storytelling in the Virtual Age\" et se focalise fondamentalement sur les strat\u00e9gies de narration dans les espaces virtuels.<\/h3>\n<p><!--more--><\/p>\n<p>Point de d\u00e9part de la discussion de la conf\u00e9rence de cette ann\u00e9e <a href=\"https:\/\/persoenlich.us6.list-manage.com\/track\/click?u=1dc4d6e86920bd90ab08b56c3&amp;id=9ce4c801af&amp;e=5fd729e27f\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Expanding Immersive Design<\/u><\/a> forme nos attentes \u00e0 l'\u00e9gard des m\u00e9dias immersifs dans une perspective neuropsychologique, technologique et historico-culturelle. En tr\u00e8s peu de temps, la RV est devenue un mot \u00e0 la mode. Pourtant, malgr\u00e9 l'entr\u00e9e sur le march\u00e9 de la technologie VR pour les consommateurs, c\u00e9l\u00e9br\u00e9e il y a tout juste un an, et toute l'euphorie qui l'accompagne, les chiffres de vente de tels syst\u00e8mes restent encore modestes jusqu'\u00e0 pr\u00e9sent. Lors de la conf\u00e9rence, des experts se pencheront de mani\u00e8re critique sur l'engouement pour la r\u00e9alit\u00e9 virtuelle et le vocabulaire qui l'accompagne. La discussion sur la notion d'\"immersion\" devrait constituer un point de d\u00e9part fructueux.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8081\" src=\"http:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-300x200.jpg\" alt=\"\" width=\"392\" height=\"261\" srcset=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-300x200.jpg 300w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-768x512.jpg 768w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-1024x683.jpg 1024w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-1110x741.jpg 1110w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-730x487.jpg 730w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-539x360.jpg 539w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-350x234.jpg 350w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-254x169.jpg 254w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0-125x83.jpg 125w, https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/digitaltag-wvg2ham3.1280x0.jpg 1280w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/p>\n<p>Le site <a href=\"https:\/\/persoenlich.us6.list-manage.com\/track\/click?u=1dc4d6e86920bd90ab08b56c3&amp;id=7dc11c8657&amp;e=5fd729e27f\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Conf\u00e9rence sp\u00e9cialis\u00e9e<\/u><\/a> ose ainsi, en collaboration avec des experts internationaux du design, de la culture et de la science, un regard courageux vers l'avenir et plaide pour une approche interdisciplinaire de ce domaine. Dans le cadre d'ateliers, de formats d'exposition et d'un vaste programme de conf\u00e9rences, elle th\u00e9matise l'urgence d'orienter le d\u00e9bat sur la r\u00e9alit\u00e9 virtuelle, la r\u00e9alit\u00e9 mixte et la r\u00e9alit\u00e9 augment\u00e9e, qui est actuellement men\u00e9 de mani\u00e8re d\u00e9terminante sur le plan \u00e9conomique et technologique, vers les questions fondamentales que sont la nature structurelle des contenus et l'architecture des espaces immersifs, num\u00e9riques et analogiques, qui les encadrent.<\/p>\n<p>Des questions telles que : Quels sc\u00e9narios d'avenir sont envisageables avec la r\u00e9alit\u00e9 augment\u00e9e (AR), la r\u00e9alit\u00e9 mixte (MR) et la r\u00e9alit\u00e9 virtuelle (VR) ? De quelle base se nourrissent nos attentes et notre vocabulaire dans le d\u00e9bat discursif sur la RV ? Comment la triade corps-conscience-technologie va-t-elle se combiner \u00e0 l'avenir ? Quels d\u00e9fis de conception et quelles questions \u00e9thiques la RV nous pose-t-elle ?<\/p>\n<p>Le site <a href=\"https:\/\/persoenlich.us6.list-manage.com\/track\/click?u=1dc4d6e86920bd90ab08b56c3&amp;id=285a8e541a&amp;e=5fd729e27f\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Vente de billets<\/u><\/a> pour la conf\u00e9rence et le <a href=\"https:\/\/persoenlich.us6.list-manage.com\/track\/click?u=1dc4d6e86920bd90ab08b56c3&amp;id=25ab5822d2&amp;e=5fd729e27f\" target=\"_blank\" rel=\"noopener noreferrer\"><u>Offre d'ateliers<\/u><\/a> ont maintenant commenc\u00e9.<\/p>\n<p>Outre la conf\u00e9rence sp\u00e9cialis\u00e9e, la ZHdK propose un <a href=\"https:\/\/persoenlich.us6.list-manage.com\/track\/click?u=1dc4d6e86920bd90ab08b56c3&amp;id=ffc894dde7&amp;e=5fd729e27f\" target=\"_blank\" rel=\"noopener noreferrer\"><u>offre compl\u00e8te<\/u><\/a> autour du th\u00e8me \"Faire l'exp\u00e9rience de la num\u00e9risation\" le 21 novembre 2017. La ZHdK fait ainsi partie de la \"Journ\u00e9e du num\u00e9rique en Suisse\", organis\u00e9e par digitalswitzerland.<\/p>\n<p>Source : Personnel \/ ZHdK<\/p>","protected":false},"excerpt":{"rendered":"Pour la deuxi\u00e8me fois, la conf\u00e9rence Expanding Immersive Design se tiendra le 21 novembre 2017 \u00e0 la Haute \u00e9cole...","protected":false},"author":12,"featured_media":8079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-8078","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Zum zweiten Mal findet am 21. November 2017 die Konferenz Expanding Immersive Design an der Z\u00fcrcher Hochschule der&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-01T06:56:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"VR-Konferenz \u00abExpanding Immersive Design\u00bb\",\"datePublished\":\"2017-11-01T06:56:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/\"},\"wordCount\":340,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VR-Konferenz.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/\",\"name\":\"VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VR-Konferenz.jpg\",\"datePublished\":\"2017-11-01T06:56:31+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VR-Konferenz.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VR-Konferenz.jpg\",\"width\":780,\"height\":361},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/01\\\/vr-konferenz-expanding-immersive-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR-Konferenz \u00abExpanding Immersive Design\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/","og_locale":"fr_FR","og_type":"article","og_title":"VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News","og_description":"Zum zweiten Mal findet am 21. November 2017 die Konferenz Expanding Immersive Design an der Z\u00fcrcher Hochschule der&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-11-01T06:56:31+00:00","og_image":[{"width":780,"height":361,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"VR-Konferenz \u00abExpanding Immersive Design\u00bb","datePublished":"2017-11-01T06:56:31+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/"},"wordCount":340,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/","url":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/","name":"VR-Konferenz \u00abExpanding Immersive Design\u00bb - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg","datePublished":"2017-11-01T06:56:31+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VR-Konferenz.jpg","width":780,"height":361},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2017\/11\/01\/vr-konferenz-expanding-immersive-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR-Konferenz \u00abExpanding Immersive Design\u00bb"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/8078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=8078"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/8078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/8079"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=8078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=8078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=8078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}