{"id":4448,"date":"2017-02-14T12:43:40","date_gmt":"2017-02-14T12:43:40","guid":{"rendered":"http:\/\/vr-room.ch\/?p=4448"},"modified":"2017-02-14T12:43:40","modified_gmt":"2017-02-14T12:43:40","slug":"video-player-lens-fuer-playstation-vr-veroeffentlicht","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/","title":{"rendered":"Sortie du lecteur vid\u00e9o Lens pour le PlayStation VR"},"content":{"rendered":"<p>Sur le site <a href=\"https:\/\/store.playstation.com\">PlayStation Store<\/a> steht ab sofort eine neue App f\u00fcr PlayStation VR zum kostenlosen Download bereit. Der Download ist nur 30 MB gross und d\u00fcrfte entsprechend schnell beendet sein. Dabei handelt es sich um &#8222;Lens&#8220;. Das ist ein Video-Player, der auf eine Online-Bibliothek mit 360-Grad-Videos zugreift. Die gesamte Aufmachung der Software ist schick gestaltet und wenn die Videos geladen wurden, kann die Qualit\u00e4t (zumindest in Teilen) durchaus \u00fcberzeugen.<\/p>\n<p>Allerdings gibt es noch ein grosses Problem: Inhalte sind bisher leider noch Mangelware, was sich mit der Zeit hoffentlich \u00e4ndern wird. Dennoch kann bei Interesse ein kurzer Blick auf &#8222;Lens&#8220; f\u00fcr PlayStation VR geworfen werden, denn mehr ist ohnehin nicht m\u00f6glich. Eine richtig gute Alternative zu VR-Videos auf YouTube und Co. stellt die App aber nicht dar. Falls keine PlayStation 4 mit PSVR vorhanden sein sollte, gibt es Abhilfe, denn &#8222;Lens&#8220; unterst\u00fctzt ebenfalls Samsung Gear VR, HTC Vive und Oculus Rift. Weitere Informationen stehen auf der <a href=\"https:\/\/lens-immersive.com\/\">offiziellen &#8222;Lens&#8220;-Seite<\/a>.<\/p>\n<p>Source : VR-Nerds<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"Une nouvelle application pour le PlayStation VR est d\u00e9sormais disponible en t\u00e9l\u00e9chargement gratuit sur le PlayStation Store. Le t\u00e9l\u00e9chargement...","protected":false},"author":11,"featured_media":4449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-4448","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Im PlayStation Store steht ab sofort eine neue App f\u00fcr PlayStation VR zum kostenlosen Download bereit. Der Download&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-14T12:43:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht\",\"datePublished\":\"2017-02-14T12:43:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/\"},\"wordCount\":172,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/LENS.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/\",\"name\":\"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/LENS.jpg\",\"datePublished\":\"2017-02-14T12:43:40+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/LENS.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/LENS.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/02\\\/14\\\/video-player-lens-fuer-playstation-vr-veroeffentlicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/","og_locale":"fr_FR","og_type":"article","og_title":"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News","og_description":"Im PlayStation Store steht ab sofort eine neue App f\u00fcr PlayStation VR zum kostenlosen Download bereit. Der Download&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-02-14T12:43:40+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht","datePublished":"2017-02-14T12:43:40+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/"},"wordCount":172,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg","articleSection":["Entertainment"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/","url":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/","name":"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg","datePublished":"2017-02-14T12:43:40+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/02\/LENS.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2017\/02\/14\/video-player-lens-fuer-playstation-vr-veroeffentlicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Video-Player Lens f\u00fcr PlayStation VR ver\u00f6ffentlicht"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/4448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=4448"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/4448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/4449"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=4448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=4448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=4448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}