{"id":20597,"date":"2022-06-01T05:48:34","date_gmt":"2022-06-01T05:48:34","guid":{"rendered":"https:\/\/vr-room.ch\/?p=20597"},"modified":"2022-05-24T05:51:56","modified_gmt":"2022-05-24T05:51:56","slug":"ein-metaveserse-turm-mitten-im-zuerichsee","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/","title":{"rendered":"Une tour de Metaveserse au milieu du lac de Zurich"},"content":{"rendered":"<div id=\"social\" class=\"col-md-2 mb0 hidden-sm hidden-xs\">\n<div id=\"socials\" class=\"socials\">\n<div id=\"detailmore\" class=\"articledetailmore\">\n<h3 id=\"drei-firmen-haben-ein-metaverse-in-form-eines-wohn-und-arbeitsturms-namens-glo-tower-mitten-im-zuercher-seebecken-realisiert\" class=\"articlelead\">Trois entreprises ont r\u00e9alis\u00e9 un m\u00e9tavers sous la forme d'une tour d'habitation et de travail appel\u00e9e Glo-Tower au milieu du bassin du lac de Zurich.<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"col-md-6 articletext sublineImage\">\n<p>Avec la Glo-Tower, le paysage urbain de Zurich se modifie consid\u00e9rablement. En effet, la tour futuriste est reconnaissable de loin, au milieu du bassin du lac de Zurich. La vue depuis les \u00e9tages sup\u00e9rieurs est \u00e0 couper le souffle, comme l'indique un communiqu\u00e9. A plus de 280 m\u00e8tres au-dessus du lac, une \"vue in\u00e9dite sur la ville, le lac et la r\u00e9gion environnante jusqu'aux Alpes et au-del\u00e0\" se pr\u00e9sente.<\/p>\n<p>Outre des appartements de luxe et des bureaux attrayants qui sont effectivement \u00e0 vendre, la tour construite num\u00e9riquement offre surtout, selon ses propres indications, des \"salles d'exposition attrayantes\". Ceux-ci pourraient \u00eatre utilis\u00e9s par des entreprises, des marques et des particuliers. La Glo-Tower serait ainsi un m\u00e9tavers en soi et cr\u00e9erait un espace virtuel pour des expositions, des pr\u00e9sentations et des placements de produits. Il est envisageable que les services de commande des magasins et restaurants participants soient int\u00e9gr\u00e9s dans la tour dans un avenir proche et que celle-ci puisse s'\u00e9tablir comme lieu d'\u00e9v\u00e9nement virtuel.<\/p>\n<p>Le Glo-Group est \u00e0 l'origine du concept du premier gratte-ciel virtuel de Zurich. Celui-ci se compose des entreprises DesignRaum, Tollkirsch et Cmsbox. Elles r\u00e9unissent leur longue exp\u00e9rience dans les domaines de la visualisation d'architecture et de produits, du branding, de la communication et des solutions web. La Glo-Tower est le r\u00e9sultat d'un \"concentr\u00e9 d'expertise\" - adapt\u00e9 aux exigences d'un marketing immobilier et de produits orient\u00e9 vers l'avenir.<\/p>\n<h3 id=\"werbung-fuer-hochhaeuser\">Publicit\u00e9 pour les gratte-ciel<\/h3>\n<p>Avec cette tour, Glo-Group veut en outre am\u00e9liorer l'acceptation des immeubles de grande hauteur en Suisse, car \"avec l'augmentation de la population dans les villes suisses, nous devons nous habituer au fait que nous allons nous rapprocher \u00e0 l'avenir\", d\u00e9clare Michael Waldvogel, membre de Glo-Group, cit\u00e9 dans le communiqu\u00e9. \"Il est possible que les gens s'habituent plus rapidement, gr\u00e2ce aux tours virtuelles, au fait que leur paysage urbain changera t\u00f4t ou tard\", ajoute Christoph Wysseier de Glo-Group.<\/p>\n<p>\"En ces temps de changement climatique, nous devons \u00e9galement cr\u00e9er plus d'espaces verts dans les villes. Des b\u00e2timents plus hauts et bien con\u00e7us peuvent contribuer \u00e0 la solution\", selon Christian Hungerb\u00fchler de Glo-Group. Ce th\u00e8me a \u00e9galement \u00e9t\u00e9 repris dans la conception de la Glo-Tower par \"une v\u00e9g\u00e9talisation verticale et la cr\u00e9ation d'oasis de verdure\" sur plusieurs \u00e9tages.<\/p>\n<p>Dans la r\u00e9alit\u00e9, il n'est pas encore possible de construire une tour de cette taille sur un site exclusif au milieu du lac de Zurich, mais dans le monde virtuel, le b\u00e2timent est d\u00e9j\u00e0 pr\u00eat \u00e0 \u00eatre occup\u00e9. Les appartements libres peuvent \u00eatre trouv\u00e9s via le\u00a0<a href=\"https:\/\/glo-tower.glo.show\/#\/objects\/5\" target=\"_blank\" rel=\"noopener\">Localisateur d'appartements Glo<\/a> et les visiter gr\u00e2ce \u00e0 une vue panoramique \u00e0 360 degr\u00e9s. Il est d'ores et d\u00e9j\u00e0 possible d'acheter un appartement num\u00e9rique dans la Glo Tower. En cliquant sur le symbole dor\u00e9 du bitcoin \u00e0 l'int\u00e9rieur de l'appartement, les personnes int\u00e9ress\u00e9es par l'achat arriveraient sur le NFT-Marketplace d'OpenSea, o\u00f9 elles pourraient faire une offre au moyen de la crypto-monnaie. Un premier appartement de la Glo-Tower a d\u00e9j\u00e0 \u00e9t\u00e9 pr\u00e9sent\u00e9 et mis aux ench\u00e8res lors de la Swissbau 2022 d\u00e9but mai.<\/p>\n<p>Source : Personnel<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"Trois entreprises ont r\u00e9alis\u00e9 un m\u00e9tavers sous la forme d'une tour d'habitation et de travail appel\u00e9e Glo-Tower au milieu du bassin du lac de Zurich....","protected":false},"author":12,"featured_media":20598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-20597","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Drei Firmen haben ein Metaverse in Form eines Wohn- und Arbeitsturms namens Glo-Tower mitten im Z\u00fcrcher Seebecken realisiert.&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T05:48:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Ein Metaveserse-Turm mitten im Z\u00fcrichsee\",\"datePublished\":\"2022-06-01T05:48:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/\"},\"wordCount\":494,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/\",\"name\":\"Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg\",\"datePublished\":\"2022-06-01T05:48:34+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg\",\"width\":940,\"height\":528,\"caption\":\"Glo-Tower\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/06\\\/01\\\/ein-metaveserse-turm-mitten-im-zuerichsee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Metaveserse-Turm mitten im Z\u00fcrichsee\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/","og_locale":"fr_FR","og_type":"article","og_title":"Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News","og_description":"Drei Firmen haben ein Metaverse in Form eines Wohn- und Arbeitsturms namens Glo-Tower mitten im Z\u00fcrcher Seebecken realisiert.&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2022-06-01T05:48:34+00:00","og_image":[{"width":940,"height":528,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Ein Metaveserse-Turm mitten im Z\u00fcrichsee","datePublished":"2022-06-01T05:48:34+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/"},"wordCount":494,"image":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/","url":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/","name":"Ein Metaveserse-Turm mitten im Z\u00fcrichsee - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg","datePublished":"2022-06-01T05:48:34+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/ein-virtueller-turm-mitten-im-zurichsee-5965.jpg","width":940,"height":528,"caption":"Glo-Tower"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2022\/06\/01\/ein-metaveserse-turm-mitten-im-zuerichsee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Ein Metaveserse-Turm mitten im Z\u00fcrichsee"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/20597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=20597"}],"version-history":[{"count":1,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/20597\/revisions"}],"predecessor-version":[{"id":20599,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/20597\/revisions\/20599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/20598"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=20597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=20597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=20597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}