{"id":19957,"date":"2021-09-17T08:18:55","date_gmt":"2021-09-17T08:18:55","guid":{"rendered":"https:\/\/vr-room.ch\/?p=19957"},"modified":"2021-09-10T08:31:18","modified_gmt":"2021-09-10T08:31:18","slug":"3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/","title":{"rendered":"Le configurateur 3D gagne - meilleur projet web suisse 2021"},"content":{"rendered":"<h3 id=\"id-doc-1ff5csc5l0\" class=\"articlecomponent text\"><span id=\"beim-best-of-swiss-web-award-2021-lautetet-das-verdikt-der-jury-diese-360-grad-umsetzung-ist-goldwuerdig-die-jury-vergab-eine-vierfachauszeichnung-fuer-ein-projekt-aus-dem-industriellen\">Lors du Best of Swiss Web Award 2021, le verdict du jury a \u00e9t\u00e9 le suivant : \"Cette r\u00e9alisation \u00e0 360 degr\u00e9s est digne de l'or\" ! Le jury a d\u00e9cern\u00e9 une quadruple r\u00e9compense \u00e0 un projet issu de l'environnement industriel. Le Best of Swiss Web Award r\u00e9compense chaque ann\u00e9e des travaux exceptionnels ax\u00e9s sur la technologie web et r\u00e9alis\u00e9s par des entreprises suisses.<\/span><\/h3>\n<p data-team-paragraph=\"\" data-nzz-article-component=\"\"><!--more--><\/p>\n<p id=\"id-doc-1ff5klhef1\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Parmi les 326 projets pr\u00e9sent\u00e9s cette ann\u00e9e dans divers secteurs, le configurateur 3D de l'EAO a su convaincre les experts : aucun autre projet n'a obtenu un meilleur r\u00e9sultat dans l'\u00e9valuation globale du jury. Lors de la c\u00e9r\u00e9monie de remise des prix en d\u00e9but de semaine, l'EAO a pu \u00eatre pr\u00e9sent\u00e9 au public. <a href=\"https:\/\/eao.com\/switzerland\/de\/\">EAO AG<\/a> a donc re\u00e7u pas moins de quatre prix : Or dans la cat\u00e9gorie \"Productivity\", argent dans les cat\u00e9gories \"Digital Commerce\" et \"Business\", et bronze dans la cat\u00e9gorie \"Usability\".<\/p>\n<h3 id=\"id-doc-1ff5d366a0\" class=\"subtitle articlecomponent\" data-team-subtitle=\"\" data-nzz-article-component=\"\"><span id=\"auszeichnung-fuer-produkt-aus-dem-industriellen-umfeld\"><span class=\"\">R\u00e9compense pour un produit issu de l'environnement industriel<\/span><\/span><\/h3>\n<p id=\"id-doc-1ff5d31vs1\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Cette distinction est remarquable et rare dans la mesure o\u00f9 un projet issu de l'environnement industriel se hisse au sommet face \u00e0 une concurrence essentiellement ax\u00e9e sur le secteur grand public, ce qui est qualifi\u00e9 de \"raret\u00e9\" pour EAO AG et qui, selon elle, \"t\u00e9moigne de la grande qualit\u00e9 du configurateur 3D EAO\". Le jugement du jury : \"Le configurateur 3D d'EAO est un coup de productivit\u00e9 r\u00e9ussi. Le constructeur en ligne assiste les clients partout dans le monde, ind\u00e9pendamment de la langue et de la culture. L'ensemble du processus de vente a \u00e9t\u00e9 nettement optimis\u00e9 en interne comme en externe\".<\/p>\n<h3 id=\"ar-ueberzeugt-restlos\">AR convainc totalement<\/h3>\n<p id=\"id-doc-1ff5d6gug1\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">La r\u00e9alisation r\u00e9ussie et l'utilisation innovante de la r\u00e9alit\u00e9 augment\u00e9e (AR) ont \u00e9t\u00e9 particuli\u00e8rement soulign\u00e9es : L'id\u00e9e de construire un configurateur de touches de secours avec l'aide de la RA a totalement convaincu le jury. Il s'agit l\u00e0 d'un cas judicieux pour la RA, qui a \u00e9t\u00e9 mis en \u0153uvre de mani\u00e8re g\u00e9niale sur le plan visuel. Verdict du jury : \"Cette r\u00e9alisation \u00e0 360 degr\u00e9s est digne de l'or\" !<\/p>\n<p id=\"id-doc-1ff5kktv31\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-vars-danzz-last-article-element=\"true\" data-nzz-article-component=\"\">David Kramer, Head of Corporate Marketing EAO AG et chef de projet du configurateur 3D, se r\u00e9jouit que l'entreprise d'Olten ait choisi la bonne voie pour l'avenir num\u00e9rique avec son configurateur 3D. Selon lui, les mois intensifs de d\u00e9veloppement en collaboration avec l'agence num\u00e9rique Eyekon et les sp\u00e9cialistes des donn\u00e9es d'Intelliact ont d\u00e9finitivement port\u00e9 leurs fruits avec l'obtention du Best of Swiss Web Award. \"EAO est fi\u00e8re de pouvoir offrir \u00e0 ses clients une excellente exp\u00e9rience num\u00e9rique\", conclut Kramer.<\/p>\n<p data-team-paragraph=\"\" data-vars-danzz-last-article-element=\"true\" data-nzz-article-component=\"\">Source : oltnertagblatt<\/p>","protected":false},"excerpt":{"rendered":"Lors du Best of Swiss Web Award 2021, le verdict du jury a \u00e9t\u00e9 le suivant : \"Cette r\u00e9alisation \u00e0 360 degr\u00e9s est digne d'or\" ! Le jury...","protected":false},"author":12,"featured_media":19958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-19957","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Beim Best of Swiss Web Award 2021 lautetet das Verdikt der Jury: \u00abDiese 360-Grad-Umsetzung ist goldw\u00fcrdig!\u00bb Die Jury&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T08:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"3D-Konfigurator gewinnt &#8211; beste Schweizer Webprojekt 2021\",\"datePublished\":\"2021-09-17T08:18:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/\"},\"wordCount\":334,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/\",\"name\":\"3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png\",\"datePublished\":\"2021-09-17T08:18:55+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png\",\"width\":795,\"height\":485,\"caption\":\"EAO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/09\\\/17\\\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3D-Konfigurator gewinnt &#8211; beste Schweizer Webprojekt 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News","og_description":"Beim Best of Swiss Web Award 2021 lautetet das Verdikt der Jury: \u00abDiese 360-Grad-Umsetzung ist goldw\u00fcrdig!\u00bb Die Jury&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2021-09-17T08:18:55+00:00","og_image":[{"width":795,"height":485,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"3D-Konfigurator gewinnt &#8211; beste Schweizer Webprojekt 2021","datePublished":"2021-09-17T08:18:55+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/"},"wordCount":334,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/","url":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/","name":"3D-Konfigurator gewinnt - beste Schweizer Webprojekt 2021 - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png","datePublished":"2021-09-17T08:18:55+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-10-at-10-24-40-3D-Konfigurator-der-Oltner-EAO-AG-ist-bestes-SchweizerWebprojekt.png","width":795,"height":485,"caption":"EAO"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/fr\/2021\/09\/17\/3d-konfigurator-der-oltner-firma-eao-ag-ist-das-beste-schweizer-webprojekt-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"3D-Konfigurator gewinnt &#8211; beste Schweizer Webprojekt 2021"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=19957"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/19958"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=19957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=19957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=19957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}