{"id":18546,"date":"2020-12-16T10:43:16","date_gmt":"2020-12-16T10:43:16","guid":{"rendered":"https:\/\/vr-room.ch\/?p=18546"},"modified":"2020-12-14T19:50:20","modified_gmt":"2020-12-14T19:50:20","slug":"augmented-reality-im-operationssaal","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2020\/12\/16\/augmented-reality-im-operationssaal\/","title":{"rendered":"R\u00e9alit\u00e9 augment\u00e9e en salle d'op\u00e9ration"},"content":{"rendered":"<h3 id=\"endlich-auch-mal-wieder-good-news-aus-einem-spital-ein-team-der-universitaetsklinik-balgrist-fuehrte-erfolgreich-die-erste-direkt-auf-den-patienten-projizierte-holographisch-navigierte-wirbelsaeulen\">Enfin de bonnes nouvelles en provenance d'un h\u00f4pital : une \u00e9quipe de l'H\u00f4pital universitaire Balgrist a r\u00e9alis\u00e9 avec succ\u00e8s la premi\u00e8re op\u00e9ration de la colonne vert\u00e9brale par navigation holographique projet\u00e9e directement sur le patient. Cette technologie a \u00e9t\u00e9 d\u00e9velopp\u00e9e \u00e0 l'H\u00f4pital universitaire Balgrist dans le cadre d'un projet auquel participe l'EPF de Zurich.<!--more--><\/h3>\n<p>Gr\u00e2ce \u00e0 des ann\u00e9es de recherche, la r\u00e9alit\u00e9 augment\u00e9e (RA) fait son entr\u00e9e dans les salles d'op\u00e9ration. Une \u00e9tape importante a ainsi \u00e9t\u00e9 franchie. D\u00e9but d\u00e9cembre 2020, la premi\u00e8re op\u00e9ration avec navigation holographique a eu lieu \u00e0 l'H\u00f4pital universitaire Balgrist. Selon une <a class=\"default-link\" href=\"https:\/\/www.balgrist.ch\/forschung\/forschergruppen\/hololens\/\">Communiqu\u00e9 de presse<\/a> le sp\u00e9cialiste de la colonne vert\u00e9brale Mazda Farshad, directeur m\u00e9dical de l'H\u00f4pital universitaire Balgrist, a op\u00e9r\u00e9 avec l'aide de lunettes AR (HoloLens 2).<\/p>\n<p>Cette op\u00e9ration marque le d\u00e9but d'un essai clinique randomis\u00e9 et contr\u00f4l\u00e9 qui \u00e9valuera les avantages de cette innovation chirurgicale. Il s'agit de la premi\u00e8re \u00e9tude de ce type au monde. On parle d'un moment historique dans la salle d'op\u00e9ration.<\/p>\n<p><iframe loading=\"lazy\" title=\"L&#039;\u00e9quipe de Balgrist r\u00e9alise la premi\u00e8re op\u00e9ration de la colonne vert\u00e9brale par navigation holographique\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/oNX9IEyl7tE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h3 id=\"ar-erweitert-die-sinne-des-chirurgen\">AR \"\u00e9largit les sens du chirurgien\".<\/h3>\n<p>Des repr\u00e9sentations 3D de l'anatomie concern\u00e9e sont g\u00e9n\u00e9r\u00e9es sur la base d'imageries CT et projet\u00e9es directement sur le champ op\u00e9ratoire pendant l'op\u00e9ration. Les chirurgiens voient cette anatomie 3D de la personne \u00e0 op\u00e9rer \u00e0 l'aide de lunettes AR. Le logiciel de navigation AR guide les \u00e9tapes critiques de l'op\u00e9ration. Il montre par exemple la pose exacte d'une vis au bon endroit et selon le bon angle.<\/p>\n<p>\"L'Hololens \u00e9largit les sens d'un chirurgien et am\u00e9liore sa capacit\u00e9 de perception\", explique Farshad, qui poursuit : \"Nous entrons ainsi dans une nouvelle \u00e8re de la chirurgie, qui doit \u00eatre \u00e9labor\u00e9e scientifiquement en cons\u00e9quence\". Meboldt, codirecteur de SURGENT, est lui aussi ravi : \"La collaboration entre des professionnels de la sant\u00e9 visionnaires comme Mazda Farshad et des chercheurs de l'universit\u00e9 et de l'EPF de Zurich est une aubaine pour tous les participants et constitue la base de ce succ\u00e8s\".<\/p>\n<p>Le patient avait des vert\u00e8bres lombaires us\u00e9es, un canal vert\u00e9bral fortement r\u00e9tr\u00e9ci et, en cons\u00e9quence, de fortes douleurs et des troubles de la sensibilit\u00e9 dans les jambes. Il se porte bien apr\u00e8s l'op\u00e9ration. \"Je vais tr\u00e8s bien\", dit-il, \"j'ai d\u00e9j\u00e0 vu des images et je suis fascin\u00e9 que cela soit possible. Bien s\u00fbr, je suis aussi fier d'avoir \u00e9t\u00e9 le premier patient \u00e0 vivre cela\".<\/p>\n<p>Source : balgrist \/ ETH<br \/>\n&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"Enfin de bonnes nouvelles d'un h\u00f4pital : une \u00e9quipe de l'H\u00f4pital universitaire Balgrist a men\u00e9 avec succ\u00e8s la...","protected":false},"author":12,"featured_media":18547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-18546","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Augmented Reality im Operationssaal - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2020\/12\/16\/augmented-reality-im-operationssaal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Augmented Reality im Operationssaal - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Endlich auch mal wieder Good News aus einem Spital: Ein Team der Universit\u00e4tsklinik Balgrist f\u00fchrte erfolgreich die erste&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2020\/12\/16\/augmented-reality-im-operationssaal\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-16T10:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Augmented Reality im Operationssaal\",\"datePublished\":\"2020-12-16T10:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/\"},\"wordCount\":366,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/csm_05_Hololens_TA_32706a54c9.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/\",\"name\":\"Augmented Reality im Operationssaal - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/csm_05_Hololens_TA_32706a54c9.jpg\",\"datePublished\":\"2020-12-16T10:43:16+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/csm_05_Hololens_TA_32706a54c9.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/csm_05_Hololens_TA_32706a54c9.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/12\\\/16\\\/augmented-reality-im-operationssaal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Augmented Reality im Operationssaal\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Augmented Reality im Operationssaal - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2020\/12\/16\/augmented-reality-im-operationssaal\/","og_locale":"fr_FR","og_type":"article","og_title":"Augmented Reality im Operationssaal - Schweizer Virtual Reality News","og_description":"Endlich auch mal wieder Good News aus einem Spital: Ein Team der Universit\u00e4tsklinik Balgrist f\u00fchrte erfolgreich die erste&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2020\/12\/16\/augmented-reality-im-operationssaal\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-12-16T10:43:16+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Augmented Reality im Operationssaal","datePublished":"2020-12-16T10:43:16+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/"},"wordCount":366,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/","url":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/","name":"Augmented Reality im Operationssaal - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg","datePublished":"2020-12-16T10:43:16+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/csm_05_Hololens_TA_32706a54c9.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2020\/12\/16\/augmented-reality-im-operationssaal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Augmented Reality im Operationssaal"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/18546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=18546"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/18546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/18547"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=18546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=18546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=18546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}