{"id":17174,"date":"2020-06-20T10:47:57","date_gmt":"2020-06-20T10:47:57","guid":{"rendered":"https:\/\/vr-room.ch\/?p=17174"},"modified":"2020-06-20T10:49:23","modified_gmt":"2020-06-20T10:49:23","slug":"pokemon-smile-ar-hilft-beim-zaehneputzen","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/","title":{"rendered":"Le sourire des Pok\u00e9mon : La RA aide \u00e0 se brosser les dents"},"content":{"rendered":"<p>Avec \"Pok\u00e9mon Smile\", The Pok\u00e9mon Company a lanc\u00e9 un jeu gratuit <a href=\"https:\/\/vr-room.ch\/fr\/virtual-reality-glossar\/#A\">Application AR<\/a> pour iOS et Android, dont le but est de motiver les enfants \u00e0 se brosser les dents tous les jours, de mani\u00e8re ludique bien s\u00fbr.<\/p>\n<p>\"Pok\u00e9mon Smile\" utilise la cam\u00e9ra de l'appareil mobile pour enregistrer les mouvements de l'enfant lorsqu'il se brosse les dents. Si l'enfant se brosse soigneusement les dents, il peut vaincre les bact\u00e9ries \u00e0 l'origine des caries et attraper ensuite des Pok\u00e9mon. Pour ce faire, il est aid\u00e9 \u00e0 brosser toutes les zones de la bouche. Au total, plus de 100 esp\u00e8ces de Pok\u00e9mon peuvent \u00eatre attrap\u00e9es et la bande-annonce donne des impressions.<\/p>\n<p>Les parents peuvent choisir de recevoir jusqu'\u00e0 trois notifications par jour de \"Pok\u00e9mon Smile\", qui leur rappellent qu'il est temps pour les enfants de se brosser les dents. De plus, la dur\u00e9e de chaque brossage de dents peut \u00e9galement \u00eatre r\u00e9gl\u00e9e entre une et trois minutes afin de r\u00e9pondre aux diff\u00e9rents besoins des enfants d'\u00e2ges diff\u00e9rents.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-17174-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=ECl_NRfTErc&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=ECl_NRfTErc\">https:\/\/www.youtube.com\/watch?v=ECl_NRfTErc<\/a><\/video><\/div>\n<p>Source : communiqu\u00e9 de presse<\/p>","protected":false},"excerpt":{"rendered":"Avec \"Pok\u00e9mon Smile\", The Pok\u00e9mon Company a lanc\u00e9 une application AR gratuite pour iOS et Android, dans laquelle...","protected":false},"author":11,"featured_media":17175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-17174","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Mit \u00abPok\u00e9mon Smile\u00bb hat The Pok\u00e9mon Company eine kostenlose AR-App f\u00fcr iOS und Android ver\u00f6ffentlicht, in der es&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-20T10:47:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-20T10:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"918\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen\",\"datePublished\":\"2020-06-20T10:47:57+00:00\",\"dateModified\":\"2020-06-20T10:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/\"},\"wordCount\":186,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pokemon_Smile.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/\",\"name\":\"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pokemon_Smile.jpg\",\"datePublished\":\"2020-06-20T10:47:57+00:00\",\"dateModified\":\"2020-06-20T10:49:23+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pokemon_Smile.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Pokemon_Smile.jpg\",\"width\":918,\"height\":532,\"caption\":\"Pok\u00e9mon Smile hilft Kindern beim Z\u00e4hneputzen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/06\\\/20\\\/pokemon-smile-ar-hilft-beim-zaehneputzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/","og_locale":"fr_FR","og_type":"article","og_title":"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News","og_description":"Mit \u00abPok\u00e9mon Smile\u00bb hat The Pok\u00e9mon Company eine kostenlose AR-App f\u00fcr iOS und Android ver\u00f6ffentlicht, in der es&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-06-20T10:47:57+00:00","article_modified_time":"2020-06-20T10:49:23+00:00","og_image":[{"width":918,"height":532,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen","datePublished":"2020-06-20T10:47:57+00:00","dateModified":"2020-06-20T10:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/"},"wordCount":186,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg","articleSection":["Entertainment"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/","url":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/","name":"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg","datePublished":"2020-06-20T10:47:57+00:00","dateModified":"2020-06-20T10:49:23+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/06\/Pokemon_Smile.jpg","width":918,"height":532,"caption":"Pok\u00e9mon Smile hilft Kindern beim Z\u00e4hneputzen"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2020\/06\/20\/pokemon-smile-ar-hilft-beim-zaehneputzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Pok\u00e9mon Smile: AR hilft beim Z\u00e4hneputzen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/17174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=17174"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/17174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/17175"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=17174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=17174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=17174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}