{"id":16212,"date":"2020-01-21T09:02:03","date_gmt":"2020-01-21T09:02:03","guid":{"rendered":"https:\/\/vr-room.ch\/?p=16212"},"modified":"2020-01-17T09:23:02","modified_gmt":"2020-01-17T09:23:02","slug":"im-landesmuseum-die-gaming-geschichte-erleben","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","title":{"rendered":"D\u00e9couvrir l'histoire du jeu au mus\u00e9e national"},"content":{"rendered":"<h3 id=\"eine-neue-ausstellung-im-landesmuseum-zeigt-vom-17-01-bis-13-04-2020-die-geschichte-der-videogames-waehrend-der-letzten-50-jahre-die-besucher-koennen-mitspielen-und-auch-vr-kann-ausprobiert-we\">Du 17 janvier au 13 avril 2020, une nouvelle exposition au Mus\u00e9e national retrace l'histoire des jeux vid\u00e9o au cours des 50 derni\u00e8res ann\u00e9es. Les visiteurs peuvent y jouer et il est \u00e9galement possible d'essayer la VR.<\/h3>\n<p><!--more--><\/p>\n<p>Il y a quelques d\u00e9cennies encore, les jeux vid\u00e9o \u00e9taient consid\u00e9r\u00e9s comme des gadgets scientifiques. Aujourd'hui, le jeu est devenu l'une des activit\u00e9s de loisirs les plus populaires. Entre 2016 et 2019, le chiffre d'affaires de ce secteur encore jeune a augment\u00e9 d'environ 22 milliards pour atteindre pr\u00e8s de 123 milliards de dollars am\u00e9ricains, un succ\u00e8s sup\u00e9rieur \u00e0 celui de l'industrie cin\u00e9matographique d'Hollywood, par exemple. Le Mus\u00e9e national de Zurich consacre une exposition \u00e0 ce ph\u00e9nom\u00e8ne extraordinaire.<\/p>\n<h3 id=\"vom-tennis-fuer-2-ueber-grosse-arcaden\">Du tennis pour 2 aux grandes arcades...<\/h3>\n<p>Aujourd'hui, environ 2,5 milliards de personnes jouent. Cela repr\u00e9sente un tiers de la population mondiale. La fascination pour les jeux vid\u00e9o a d\u00e9but\u00e9 dans les ann\u00e9es 1950 aux \u00c9tats-Unis. William Higinbotham a permis \u00e0 tous ceux qui n'aimaient pas le sport de jouer au tennis confortablement install\u00e9s dans leur canap\u00e9. Le \"Tennis for Two\" du physicien a \u00e9t\u00e9 le deuxi\u00e8me jeu vid\u00e9o au monde et le v\u00e9ritable point de d\u00e9part de son d\u00e9veloppement. Au plus tard \u00e0 partir des ann\u00e9es 1970, les jeux sont devenus un facteur \u00e9conomique s\u00e9rieux.<\/p>\n<p>Les jeux \u00e9lectroniques ont fait leur entr\u00e9e dans les salons et ont \u00e9t\u00e9 commercialis\u00e9s en tant qu'activit\u00e9 familiale. Parall\u00e8lement, les jeux vid\u00e9o se sont \u00e9galement impos\u00e9s dans les espaces publics. Dans les salles d'arcade, ils devinrent un s\u00e9rieux concurrent pour les flippers, jusqu'alors tr\u00e8s populaires. Une \u00e8re dor\u00e9e s'ouvrait : L'\u00e9poque des jeux d'arcade. Dans les restaurants, les centres commerciaux ou les a\u00e9roports, on pouvait jouer \u00e0 des jeux comme \"Pac-Man\" ou \"Space Invaders\" et plus d'un contemporain jouait tout son argent de poche sur ces bo\u00eetes populaires.<\/p>\n<h3 id=\"zu-partys-und-schlussendlich-vr\">... aux f\u00eates et enfin \u00e0 la RV<\/h3>\n<p>Une d\u00e9cennie plus tard, les premi\u00e8res LAN parties ont vu le jour. Les joueurs se r\u00e9unissaient et connectaient leurs ordinateurs via un r\u00e9seau local pour jouer ensemble. Ces groupes remplissaient parfois des salles enti\u00e8res. Parall\u00e8lement, l'industrie informatique a d\u00e9velopp\u00e9 des appareils mobiles, permettant ainsi de jouer en ligne et en d\u00e9placement. Au cours du nouveau mill\u00e9naire, les jeux vid\u00e9o ont finalement \u00e9t\u00e9 combin\u00e9s \u00e0 la r\u00e9alit\u00e9 virtuelle. L'immersion totale dans les mondes de jeu \u00e9tait une toute nouvelle exp\u00e9rience.<\/p>\n<p>\"Il a \u00e9t\u00e9 plus difficile de choisir des pi\u00e8ces d'exposition pour les ann\u00e9es 2010\", explique le co-commissaire Michael Kempf. \"Nous avons finalement opt\u00e9 pour une salle enti\u00e8rement consacr\u00e9e \u00e0 la r\u00e9alit\u00e9 virtuelle, car beaucoup de nos visiteurs n'ont probablement pas eux-m\u00eames de casques VR chez eux et peuvent les essayer ici\".<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-16214\" src=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-300x200.jpg\" alt=\"\" width=\"465\" height=\"310\" srcset=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-300x200.jpg 300w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-768x512.jpg 768w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-1024x683.jpg 1024w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-1110x740.jpg 1110w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-730x487.jpg 730w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-539x359.jpg 539w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-350x233.jpg 350w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-254x169.jpg 254w, https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/12_virtual-reality_2010er-125x83.jpg 125w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/p>\n<p>Sp\u00e9cialement pour l'exposition, Ruppert a d\u00e9velopp\u00e9 un jeu vid\u00e9o qui se base sur la <a href=\"https:\/\/www.landesmuseum.ch\/games\" target=\"_blank\" rel=\"noopener noreferrer\">Site web du mus\u00e9e national<\/a> peut \u00eatre jou\u00e9. \"Nous voulions voir comment les gens r\u00e9agissaient \u00e0 la publicit\u00e9 par le biais d'un jeu\", explique Alice Ruppert, game designer suisse.<\/p>\n<h3 id=\"kritischer-blick\">Un regard critique<\/h3>\n<p>\"Lors de la conception de l'exposition, nous avions en t\u00eate un public jeune, par exemple des classes scolaires, pour lesquelles elle est tr\u00e8s int\u00e9ressante en raison de son interactivit\u00e9\", explique Stuber. Mais elle est \u00e9galement attrayante pour un public plus \u00e2g\u00e9, et pas seulement en raison du facteur nostalgie. \"Les grands-parents peuvent tr\u00e8s bien visiter l'exposition avec leurs petits-enfants et se faire expliquer les choses pour une fois par les enfants\", estime Michael Kempf.<\/p>\n<p>Mais l'exposition porte \u00e9galement un regard critique sur l'\u00e9volution des jeux au fil des ann\u00e9es. Sur les nombreux \u00e9crans r\u00e9partis dans les salles, la cat\u00e9gorie \"toxic\" (toxique) aborde des th\u00e8mes comme la d\u00e9pendance au jeu ou la violence dans les jeux vid\u00e9o.<\/p>\n<p>Des stations de jeu invitent \u00e0 se plonger dans des mondes virtuels et \u00e0 essayer les jeux eux-m\u00eames. L'entr\u00e9e est gratuite pour les jeunes jusqu'\u00e0 16 ans et co\u00fbte 10 francs pour les adultes. Dans ce sens, let's play !<\/p>\n<p>Source : Mus\u00e9e national, 20 minutes<\/p>","protected":false},"excerpt":{"rendered":"Du 17 janvier au 13 avril 2020, une nouvelle exposition au Mus\u00e9e national retrace l'histoire des jeux vid\u00e9o au cours des 50 derni\u00e8res...","protected":false},"author":12,"featured_media":16213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-16212","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Eine neue Ausstellung im Landesmuseum zeigt vom 17.01. bis\u00a0 13.04.2020 die Geschichte der Videogames w\u00e4hrend der letzten 50&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T09:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Im Landesmuseum die Gaming-Geschichte erleben\",\"datePublished\":\"2020-01-21T09:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"},\"wordCount\":553,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\",\"name\":\"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"datePublished\":\"2020-01-21T09:02:03+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/00_games-key-visual-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2020\\\/01\\\/21\\\/im-landesmuseum-die-gaming-geschichte-erleben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Landesmuseum die Gaming-Geschichte erleben\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","og_locale":"fr_FR","og_type":"article","og_title":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","og_description":"Eine neue Ausstellung im Landesmuseum zeigt vom 17.01. bis\u00a0 13.04.2020 die Geschichte der Videogames w\u00e4hrend der letzten 50&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-01-21T09:02:03+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Im Landesmuseum die Gaming-Geschichte erleben","datePublished":"2020-01-21T09:02:03+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"},"wordCount":553,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","url":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/","name":"Im Landesmuseum die Gaming-Geschichte erleben - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","datePublished":"2020-01-21T09:02:03+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/01\/00_games-key-visual-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2020\/01\/21\/im-landesmuseum-die-gaming-geschichte-erleben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Im Landesmuseum die Gaming-Geschichte erleben"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/16212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=16212"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/16212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/16213"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=16212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=16212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=16212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}