{"id":15333,"date":"2019-10-15T09:40:20","date_gmt":"2019-10-15T09:40:20","guid":{"rendered":"https:\/\/vr-room.ch\/?p=15333"},"modified":"2019-10-09T09:57:07","modified_gmt":"2019-10-09T09:57:07","slug":"deutsches-auswandererhaus-testet-virtuelle-realitaet","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/","title":{"rendered":"Le Deutsches Auswandererhaus fournit une \u00e9tude sur la RV"},"content":{"rendered":"<section class=\"content\" data-type=\"text\">\n<h3 id=\"in-einem-experiment-haben-die-meisten-teilnehmer-virtuellen-elementen-im-museum-einen-groesseren-unterhaltungswert-als-konventionellen-praesentationsformen-beigemessen-ueberraschenderweise-loeste-vr\" class=\"font_primary color_black article-text font-weight-normal bold\">Lors d'une exp\u00e9rience, la plupart des participants ont attribu\u00e9 aux \u00e9l\u00e9ments virtuels dans les mus\u00e9es une plus grande valeur de divertissement que les formes de pr\u00e9sentation conventionnelles. De mani\u00e8re surprenante, la RV a en revanche suscit\u00e9 moins d'empathie. C'est \u00e0 cet \u00e9v\u00e9nement que le <a href=\"https:\/\/dah-bremerhaven.de\/museum4punkt0\/\">maison de l'\u00e9migration allemande \u00e0 Bremerhaven<\/a> apr\u00e8s une phase de test avec VR.<\/h3>\n<\/section>\n<p><!--more--><\/p>\n<section class=\"content\" data-type=\"text\">Comment la num\u00e9risation peut-elle \u00eatre mise en \u0153uvre dans les mus\u00e9es ? O\u00f9 et comment les nouvelles technologies peuvent-elles aider \u00e0 transmettre des contenus mus\u00e9aux ? Dans le cadre du projet de recherche \"museum4punkt0 - Strat\u00e9gies num\u00e9riques pour le mus\u00e9e du futur\", le Deutsches Auswandererhaus Bremerhaven se penche sur la question de la transmission num\u00e9rique des aspects historiques et \u00e9motionnels de la migration : Une \u00e9tude d'exposition compare les formes de narration num\u00e9riques et analogiques, des \u00e9valuations dans le mus\u00e9e et sur le site web testent les possibilit\u00e9s d'impliquer les visiteurs avant et apr\u00e8s la visite physique du mus\u00e9e. Parall\u00e8lement, les activit\u00e9s de collecte du mus\u00e9e seront \u00e9tendues au num\u00e9rique et compl\u00e9t\u00e9es par des interviews d'histoire orale. En outre, des comp\u00e9tences m\u00e9diatiques seront transmises et les aspects irrationnels des d\u00e9bats sur la migration seront pr\u00e9sent\u00e9s aux visiteurs \u00e0 l'aide des nouvelles technologies.<\/p>\n<h3 id=\"analoge-und-virtuelle-realitaeten-im-vergleich\" class=\"widget-title\">Comparaison des r\u00e9alit\u00e9s analogiques et virtuelles<\/h3>\n<div class=\"textwidget\">\n<p>Au d\u00e9but de l'exp\u00e9rience avec l'aide de la r\u00e9alit\u00e9 virtuelle, la question \u00e9tait donc de savoir si les visiteurs du mus\u00e9e se laissaient emporter \u00e9motionnellement par la nouvelle technique. Quelle est l'importance des objets originaux \u00e0 l'\u00e9poque de la num\u00e9risation ? Les sensations des personnes \u00e9trang\u00e8res sont-elles mieux transmises par des objets biographiques ou par des histoires num\u00e9riques ?<\/p>\n<p>Dans l'exposition-exp\u00e9rience \"KRIEGsgefangen. OHNMACHT. SEHNSUCHT. 1914 - 1921\", on a cherch\u00e9 \u00e0 savoir si et comment l'empathie pouvait \u00eatre transmise par voie num\u00e9rique. Dans l'exposition, certains contenus \u00e9taient accessibles aussi bien dans les salles d'exposition classiques que sous forme num\u00e9rique \u00e0 l'aide de lunettes VR. Le th\u00e8me \u00e9tait le destin d'un prisonnier de guerre de la Premi\u00e8re Guerre mondiale et de sa famille \u00e0 Hambourg. Sur la base d'enqu\u00eates auxquelles ont particip\u00e9 plus de 700 visiteurs avant et apr\u00e8s la visite de l'exposition, une \u00e9tude \u00e0 grande \u00e9chelle analyse les diff\u00e9rents effets de ces formes de narration.<\/p>\n<\/div>\n<p class=\"font_primary color_black article-text font-weight-normal\">Die Mehrheit der Teilnehmer bescheinigen den virtuellen Elementen einen gr\u00f6sseren Unterhaltungswert. Doch &#8222;museale Objekte erzeugen mehr Mitgef\u00fchl f\u00fcr historische Personen als &#8222;Virtual-Reality&#8220;-Anwendungen&#8220;, sagte Museumsdirektorin Simone Eick. Letzteres widerspricht demnach ein wenig der <a href=\"https:\/\/vr-room.ch\/fr\/2019\/10\/09\/virtual-reality-als-neue-kommunikationsmethode-fuer-ngos\/\">\u00c9tude<\/a> de l'International School of Management, qui a montr\u00e9, dans le contexte des ONG, que la RV d\u00e9clenche de l'empathie.<\/p>\n<\/section>\n<section class=\"content\" data-type=\"text\">Source : Auswandererhaus \/ RTL<\/section>","protected":false},"excerpt":{"rendered":"Lors d'une exp\u00e9rience, la plupart des participants ont attribu\u00e9 aux \u00e9l\u00e9ments virtuels du mus\u00e9e une plus grande valeur de divertissement que les formes de pr\u00e9sentation conventionnelles....","protected":false},"author":12,"featured_media":15334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"class_list":{"0":"post-15333","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-gesellschaft","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"In einem Experiment haben die meisten Teilnehmer virtuellen Elementen im Museum einen gr\u00f6sseren Unterhaltungswert als konventionellen Pr\u00e4sentationsformen beigemessen.&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-15T09:40:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Deutsches Auswandererhaus liefert Studie zu VR\",\"datePublished\":\"2019-10-15T09:40:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/\"},\"wordCount\":363,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/auswanderer.jpg\",\"articleSection\":[\"Gesellschaft\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/\",\"name\":\"Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/auswanderer.jpg\",\"datePublished\":\"2019-10-15T09:40:20+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/auswanderer.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/auswanderer.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2019\\\/10\\\/15\\\/deutsches-auswandererhaus-testet-virtuelle-realitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutsches Auswandererhaus liefert Studie zu VR\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/","og_locale":"fr_FR","og_type":"article","og_title":"Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News","og_description":"In einem Experiment haben die meisten Teilnehmer virtuellen Elementen im Museum einen gr\u00f6sseren Unterhaltungswert als konventionellen Pr\u00e4sentationsformen beigemessen.&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2019-10-15T09:40:20+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Deutsches Auswandererhaus liefert Studie zu VR","datePublished":"2019-10-15T09:40:20+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/"},"wordCount":363,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg","articleSection":["Gesellschaft"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/","url":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/","name":"Deutsches Auswandererhaus liefert Studie zu VR - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg","datePublished":"2019-10-15T09:40:20+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/10\/auswanderer.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2019\/10\/15\/deutsches-auswandererhaus-testet-virtuelle-realitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Deutsches Auswandererhaus liefert Studie zu VR"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/15333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=15333"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/15333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/15334"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=15333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=15333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=15333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}