{"id":12602,"date":"2019-01-21T18:30:38","date_gmt":"2019-01-21T18:30:38","guid":{"rendered":"http:\/\/vr-room.ch\/?p=12602"},"modified":"2019-01-22T15:46:46","modified_gmt":"2019-01-22T15:46:46","slug":"15-vr-spiele-auf-die-wir-uns-freuen","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/","title":{"rendered":"15 jeux VR que nous attendons avec impatience"},"content":{"rendered":"<p>2018 ist vorbei und es war ein grossartiges VR-Jahr. Es waren nicht wenige geniale Vorzeigetitel wie <a href=\"http:\/\/vr-room.ch\/2018\/10\/12\/astro-bot-rescue-mission-im-test\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abAstro Bot: Rescue Mission\u00bb<\/a>, <a href=\"http:\/\/vr-room.ch\/2017\/11\/16\/test-so-fuehlt-sich-skyrim-in-vr-an\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abSkyrim VR\u00bb<\/a> und\u00a0<a href=\"http:\/\/vr-room.ch\/2018\/11\/20\/lichtschwert-test-beat-saber\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abBeat Saber\u00bb<\/a>,\u00a0die uns best\u00e4tigt haben, was in der VR noch m\u00f6glich ist \u2013 aber erst recht, was alles noch kommen mag. Eines ist sicher:\u00a0Es werden immer vielseitigere und umfassendere virtuelle Abenteuer. Einen Vorgeschmack auf die Spiele, auf die wir uns in diesem Jahr besonders freuen, wollen wir euch an dieser Stelle nicht vorenthalten.<\/p>\n<h2 id=\"blood-and-truth-psvr\">Blood and Truth (PSVR)<\/h2>\n<p>Mit \u00abBlood &amp; Truth\u00bb wartet ein Sequel zu \u00abThe London Heist\u00bb auf uns: Der kurze, aber eindr\u00fcckliche Noir-Shooter mit eindr\u00fccklichen Szenen wie Drive-by-Ganoven-Erledigung aus einer Autoverfolgungsjagd spielte sich schon damals mit den Move Controllern geschmeidig. Ein Datum f\u00fcr die Ver\u00f6ffentlichung des geistigen Nachfolgers gibt es noch nicht, aber Sony lud Gamejournalisten bereits vor einigen Monaten zum Ausprobieren ein. Unsere Kollegen vom Games.ch haben den Shooter f\u00fcr uns\u00a0<a href=\"http:\/\/vr-room.ch\/2018\/12\/15\/hands-on-blood-and-truth\/\" target=\"_blank\" rel=\"noopener noreferrer\">angetestet<\/a>\u00a0und hatten trotz kleiner Kritik am Tracking ihren Spass an dem Mix\u00a0aus Schusswaffen, Handgranaten, Klettereinlagen und ein Minispielen. Das Spielgeschehen basiert auf einer Mischung von Stehen, Bewegen, Teleportieren und Ausweichen, gepaart mit Elementen wie dem Knacken von Schl\u00f6ssern.<\/p>\n<p><iframe loading=\"lazy\" title=\"Blood &amp; Truth - PGW 2017 Announce Trailer | PS VR\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/F25wPhd9r4I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"stormland-oculus-rift\">Stormland (Oculus Rift)<\/h2>\n<p>In \u00abStormland\u00bb schl\u00fcpft ihr in die Rolle eines apokalyptischen Androiden. Nach unz\u00e4hligen Jahren, von einem Sturm zerfetzt, erwacht ihr\u00a0 aus dem Tiefschlaf und befindet euch pl\u00f6tzlich in einer v\u00f6llig anderen Umgebung. Zu Fuss und mit Klettergeschick begegnet ihr in der Zukunft weiteren Robotern, die euch nicht unbedingt freundlich gesinnt sind. Die offene Spielwelt soll sowohl zu einem Singleplayer- als auch zu einem Koop-Modus einladen. Dabei werdet ihr auch mittels Crafting zahlreiche neue Ausr\u00fcstungsgegenst\u00e4nde aneignen. Nach und nach werden mit erweiterten F\u00e4higkeiten neue Orte in der grossen Welt freigeschaltet.<\/p>\n<p><iframe loading=\"lazy\" title=\"Stormland | E3 Announce Trailer | Oculus Rift\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/2Ak2h3PkY1I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"deflector-rift\">Deflector (Rift)<\/h2>\n<p>Bei \u00abDeflector\u00bb, aus der Schmiede von <a href=\"https:\/\/www.oculus.com\/experiences\/rift\/1225484597472435\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abWilson&#8217;s Heart\u00bb<\/a>, handelt es sich um einen Rift-Exklusivtitel. Ihr schl\u00fcpft in die Rolle eines Agenten, der ein globales Verbrechersyndikat aufdecken soll. Dabei geht es offenbar nicht nur darum, b\u00f6se Kerle mit eurem Schusseisen dingfest zu machen: Vereinzelt warten auch Faustk\u00e4mpfe auf euch und ihr k\u00f6nnt euch auf spektakul\u00e4re Stunt-Aktionen freuen. Die Kollegen von \u00abRoad to VR\u00bb (siehe\u00a0 Video) haben den Titel bereits im Rahmen einer Hands-on-Session angespielt. Jetzt warten wir nur noch auf einen Release-Termin, den man sich im Kalender markieren kann.<\/p>\n<p><iframe loading=\"lazy\" title=\"&#039;Defector&#039; Gameplay \u2013 Oculus Rift Exclusive\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/G3eHB3BEMIo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"eden-tomorrow-psvr\">Eden Tomorrow (PSVR)<\/h2>\n<p>Das urspr\u00fcnglich f\u00fcr Oculus Rift geplante Sci-Fi-Abenteuer \u00abEden Tomorrow\u00bb erscheint bald exklusiv auf der PlayStation VR. Ausprobieren konnten es schon unsere Kollegen vom Games.ch und haben uns einen Ersteindruck <a href=\"http:\/\/vr-room.ch\/2018\/11\/21\/vorschau-eden-tomorrow-psvr\/\" target=\"_blank\" rel=\"noopener noreferrer\">zur Verf\u00fcgung gestellt<\/a>. Ihrem ersten Urteil nach soll das Abenteuer ziemlich vielversprechend sein.\u00a0Es kommt noch besser:\u00a0Seit wenigen Tagen steht nun die offizielle Demo im PlayStation Store <a href=\"https:\/\/store.playstation.com\/de-ch\/product\/EP2299-CUSA13009_00-ETDEMO0000000002\" target=\"_blank\" rel=\"noopener noreferrer\">zum Ausprobieren bereit<\/a>. Man darf jetzt nur noch gespannt sein, was die Entwickler\u00a0aus der finalen Version machen. Irgendwann im ersten Quartal 2019 soll es soweit sein.<\/p>\n<p><iframe loading=\"lazy\" title=\"Eden-Tomorrow | PGW 2017 Trailer | PlayStation VR\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/fiOSvdKfCl8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"the-gallery-episode-3\">The Gallery Episode 3<\/h2>\n<p>\u00abThe Gallery\u00bb aus den H\u00e4nden der kanadischer VR-Profis von \u00abCloudhead Games\u00bb ist bis jetzt als zweiteiliges Epos f\u00fcr Oculus Rift und HTC Vive erschienen. Der erste Part \u00abCall of The Starseed\u00bb war angesichts der fr\u00fchen PC-VR-Brillenzeit fast schon ein Meisterwerk, weil sowohl Gameplay als auch Grafik und Filmsequenzen auf der verlassenen Insel \u00fcberzeugten. Wer sich noch an das explorative \u00abMyst\u00bb-Puzzle-Adventure aus den Neunzigern erinnert, wird darin \u00e4hnliche Elemente wiedererkennen, weil es vor allem darum geht, einfachere bis mittelschwere R\u00e4tsel mit Gegenst\u00e4nden zu l\u00f6sen, um dem Spielplot folgen zu k\u00f6nnen.\u00a0Der zweite Teil, \u00abHeart of The Emberstone\u00bb, beinhaltet aufregende F\u00e4higkeiten mit euren H\u00e4nden.\u00a0Dazu z\u00e4hlen auch Gravitation und Spezialhandschuhe, um Gegenst\u00e4nde herumzuschleudern. Einen ersten Trailer zum dritten Teil gibt es noch nicht. Wer die beiden Puzzle-Abenteuer nicht kennt, schaue sich einmal den Trailer von Teil 2 an.<\/p>\n<p><iframe loading=\"lazy\" title=\"The Gallery: Heart of the Emberstone - VR Launch Trailer\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/3GAJ4krEetU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"lone-echo-2-oculus-rift\">Lone Echo 2 (Oculus Rift)<\/h2>\n<p>Der Schwerkraft ausgeliefert, erkundet ihr in dem Weltraum-Puzzle-Abenteuer \u00abLone Echo 2\u00bb f\u00fcr Oculus Rift als humanoider Roboter \u2013 aller Voraussicht nach \u2013 wieder eine sehr detailreiche Weltraumstation. Noch sind aber nicht viele Infos zum Sequel <a href=\"http:\/\/vr-room.ch\/2018\/09\/30\/lone-echo-2-oculus-rift\/\" target=\"_blank\" rel=\"noopener noreferrer\">durchgesickert<\/a>. Die Space-Physik des Vorg\u00e4ngers war f\u00fcr ein VR-Spiel auf jeden Fall sehr eindr\u00fccklich umgesetzt, wie ihr <a href=\"http:\/\/vr-room.ch\/2017\/07\/24\/lone-echo-fuer-oculus-rift-im-test\/\" target=\"_blank\" rel=\"noopener noreferrer\">in unserem Test<\/a> nachlesen k\u00f6nnt. Ihr klammert euch an S\u00e4ulen fest und lasst euch bei Bedarf von der Schubkraft treiben. Immerhin haben Oculus Studios und Ready At Dawn haben bereits einen ersten Trailer sowie ein 360-Grad-Video zu \u00abLone Echo 2\u00bb ver\u00f6ffentlicht.<\/p>\n<p><iframe loading=\"lazy\" title=\"Lone Echo II | 360 Experience Trailer | Oculus Rift\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/Z3xJB8QcSAo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"golem-psvr\">Golem (PSVR)<\/h2>\n<p>Wo bleibt eigentlich \u00abGolem\u00bb? Der schon vielfach angepriesene PSVR-Titel von Highware Games hat erneut Versp\u00e4tung, war das Exklusiv-Spiel doch zuletzt auf 2018 angek\u00fcndigt worden.\u00a0Dabei hat man\u00a0den Titel schon sehr fr\u00fch nach der Lancierung der PlayStation VR in Aussicht gestellt. Aber die Hoffnung stirbt ja bekanntlich zuletzt.\u00a0Das Abenteuer erz\u00e4hlt die Geschichte von einem M\u00e4dchen, das einen schweren Unfall erlitt. Sie entwickelt darauf magische Kr\u00e4fte, mit denen sie die Kontrolle \u00fcber Golems \u00fcbernehmen kann.\u00a0Nach wie vor ist leider kein\u00a0genauer\u00a0Ver\u00f6ffentlichungstermin bekannt \u2013 aber wir warten gerne.<\/p>\n<p><iframe loading=\"lazy\" title=\"PlayStation Experience 2015: Golem - Announcement Trailer | PS VR\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/lAC8_DHvb78?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"a-fishermans-tale-vive-rift-wmr-psvr\">A Fisherman&#8217;s Tale (Vive, Rift, WMR, PSVR)<\/h2>\n<p>Bei \u00abA Fisherman&#8217;s Tale\u00bb seid ihr quasi in euch selbst gefangen. Originell: In einem Leuchtturm eingesperrt, l\u00f6st ihr als Marionette verschiedene R\u00e4tsel, indem ihr eine Puppenhaus-Miniaturversion desselben Raums manipuliert. So seht ihr, wenn ihr in den Himmel schaut, eine riesige Verson von euch selbst, die auf euch herunter blickt. Ein spezielles\u00a0Ambiente vermittelt da gewiss auch die witzig designte Comic-Welt, die schon im ersten Trailer ihren ganz speziellen Charme verspr\u00fcht.<\/p>\n<p><iframe loading=\"lazy\" title=\"A Fisherman&#039;s Tale - Gameplay Trailer | PS VR\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/qZtzlnwrggc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"star-child-psvr\">Star Child (PSVR)<\/h2>\n<p>Es hiess einmal, die Arbeit an \u00abStar Child\u00bb, von den Machern von <a href=\"https:\/\/www.oculus.com\/experiences\/rift\/909129545868758\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abLucky&#8217;s Tale\u00bb<\/a> (2016), sei abgebrochen worden. Aber offenbar\u00a0befindet sich das Spiel f\u00fcr PSVR nach wie vor in der Entwicklung.\u00a0Nichts Neues gibt es aber zu einem Ver\u00f6ffentlichungstermin. Die\u00a0Macher des stereoskopischen VR-Plattformers haben mit \u00abLucky&#8217;s Tale\u00bb damals einen geschmeidigen 3D-H\u00fcpfer in bester Qualit\u00e4t abgeliefert. Der knuddlige\u00a0Rift-Launch-Titel ist auch heute noch ein Geheimtipp.\u00a0Trotz des geringen Einbezugs der VR-M\u00f6glichkeiten war es ein tolles Spiel. Auch bei \u00abStar Child\u00bb verfolgt ihr Geschehen aus einer m\u00f6glicherweise aufregenden Puppentheatersicht.<\/p>\n<p><iframe loading=\"lazy\" title=\"Star Child - PS VR Announce Trailer | E3 2017\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/cRKiFsXvdyw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"firmament-rift-vive\">Firmament (Rift, Vive)<\/h2>\n<p>Ein Spiel von Cyan! Tats\u00e4chlich befindet sich sogar aus der Entwicklergarage der Mausklick-R\u00e4tsel aus den Neunzigern (\u00abMyst\u00bb und \u00abObduction\u00bb) ein VR-Spiel in Entwicklung. Noch\u00a0ist aber vieles zu dem Game-Projekt \u00abFirmament\u00bb unter Verschluss. Laut den Entwicklern geht es um eine \u00abmonumentale Reise durch verschiedene geheimnisvolle Welten\u00bb. Da sind wir einmal gespannt.\u00a0Als \u00abAmuse Bouche\u00bb bleibt uns da im Moment nur ein mystischer Trailer \u2013 aber es soll ja spannend werden.<\/p>\n<p><iframe loading=\"lazy\" title=\"Firmament Teaser Trailer\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/9-DpB7tXs4g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"dreams-psvr\">Dreams (PSVR)<\/h2>\n<p>Shooter, Plattformer oder interaktiver Film? \u00abDreams\u00bb stammt von den Machern des Kulthits \u00abLittle Big Planet\u00bb. Der Kreativtitel l\u00e4sst euch eine komplette Spielwelt nach eigenen Vorlieben erzeugen und mit Freunden oder der Community teilen. Dabei werdet ihr verschiedene Gestalten annehmen: Der Kreativit\u00e4t sind beinahe keine Grenzen gesetzt. Selbst das Erzeugen von Filmen und Musik ohne Gameplay ist m\u00f6glich. Es w\u00fcrde nicht \u00fcberraschen, wenn Sony nach <a href=\"http:\/\/vr-room.ch\/2018\/10\/12\/astro-bot-rescue-mission-im-test\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0\u00abAstro Bot: Rescue Mission\u00bb<\/a>, dem VR-Spiel des Jahres (2018), gleich einen weiteren Knaller mit Alleinstellungsmerkmalen herausbringt.<\/p>\n<p><a href=\"https:\/\/youtu.be\/odfYSiTpXpo\">https:\/\/youtu.be\/odfYSiTpXpo<\/a><\/p>\n<h2 id=\"wolfenstein-cyberpilot-vive-psvr\">Wolfenstein: Cyberpilot (Vive, PSVR)<\/h2>\n<p>Ob es nach <a href=\"https:\/\/www.games.ch\/doom-vfr\/test\/review-giaT\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abDoom VFR\u00bb<\/a> noch ein weiterer Bethesda-Ableger in die Hitparade der VR-Shooter-Zone schafft? Offenbar vermochte die erste Pr\u00e4sentation an der E3 noch nicht die ganze Audienz zu \u00fcberzeugen.\u00a0Was nicht ist, kann ja noch werden. Ihr seid jedenfalls wieder B.J. Blazkowicz, den man schon vom Ur-Wolfenstein kennt, und k\u00fcmmert euch ums Hacken verschiedener Kriegsmaschinerien, aber auch ums Beseitigen s\u00e4mtlicher Nazi-Horden. Gemessen an dem aktiven Communitiy-Austausch kleineren VR-Entwicklergemeinden, wird Bethesda als Triple-A-Studio gewiss noch an vielen Details des Titels feilen. Hoffen wirs.<\/p>\n<p><iframe loading=\"lazy\" title=\"Wolfenstein: Cyberpilot (VR) \u2013 Offizieller E3-Ank\u00fcndigungstrailer\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/heTH0P2o9vc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"titan-arena-rift-vive\">Titan Arena (Rift, Vive)<\/h2>\n<p>Wenn die virtuelle Realit\u00e4t etwas in ziemlich eindr\u00fccklicher Weise zu vermitteln vermag, dann gewiss die Ego-Sicht aus einem riesigen Titanen.\u00a0Man muss nur einmal einen Railshooter wie <a href=\"http:\/\/vr-room.ch\/2017\/08\/13\/archangel-fuer-htc-vive-im-test\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abArchangel\u00bb<\/a>\u00a0spielen, um aus der kolossalen Egoperspektive in einen \u00abMechwarrior\u00bb zu schl\u00fcpfen. \u00c4hnlich wie \u00abShadow of the Colossus\u00bb d\u00fcrfte das opulent anmutende Abenteuer, von dem es schon einen Trailer gibt, aber eher eine ruhige Erkundungs-Adventure-Komponente ins Spiel bringen, bei dessen Handlung es haupts\u00e4chlich um die Zermalmung grosser Titanen geht. An diesem Gedanken finden wir aber schon einmal Gefallen \u2013 auch am Trailer.<\/p>\n<p><iframe loading=\"lazy\" title=\"Titan Arena Work In Progress Trailer\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/ONQ5YIXadGA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"ghost-giant-psvr\">Ghost Giant (PSVR)<\/h2>\n<p>Sony hat mit \u00abGhost Giant\u00bb ein weiteres neues Abenteuerspiel f\u00fcr Playstation VR angek\u00fcndigt, das von Grund auf f\u00fcr die VR-Brille entwickelt wurde. Ihr habt das Geschick der Spielfigur eines geistigen Wesens in der Hand. Eure H\u00e4nde sind es auch, die dem einsamen Farmerjungen Louis durch den beschwerlichen Alltag helfen. \u00c4hnlich wie bei bei \u00abMoss\u00bb unterst\u00fctzt ihr den Protoganisten, indem ihr dem Jungen mit euren Astralh\u00e4nden den Weg weist. Dabei gilt es, das Geschehen zu beobachten und gleichzeitig Fenster und T\u00fcren in der Umgebung zu \u00f6ffnen.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ghost Giant - E3 2018 Announcement Trailer | PS VR\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/hEJnJz43e10?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"space-junkies-vive-rift\">Space Junkies (Vive, Rift)<\/h2>\n<p>\u00abSpace Junkies\u00bb ist laut Ubisoft ein Arcade-Shooter mit Jetpack-Action, der exklusiv f\u00fcr die Virtual Reality entwickelt wird. Der Titel bietet den Machern zufolge einen \u00abintuitiven, rasanten Mehrspieler-Spass in dreidimensionalen, orbitalen Arenen\u00bb. Unterst\u00fctzt wird eine volle VR-K\u00f6rpersteuerung, wodurch man in intensive und schwerelose K\u00e4mpfe eintauchen kann. An einer Closed Beta konnte man letztes Jahr schon teilnehmen (<a href=\"http:\/\/vr-room.ch\/2017\/10\/23\/vr-shooter-space-junkies-beta\/\" target=\"_blank\" rel=\"noopener noreferrer\">wir berichteten<\/a>): \u00abSpace Junkies\u00bb wird im Fr\u00fchjahr 2018 f\u00fcr Oculus Rift mit Touch und HTC Vive erscheinen.<\/p>\n<p><iframe loading=\"lazy\" title=\"Space Junkies - Official Trailer - VR Arcade Shooter | Trailer | Ubisoft [NA]\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/t3xUKjhsjiU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"L'ann\u00e9e 2018 est termin\u00e9e et elle a \u00e9t\u00e9 une grande ann\u00e9e pour la VR. Il y a eu des titres phares g\u00e9niaux comme \"Astro Bot :...","protected":false},"author":13,"featured_media":12625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-12602","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"2018 ist vorbei und es war ein grossartiges VR-Jahr. Es waren nicht wenige geniale Vorzeigetitel wie \u00abAstro Bot:&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-21T18:30:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-22T15:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/\"},\"author\":{\"name\":\"Simon\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/eb899844a9b1c36243c97c7cadb9401b\"},\"headline\":\"15 VR-Spiele, auf die wir uns freuen\",\"datePublished\":\"2019-01-21T18:30:38+00:00\",\"dateModified\":\"2019-01-22T15:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/\"},\"wordCount\":1647,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stormland_teaser3-scaled.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/\",\"name\":\"15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stormland_teaser3-scaled.jpg\",\"datePublished\":\"2019-01-21T18:30:38+00:00\",\"dateModified\":\"2019-01-22T15:46:46+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/eb899844a9b1c36243c97c7cadb9401b\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stormland_teaser3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/stormland_teaser3-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/01\\\/21\\\/15-vr-spiele-auf-die-wir-uns-freuen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 VR-Spiele, auf die wir uns freuen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/eb899844a9b1c36243c97c7cadb9401b\",\"name\":\"Simon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Simon-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Simon-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Simon-96x96.jpg\",\"caption\":\"Simon\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/simon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/","og_locale":"fr_FR","og_type":"article","og_title":"15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News","og_description":"2018 ist vorbei und es war ein grossartiges VR-Jahr. Es waren nicht wenige geniale Vorzeigetitel wie \u00abAstro Bot:&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2019-01-21T18:30:38+00:00","article_modified_time":"2019-01-22T15:46:46+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg","type":"image\/jpeg"}],"author":"Simon","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Simon","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/"},"author":{"name":"Simon","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/eb899844a9b1c36243c97c7cadb9401b"},"headline":"15 VR-Spiele, auf die wir uns freuen","datePublished":"2019-01-21T18:30:38+00:00","dateModified":"2019-01-22T15:46:46+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/"},"wordCount":1647,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg","articleSection":["Games"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/","url":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/","name":"15 VR-Spiele, auf die wir uns freuen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg","datePublished":"2019-01-21T18:30:38+00:00","dateModified":"2019-01-22T15:46:46+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/eb899844a9b1c36243c97c7cadb9401b"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/01\/stormland_teaser3-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2019\/01\/21\/15-vr-spiele-auf-die-wir-uns-freuen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"15 VR-Spiele, auf die wir uns freuen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/eb899844a9b1c36243c97c7cadb9401b","name":"Simon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/Simon-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/Simon-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/Simon-96x96.jpg","caption":"Simon"},"url":"https:\/\/vr-room.ch\/fr\/author\/simon\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/12602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=12602"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/12602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/12625"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=12602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=12602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=12602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}