{"id":11465,"date":"2018-10-06T06:33:14","date_gmt":"2018-10-06T06:33:14","guid":{"rendered":"http:\/\/vr-room.ch\/?p=11465"},"modified":"2018-10-05T14:44:29","modified_gmt":"2018-10-05T14:44:29","slug":"abheben-in-den-entertainment-himmel","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/fr\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","title":{"rendered":"D\u00e9collage vers le ciel du divertissement"},"content":{"rendered":"<div class=\"row\">\n<div id=\"articletop\" class=\"col-md-9 col-md-offset-1 articletop mb50\">\n<h3 id=\"zusammen-mit-staay-interactive-hat-die-agentur-jeff-ein-virtual-reality-erlebnis-namens-ab-in-den-entertainment-himmel-fuer-upc-kreiert-in-einem-fliegenden-tv-sessel-gehen-die-besucher-am\" class=\"articlelead\">En collaboration avec Staay Interactive, l'agence Jeff a cr\u00e9\u00e9 une exp\u00e9rience de r\u00e9alit\u00e9 virtuelle appel\u00e9e \"Ab in den Entertainment-Himmel\" pour UPC. Install\u00e9s dans un fauteuil TV volant, les visiteurs du Festival du film de Zurich partent pour un voyage interactif.<\/h3>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div id=\"socheight\" class=\"row\">\n<div class=\"col-md-6 articletext sublineImage\">\n<p>Cette ann\u00e9e, les visiteurs du Festival du film de Zurich feront une exp\u00e9rience sp\u00e9ciale de r\u00e9alit\u00e9 virtuelle : sous le slogan \"Ab in den Entertainment-Himmel\", ils auront la possibilit\u00e9 de vivre de pr\u00e8s la nouvelle exp\u00e9rience TV d'UPC, comme l'indique Jeff dans un communiqu\u00e9. A peine assis dans le fauteuil du simulateur, le visiteur est catapult\u00e9 de son salon virtuel vers le ciel.<\/p>\n<p>Une fois sur place, il prend le contr\u00f4le \u00e0 l'aide de la nouvelle t\u00e9l\u00e9commande UPC-TV et s'envole vers d'immenses \u00e9crans TV flottants qui diffusent les derniers films d'UPC TV. Si le sujet dirige son regard vers le bas, il est fascin\u00e9 par la vue \u00e0 vol d'oiseau sur la ville de Zurich.<\/p>\n<p>Ce qui est particulier, c'est que le fauteuil TV \"joue\" lui aussi le jeu. Le fauteuil mobile, produit sp\u00e9cialement pour l'Experience, s'\u00e9l\u00e8ve \u00e9galement en hauteur au moment du d\u00e9collage, de sorte que les pieds perdent le contact avec le sol et que le visiteur soit totalement immerg\u00e9 dans le monde virtuel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11466\" src=\"http:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-225x300.jpg\" alt=\"\" width=\"357\" height=\"476\" srcset=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-225x300.jpg 225w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-768x1024.jpg 768w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-833x1110.jpg 833w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-1110x1480.jpg 1110w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-730x973.jpg 730w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-539x719.jpg 539w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-350x467.jpg 350w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-254x339.jpg 254w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie-125x167.jpg 125w, https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/1_Simulator-Sessel-am-UPC-Stand-Kopie.jpg 3024w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/p>\n<h3 id=\"gewinnspiel-als-zusaetzliche-massnahme\">Jeu-concours comme mesure suppl\u00e9mentaire<\/h3>\n<p>Si la visiteuse veut gagner un prix en plus de l'exp\u00e9rience de vol, elle doit ensuite associer tous les films \u00e0 la bonne affiche sur une application pour tablette. La concentration est de mise, car des jumbo-jets bruyants ou des cerfs-volants tentent de d\u00e9tourner l'attention. Des lunettes VR sont \u00e0 gagner chaque jour et le premier prix est un an de \"Happy Home\" gratuit avec la nouvelle UPC TV.<\/p>\n<p>Le concept, le storytelling interactif et la mise en \u0153uvre ont \u00e9t\u00e9 r\u00e9alis\u00e9s par Jeff et le studio de jeu <a href=\"https:\/\/staay.io\/de\/\">Staay <\/a>Interactive (vainqueur du Best of Swiss Apps 2017 dans les cat\u00e9gories Best Game et Best Campaign). Les personnes int\u00e9ress\u00e9es peuvent encore d\u00e9couvrir le ciel du divertissement jusqu'au dimanche 7 octobre au Zurich Film Festival.<\/p>\n<p><iframe loading=\"lazy\" title=\"3 exp\u00e9rience de r\u00e9alit\u00e9 virtuelle immersive\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/pKmCmTrFDXQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Il ne reste plus qu'\u00e0 esp\u00e9rer pour les visiteurs que le vol se d\u00e9roulera un peu plus en douceur que lors de l'exp\u00e9rience de la t\u00eate en bas lors de la promotion avec Samsung et UPC il y a plus d'un an et demi, dont nous avons parl\u00e9. <a href=\"http:\/\/vr-room.ch\/fr\/2017\/01\/17\/kopfueber-bei-samsung-upc\/\">ont rapport\u00e9<\/a>.<\/p>\n<p>Source : Personnel<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"En collaboration avec Staay Interactive, l'agence Jeff a cr\u00e9\u00e9 une exp\u00e9rience de r\u00e9alit\u00e9 virtuelle appel\u00e9e \"Ab in den Entertainment-Himmel\" pour UPC....","protected":false},"author":12,"featured_media":11467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-11465","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Zusammen mit Staay Interactive hat die Agentur Jeff ein Virtual-Reality-Erlebnis namens \u00abAb in den Entertainment-Himmel\u00bb f\u00fcr UPC kreiert.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-06T06:33:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm-1024x542.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Abheben in den Entertainment-Himmel\",\"datePublished\":\"2018-10-06T06:33:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"},\"wordCount\":334,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\",\"name\":\"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"datePublished\":\"2018-10-06T06:33:14+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/2_Blockbuster-aus-UPC-Programm.png\",\"width\":1920,\"height\":1017},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/10\\\/06\\\/abheben-in-den-entertainment-himmel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abheben in den Entertainment-Himmel\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","og_locale":"fr_FR","og_type":"article","og_title":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","og_description":"Zusammen mit Staay Interactive hat die Agentur Jeff ein Virtual-Reality-Erlebnis namens \u00abAb in den Entertainment-Himmel\u00bb f\u00fcr UPC kreiert.&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-10-06T06:33:14+00:00","og_image":[{"width":1024,"height":542,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm-1024x542.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Abheben in den Entertainment-Himmel","datePublished":"2018-10-06T06:33:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"},"wordCount":334,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","url":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/","name":"Abheben in den Entertainment-Himmel - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","datePublished":"2018-10-06T06:33:14+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/10\/2_Blockbuster-aus-UPC-Programm.png","width":1920,"height":1017},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2018\/10\/06\/abheben-in-den-entertainment-himmel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Abheben in den Entertainment-Himmel"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/11465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=11465"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/11465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/11467"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=11465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=11465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=11465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}