{"id":8568,"date":"2017-11-22T09:02:28","date_gmt":"2017-11-22T09:02:28","guid":{"rendered":"http:\/\/vr-room.ch\/?p=8568"},"modified":"2017-11-22T09:02:28","modified_gmt":"2017-11-22T09:02:28","slug":"vr-erfahrung-assassins-creed","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/","title":{"rendered":"Assassin's Creed VR Experience"},"content":{"rendered":"<p>Nachdem zuletzt &#8222;Assassin&#8217;s Creed Origins&#8220; f\u00fcr den PC, die Xbox One und die PlayStation 4 erschienen ist, versucht sich Ubisoft nun an einer VR-Erfahrung zu &#8222;Assassin&#8217;s Creed&#8220;, die in Zusammenarbeit mit Triotech entsteht.<\/p>\n<p><a href=\"http:\/\/trio-tech.com\/\">Triotech<\/a> hat sich auf interaktive Erfahrungen wie beispielsweise 3D-Fahrgesch\u00e4fte spezialisiert. Allerdings ist die VR-Erfahrung zu &#8222;Assassin&#8217;s Creed&#8220; vorerst nicht f\u00fcr den Heimgebrauch gedacht. Ubisoft peilt VR-Arcades an. Die VR-Experience wird zun\u00e4chst nur im Ubisoft Center in Montreal erlebbar sein.<\/p>\n<p>Ob &#8222;Assassin&#8217;s Creed VR&#8220; irgendwann auch auf HTC Vive, Oculus Rift, PlayStation VR und Co. zur Verf\u00fcgung stehen wird, ist zum jetzigen Zeitpunkt leider nicht bekannt. Aber es w\u00e4re fast schon verwunderlich, wenn sich Ubisoft diese Gelegenheit entgehen liesse. <a href=\"https:\/\/www.ubisoft.com\/de-de\/\">Ubisoft<\/a> hat bereits VR-Spiele wie &#8222;Star Trek: Bridge Crew&#8220; und &#8222;Eagle Flight&#8220; ver\u00f6ffentlicht.<\/p>\n<p>Source: VR-World<\/p>","protected":false},"excerpt":{"rendered":"Nachdem zuletzt &#8222;Assassin&#8217;s Creed Origins&#8220; f\u00fcr den PC, die Xbox One und die PlayStation 4 erschienen ist, versucht&hellip;","protected":false},"author":11,"featured_media":8569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-8568","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR-Erfahrung zu Assassin&#039;s Creed - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR-Erfahrung zu Assassin&#039;s Creed - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Nachdem zuletzt &#8222;Assassin&#8217;s Creed Origins&#8220; f\u00fcr den PC, die Xbox One und die PlayStation 4 erschienen ist, versucht&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-22T09:02:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1408\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"VR-Erfahrung zu Assassin&#8217;s Creed\",\"datePublished\":\"2017-11-22T09:02:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/\"},\"wordCount\":141,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/assassins-creed-origins.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/\",\"name\":\"VR-Erfahrung zu Assassin's Creed - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/assassins-creed-origins.jpg\",\"datePublished\":\"2017-11-22T09:02:28+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/assassins-creed-origins.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/assassins-creed-origins.jpg\",\"width\":1408,\"height\":792},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/11\\\/22\\\/vr-erfahrung-assassins-creed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR-Erfahrung zu Assassin&#8217;s Creed\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR-Erfahrung zu Assassin's Creed - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/","og_locale":"en_GB","og_type":"article","og_title":"VR-Erfahrung zu Assassin's Creed - Schweizer Virtual Reality News","og_description":"Nachdem zuletzt &#8222;Assassin&#8217;s Creed Origins&#8220; f\u00fcr den PC, die Xbox One und die PlayStation 4 erschienen ist, versucht&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-11-22T09:02:28+00:00","og_image":[{"width":1408,"height":792,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"VR-Erfahrung zu Assassin&#8217;s Creed","datePublished":"2017-11-22T09:02:28+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/"},"wordCount":141,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg","articleSection":["Entertainment"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/","url":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/","name":"VR-Erfahrung zu Assassin's Creed - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg","datePublished":"2017-11-22T09:02:28+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/11\/assassins-creed-origins.jpg","width":1408,"height":792},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2017\/11\/22\/vr-erfahrung-assassins-creed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR-Erfahrung zu Assassin&#8217;s Creed"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=8568"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/8569"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=8568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=8568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=8568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}