{"id":5651,"date":"2017-06-05T07:43:20","date_gmt":"2017-06-05T07:43:20","guid":{"rendered":"http:\/\/vr-room.ch\/?p=5651"},"modified":"2017-05-29T20:58:36","modified_gmt":"2017-05-29T20:58:36","slug":"ein-teppich-der-lebt-aus-der-schweiz","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/","title":{"rendered":"A carpet that lives from Switzerland"},"content":{"rendered":"<p>At <a href=\"http:\/\/vr-room.ch\/en\/2017\/05\/15\/vr-in-allen-facetten-an-der-2-ausgabe-des-world-vr-forums\/\">VR Forum<\/a> we also took a look at Adventures-Lab. The Swiss company from Sierre has focussed on augmented reality and has come up with something particularly exciting for kids aged between 6 and 12. The Adventures-Mat is a carpet measuring 95 x 95 cm. Although it cannot (yet) fly, it can be brought to life with the accompanying free app. If the children hold the camera of their smartphone or tablet over the carpet, they can use the AR app to expand their knowledge, test their knowledge in a quiz and also play short games. This makes learning fun!<br \/>\nAdventures-Lab aims to bring out at least two more rugs every year - with different themes. The first deals with the human body and the hospital theme.<br \/>\nThe short clip shows - in French - more about the ingenious carpet.<\/p>\n<p>https:\/\/youtu.be\/kMu1SRV3EnU<\/p>\n<p>The app is available in German, French and English.<\/p>\n<p>Source images: Adventure-Lab<\/p>","protected":false},"excerpt":{"rendered":"At the VR Forum, we also took a look at Adventures-Lab. The Swiss company from Sierre has specialised in...","protected":false},"author":12,"featured_media":5652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-5651","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Am VR Forum haben wir auch bei Adventures-Lab herein geschaut. Die Schweizer Firma aus Sierre hat sich auf&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-05T07:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"831\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Ein Teppich, der lebt aus der Schweiz\",\"datePublished\":\"2017-06-05T07:43:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/\"},\"wordCount\":171,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/adventure-mat.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/\",\"name\":\"Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/adventure-mat.jpg\",\"datePublished\":\"2017-06-05T07:43:20+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/adventure-mat.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/adventure-mat.jpg\",\"width\":831,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/06\\\/05\\\/ein-teppich-der-lebt-aus-der-schweiz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Teppich, der lebt aus der Schweiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/","og_locale":"en_GB","og_type":"article","og_title":"Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News","og_description":"Am VR Forum haben wir auch bei Adventures-Lab herein geschaut. Die Schweizer Firma aus Sierre hat sich auf&hellip;","og_url":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-06-05T07:43:20+00:00","og_image":[{"width":831,"height":701,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Ein Teppich, der lebt aus der Schweiz","datePublished":"2017-06-05T07:43:20+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/"},"wordCount":171,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg","articleSection":["Schweiz"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/","url":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/","name":"Ein Teppich, der lebt aus der Schweiz - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg","datePublished":"2017-06-05T07:43:20+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/adventure-mat.jpg","width":831,"height":701},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2017\/06\/05\/ein-teppich-der-lebt-aus-der-schweiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Ein Teppich, der lebt aus der Schweiz"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/5651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=5651"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/5651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/5652"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=5651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=5651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=5651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}