{"id":3515,"date":"2017-01-02T06:59:57","date_gmt":"2017-01-02T06:59:57","guid":{"rendered":"http:\/\/vr-room.ch\/?p=3515"},"modified":"2017-01-12T13:59:55","modified_gmt":"2017-01-12T13:59:55","slug":"rigs-mechanized-combat-league-besucht-die-schweiz","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/","title":{"rendered":"RIGS: Mechanised Combat League visits Switzerland"},"content":{"rendered":"<p>Switzerland has been prominently represented in \"RIGS: Mechanised Combat League\" for a few days now. Guerrilla Games and <a href=\"https:\/\/www.playstation.com\/de-de\/\">Sony Interactive Entertainment<\/a> have made the free winter update available for the title. It includes the first new additional arena of the game, which is set in Zurich. As soon as the PlayStation 4 is connected to the internet, the VR game should contact you about the update.<\/p>\n<p>According to the developers, the new arena draws a lot of inspiration from skate parks. It focuses on a total of four sunken pools that flow into the neighbouring structures and enable high air jumps. The arena in Zurich can be used in both single and multiplayer mode. It also has its own challenges. The trailer provides suitable impressions.<\/p>\n<p>The winter update for \"RIGS: Mechanised Combat League\" also includes the first batch of new APX RIGS, which feature an improved boost system and lead to a higher top speed. The free winter update is described by the developers as just the first step. Further content for \"RIGS: Mechanised Combat League\" is to follow in the coming months. The VR multiplayer game is already available for the release of <a href=\"https:\/\/www.playstation.com\/de-de\/explore\/playstation-vr\/\">PlayStation VR<\/a> came onto the market.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3515-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=t_2w0PCVHv8&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=t_2w0PCVHv8\">https:\/\/www.youtube.com\/watch?v=t_2w0PCVHv8<\/a><\/video><\/div>\n<p>Source: Official PlayStation Blog<\/p>","protected":false},"excerpt":{"rendered":"Switzerland has been prominently represented in \"RIGS: Mechanised Combat League\" for a few days now. Guerrilla Games and Sony Interactive...","protected":false},"author":11,"featured_media":3939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-3515","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Die Schweiz ist seit einigen Tagen prominent in \u201eRIGS: Mechanized Combat League\u201c vertreten. Guerrilla Games und Sony Interactive&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-02T06:59:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-12T13:59:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich-1024x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"RIGS: Mechanized Combat League besucht die Schweiz\",\"datePublished\":\"2017-01-02T06:59:57+00:00\",\"dateModified\":\"2017-01-12T13:59:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/\"},\"wordCount\":222,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Zurich.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/\",\"name\":\"RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Zurich.jpg\",\"datePublished\":\"2017-01-02T06:59:57+00:00\",\"dateModified\":\"2017-01-12T13:59:55+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Zurich.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Zurich.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/01\\\/02\\\/rigs-mechanized-combat-league-besucht-die-schweiz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIGS: Mechanized Combat League besucht die Schweiz\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/","og_locale":"en_GB","og_type":"article","og_title":"RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News","og_description":"Die Schweiz ist seit einigen Tagen prominent in \u201eRIGS: Mechanized Combat League\u201c vertreten. Guerrilla Games und Sony Interactive&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-01-02T06:59:57+00:00","article_modified_time":"2017-01-12T13:59:55+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich-1024x576.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"RIGS: Mechanized Combat League besucht die Schweiz","datePublished":"2017-01-02T06:59:57+00:00","dateModified":"2017-01-12T13:59:55+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/"},"wordCount":222,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich.jpg","articleSection":["Games"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/","url":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/","name":"RIGS: Mechanized Combat League besucht die Schweiz - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich.jpg","datePublished":"2017-01-02T06:59:57+00:00","dateModified":"2017-01-12T13:59:55+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/Zurich.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/fr\/2017\/01\/02\/rigs-mechanized-combat-league-besucht-die-schweiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"RIGS: Mechanized Combat League besucht die Schweiz"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/3515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=3515"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/3515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/3939"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=3515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=3515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=3515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}