{"id":19948,"date":"2021-09-13T10:41:34","date_gmt":"2021-09-13T10:41:34","guid":{"rendered":"https:\/\/vr-room.ch\/?p=19948"},"modified":"2021-09-06T10:42:26","modified_gmt":"2021-09-06T10:42:26","slug":"empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/","title":{"rendered":"Empa and Eawag let you experience the future campus with AR"},"content":{"rendered":"<p><strong>Less than four months after the groundbreaking ceremony, the foundation stone for the \"co-operate\" research campus of Empa and Eawag was laid on 3 September 2021. At the festive event in D\u00fcbendorf, the hosts and guests filled a time capsule with items typical of the time and thus, together with an augmented reality (AR) app, gave the starting signal for \"co-operate\". <\/strong><!--more--><\/p>\n<p>What should one put in a \"time capsule\" that is concreted into the foundation stone of a research building under construction and is intended to provide future generations with information about the era at the time of construction? Empa decided on a few products from its own research: a small steel rod made of a shape memory alloy developed at Empa and a cube created by 3D printing that demonstrates the possibilities of digital production of unique items.<\/p>\n<p>Eawag Director Janet Hering put something about the liquid fertiliser \"Aurin\" developed at Eawag in the capsule. This contains valuable nutrients derived from urine. The new buildings will be equipped with toilets that can separate and collect urine. Jens Vollmar, Head Buildings at Implenia, contributed a stick on which the construction plans for \"co-operate\" are stored.<\/p>\n<h3 id=\"mit-bim-zum-digitalen-zwilling\">With BIM to the digital twin<\/h3>\n<p>Gem\u00e4ss Bona soll der neue Forschungscampus \u00abco-operate\u00bb zu einem Ort vielf\u00e4ltiger Zusammenarbeit mit Empa-Partnern werden und die Institutionen des ETH-Bereichs noch st\u00e4rker miteinander vernetzen. Der Leiter des Empa-Immobilienmanagements, Hannes Pichler: \u00abBei co-operate wird die Methode des &#8222;Building Information Modeling&#8220; angewendet. Das heisst, bevor die Umsetzung auf der Baustelle beginnt, wird ein digitaler Zwilling erzeugt, durch den Planungs- und Realisierungsfehler reduziert werden. Die erhaltenen Daten werden zudem sp\u00e4ter im Betrieb genutzt\u00bb.<\/p>\n<h3 id=\"augmented-reality-macht-bauten-sicht-und-erlebbar\">Augmented reality makes buildings visible and tangible<\/h3>\n<p>Before the partners then climbed into the excavation pit together to set the time capsule in concrete and lay the foundation stone, there was a special experience for all those present: instead of studying building plans and descriptions and then imagining the future campus in their own imagination, they were able to experience the future on their smartphones and tablets today, so to speak. This was made possible by an augmented reality app \"co-operate AR\" programmed especially for the event. It was an impressive experience that many onlookers will probably also enjoy during the construction period.<\/p>\n<p>Source: MM<\/p>","protected":false},"excerpt":{"rendered":"Barely four months after the groundbreaking ceremony, the foundation stone was laid on 3 September 2021 for the \"co-operate\" research campus of...","protected":false},"author":12,"featured_media":19949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-19948","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Knapp vier Monate nach dem ersten Spatenstich wurde am 3. September 2021 der Grundstein zum Forschungscampus \u00abco-operate\u00bb der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-13T10:41:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben\",\"datePublished\":\"2021-09-13T10:41:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/\"},\"wordCount\":384,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Grundsteinlegung-Stopper-2.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/\",\"name\":\"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Grundsteinlegung-Stopper-2.jpg\",\"datePublished\":\"2021-09-13T10:41:34+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Grundsteinlegung-Stopper-2.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Grundsteinlegung-Stopper-2.jpg\",\"width\":870,\"height\":489,\"caption\":\"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2021\\\/09\\\/13\\\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/","og_locale":"en_GB","og_type":"article","og_title":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News","og_description":"Knapp vier Monate nach dem ersten Spatenstich wurde am 3. September 2021 der Grundstein zum Forschungscampus \u00abco-operate\u00bb der&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2021-09-13T10:41:34+00:00","og_image":[{"width":870,"height":489,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben","datePublished":"2021-09-13T10:41:34+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/"},"wordCount":384,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg","articleSection":["Schweiz"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/","url":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/","name":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg","datePublished":"2021-09-13T10:41:34+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/09\/Grundsteinlegung-Stopper-2.jpg","width":870,"height":489,"caption":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2021\/09\/13\/empa-und-eawag-lassen-mit-ar-kuenfitgen-campus-erleben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Empa und Eawag lassen mit AR k\u00fcnfitgen Campus erleben"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/19948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=19948"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/19948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/19949"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=19948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=19948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=19948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}