{"id":19884,"date":"2021-08-22T09:18:48","date_gmt":"2021-08-22T09:18:48","guid":{"rendered":"https:\/\/vr-room.ch\/?p=19884"},"modified":"2021-08-22T09:20:22","modified_gmt":"2021-08-22T09:20:22","slug":"zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/","title":{"rendered":"Second part of Star Wars: Tales from the Galaxy's Edge in autumn"},"content":{"rendered":"<p>The second part of \"Star Wars: Tales from the Galaxy's Edge\", subtitled \"Last Call\", will be released for the Oculus Quest platform in autumn 2021, developer ILMxLAB and Disney have confirmed.<\/p>\n<p>In Last Call, Batuu's curmudgeonly antiques dealer Dok-Ondar once again asks VR players to take on the role of a droid repair technician turned adventurer to secure some valuable relics. In the process, VR users will encounter at least two new characters: Lens Kamo and Baron Attsmun. These can also be seen in the new trailer and key art.<\/p>\n<p>Director Jose Perez III has elaborated on what to expect from the new game: \"More swashbuckling adventures! A large part of Last Call borrows heavily from Indiana Jones and Star Wars. So we had a lot of fun developing interesting environmental puzzles for the player to solve while investigating deeper into the ruins of an ancient Jedi temple.\"<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-19884-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=Dk5nqS2jc5Q&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=Dk5nqS2jc5Q\">https:\/\/www.youtube.com\/watch?v=Dk5nqS2jc5Q<\/a><\/video><\/div>\n<p>Source: <a href=\"https:\/\/www.starwars.com\/news\/star-wars-tales-from-the-galaxys-edge-last-call\">StarWars.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"The second part of \"Star Wars: Tales from the Galaxy's Edge\", subtitled \"Last Call\", will...","protected":false},"author":11,"featured_media":19885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-19884","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zweiter Teil von Star Wars: Tales from the Galaxy&#039;s Edge im Herbst - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/en\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zweiter Teil von Star Wars: Tales from the Galaxy&#039;s Edge im Herbst - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Der zweite Teil von \u00abStar Wars: Tales from the Galaxy\u2019s Edge\u00bb, der den Untertitel \u00abLast Call\u00bb tr\u00e4gt, wird&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/en\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-22T09:18:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-22T09:20:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Zweiter Teil von Star Wars: Tales from the Galaxy&#8217;s Edge im Herbst\",\"datePublished\":\"2021-08-22T09:18:48+00:00\",\"dateModified\":\"2021-08-22T09:20:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/\"},\"wordCount\":189,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/star-wars-tales-from-the-galaxys-edge-last-call.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/\",\"name\":\"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/star-wars-tales-from-the-galaxys-edge-last-call.jpg\",\"datePublished\":\"2021-08-22T09:18:48+00:00\",\"dateModified\":\"2021-08-22T09:20:22+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/star-wars-tales-from-the-galaxys-edge-last-call.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/star-wars-tales-from-the-galaxys-edge-last-call.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2021\\\/08\\\/22\\\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zweiter Teil von Star Wars: Tales from the Galaxy&#8217;s Edge im Herbst\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/en\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/","og_locale":"en_GB","og_type":"article","og_title":"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst - Schweizer Virtual Reality News","og_description":"Der zweite Teil von \u00abStar Wars: Tales from the Galaxy\u2019s Edge\u00bb, der den Untertitel \u00abLast Call\u00bb tr\u00e4gt, wird&hellip;","og_url":"http:\/\/vr-room.ch\/en\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2021-08-22T09:18:48+00:00","article_modified_time":"2021-08-22T09:20:22+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Zweiter Teil von Star Wars: Tales from the Galaxy&#8217;s Edge im Herbst","datePublished":"2021-08-22T09:18:48+00:00","dateModified":"2021-08-22T09:20:22+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/"},"wordCount":189,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg","articleSection":["Games"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/","url":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/","name":"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg","datePublished":"2021-08-22T09:18:48+00:00","dateModified":"2021-08-22T09:20:22+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/08\/star-wars-tales-from-the-galaxys-edge-last-call.jpg","width":1280,"height":720,"caption":"Zweiter Teil von Star Wars: Tales from the Galaxy's Edge im Herbst"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/fr\/2021\/08\/22\/zweiter-teil-von-star-wars-tales-from-the-galaxys-edge-im-herbst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Zweiter Teil von Star Wars: Tales from the Galaxy&#8217;s Edge im Herbst"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/19884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=19884"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/19884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/19885"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=19884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=19884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=19884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}