{"id":18612,"date":"2020-12-26T15:30:29","date_gmt":"2020-12-26T15:30:29","guid":{"rendered":"https:\/\/vr-room.ch\/?p=18612"},"modified":"2020-12-23T15:34:20","modified_gmt":"2020-12-23T15:34:20","slug":"lindt-eine-reise-ins-schokoladen-universum","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/","title":{"rendered":"Lindt: A journey into the chocolate universe"},"content":{"rendered":"<h3 id=\"in-kilchberg-in-der-schweiz-wurde-das-lindt-home-of-chocolate-eroeffnet-am-historischen-hauptsitz-von-lindt-spruengli-aus-dem-jahr-1899-strahlt-der-neubau-aus-weissen-und-roten-backsteinen-opti\">The Lindt Home of Chocolate has opened in Kilchberg, Switzerland. The new building made of white and red bricks stands out visually at the historic headquarters of Lindt &amp; Spr\u00fcngli, which dates back to 1899. Visitors can embark on a journey of discovery into the Swiss chocolate cosmos. AR brings the machines to life.<!--more--><\/h3>\n<p style=\"text-align: left\">The sweet multifunctional building complex with 20,000 square metres of floor space serves as a training and further education centre for specialists on the one hand, and as a showroom, experience destination and interactive information platform for the public on the other. We are talking about the new Lindt Home of Chocolate in Kilchberg.<\/p>\n<p>On the first floor, visitors can embark on a journey of discovery into a world of chocolate experiences. On an exhibition area of 1,500 square metres, you can find out everything about the cocoa bean. Each room is individually designed. The first room visualises a visit to a cocoa plantation in Ghana.<\/p>\n<h3 id=\"interaktiv\">Interactive<\/h3>\n<p>In the \"Chocolate History\" room, everything revolves around the 5,000-year history of chocolate. A drawn and digitally animated 360-degree panorama tells the story of the origins of chocolate with the Mayans and how it came to Europe. A round media table in the centre of the room provides information about the preparation and consumption of the sweet delicacy throughout history. At integrated media tables, visitors can virtually grind cocoa beans and stir the drink until it is frothy. In addition to other attractions, visitors to the Innovation Labs can take a look inside a real test facility. Augmented reality makes it possible to take a look inside the machines.<\/p>\n<p>Let's hope that we'll soon be able to visit them for an AR chocolate test.<\/p>\n<p>Source: stores-shops<\/p>","protected":false},"excerpt":{"rendered":"The Lindt Home of Chocolate opened in Kilchberg, Switzerland. At the historic headquarters of Lindt &amp;...","protected":false},"author":12,"featured_media":18613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":{"0":"post-18612","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-schweiz","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"In Kilchberg in der Schweiz wurde das Lindt Home of Chocolate er\u00f6ffnet. Am historischen Hauptsitz von Lindt &amp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-26T15:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"964\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Lindt: Eine Reise ins Schokoladen-Universum\",\"datePublished\":\"2020-12-26T15:30:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/\"},\"wordCount\":260,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Lindt_Chocolate_1.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/\",\"name\":\"Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Lindt_Chocolate_1.jpg\",\"datePublished\":\"2020-12-26T15:30:29+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Lindt_Chocolate_1.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Lindt_Chocolate_1.jpg\",\"width\":1280,\"height\":964,\"caption\":\"Lindt AR Erlebnis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/12\\\/26\\\/lindt-eine-reise-ins-schokoladen-universum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lindt: Eine Reise ins Schokoladen-Universum\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/","og_locale":"en_GB","og_type":"article","og_title":"Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News","og_description":"In Kilchberg in der Schweiz wurde das Lindt Home of Chocolate er\u00f6ffnet. Am historischen Hauptsitz von Lindt &amp;&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-12-26T15:30:29+00:00","og_image":[{"width":1280,"height":964,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Lindt: Eine Reise ins Schokoladen-Universum","datePublished":"2020-12-26T15:30:29+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/"},"wordCount":260,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg","articleSection":["Schweiz"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/","url":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/","name":"Lindt: Eine Reise ins Schokoladen-Universum - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg","datePublished":"2020-12-26T15:30:29+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/12\/Lindt_Chocolate_1.jpg","width":1280,"height":964,"caption":"Lindt AR Erlebnis"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2020\/12\/26\/lindt-eine-reise-ins-schokoladen-universum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Lindt: Eine Reise ins Schokoladen-Universum"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"https:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/18612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=18612"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/18612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/18613"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=18612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=18612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=18612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}