{"id":12787,"date":"2019-02-14T11:50:52","date_gmt":"2019-02-14T11:50:52","guid":{"rendered":"http:\/\/vr-room.ch\/?p=12787"},"modified":"2019-02-14T11:52:47","modified_gmt":"2019-02-14T11:52:47","slug":"termin-space-junkies-trailer","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/","title":{"rendered":"Date for Space Junkies &amp; Trailer"},"content":{"rendered":"<p>Ubisoft hat jetzt bekannt gegeben, dass der VR-Arcade-Shooter &#8222;Space Junkies&#8220; am 26. M\u00e4rz 2019 f\u00fcr PlayStation VR, Windows Mixed Reality, Oculus Rift + Touch und HTC Vive erscheinen wird.<\/p>\n<p>If that's not enough, you can also watch a new trailer. According to Ubisoft, there will also be several test phases before the official launch, including an open beta. However, no dates have yet been announced. On the <a href=\"https:\/\/betasignup.ubisoft.com\/\">official side<\/a> you can register for it.<\/p>\n<p>Zur Ver\u00f6ffentlichung wird &#8222;Space Junkies&#8220; 1v1-, 2v2- und Free-for-all-Modi sowie verschiedene Waffen- und Anpassungsoptionen in sechs Innenr\u00e4umen und Aussenarealen anbieten. Jede Arena verf\u00fcgt \u00fcber einzigartige taktische Zonen, dynamische Beleuchtung und zerst\u00f6rbare Umgebungen.<\/p>\n<p>Ubisoft verspricht: &#8222;Jeder Kampf wird sich einzigartig anf\u00fchlen, und die Spieler brauchen ihren Verstand und ihre Kampfkunst, um zu verhindern, dass der Tod sie aus allen Richtungen ereilt. Zus\u00e4tzlich erh\u00e4lt das Spiel nach der Ver\u00f6ffentlichung neue Inhaltsupdates einschliesslich neuer Modi, Karten, Waffen und Anpassungsgegenst\u00e4nde.&#8220;<\/p>\n<p>&#8222;Wir sind mehr als begeistert vom Space Junkies-Start und k\u00f6nnen es kaum erwarten, dass die Spieler in diesen raketenstarken, Laser-Pistolenheld-Bonanza-Weltraum springen,&#8220; so Adrian Lacey, Producer bei Ubisoft Montpellier. &#8222;Die M\u00f6glichkeit, auf PlayStation VR zu ver\u00f6ffentlichen, ist eine grossartige Nachricht f\u00fcr unsere Spieler, und wir pr\u00fcfen die Unterst\u00fctzung zus\u00e4tzlicher Headsets, um das Erlebnis der Space Junkies in Zukunft noch mehr Menschen zug\u00e4nglich zu machen.&#8220;<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12787-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=VBRC5kQvsxo&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=VBRC5kQvsxo\">https:\/\/www.youtube.com\/watch?v=VBRC5kQvsxo<\/a><\/video><\/div>\n<p>Source: Press release<\/p>","protected":false},"excerpt":{"rendered":"Ubisoft hat jetzt bekannt gegeben, dass der VR-Arcade-Shooter &#8222;Space Junkies&#8220; am 26. M\u00e4rz 2019 f\u00fcr PlayStation VR, Windows&hellip;","protected":false},"author":11,"featured_media":12788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-12787","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Ubisoft hat jetzt bekannt gegeben, dass der VR-Arcade-Shooter &#8222;Space Junkies&#8220; am 26. M\u00e4rz 2019 f\u00fcr PlayStation VR, Windows&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-14T11:50:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-14T11:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Termin f\u00fcr Space Junkies &amp; Trailer\",\"datePublished\":\"2019-02-14T11:50:52+00:00\",\"dateModified\":\"2019-02-14T11:52:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/\"},\"wordCount\":250,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/SpaceJunkies.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/\",\"name\":\"Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/SpaceJunkies.jpg\",\"datePublished\":\"2019-02-14T11:50:52+00:00\",\"dateModified\":\"2019-02-14T11:52:47+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/SpaceJunkies.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/SpaceJunkies.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2019\\\/02\\\/14\\\/termin-space-junkies-trailer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Termin f\u00fcr Space Junkies &amp; Trailer\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/","og_locale":"en_GB","og_type":"article","og_title":"Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News","og_description":"Ubisoft hat jetzt bekannt gegeben, dass der VR-Arcade-Shooter &#8222;Space Junkies&#8220; am 26. M\u00e4rz 2019 f\u00fcr PlayStation VR, Windows&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2019-02-14T11:50:52+00:00","article_modified_time":"2019-02-14T11:52:47+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Termin f\u00fcr Space Junkies &amp; Trailer","datePublished":"2019-02-14T11:50:52+00:00","dateModified":"2019-02-14T11:52:47+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/"},"wordCount":250,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg","articleSection":["Games"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/","url":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/","name":"Termin f\u00fcr Space Junkies &amp; Trailer - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg","datePublished":"2019-02-14T11:50:52+00:00","dateModified":"2019-02-14T11:52:47+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/02\/SpaceJunkies.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2019\/02\/14\/termin-space-junkies-trailer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Termin f\u00fcr Space Junkies &amp; Trailer"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/12787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=12787"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/12787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/12788"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=12787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=12787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=12787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}