{"id":11192,"date":"2018-08-24T07:45:58","date_gmt":"2018-08-24T07:45:58","guid":{"rendered":"http:\/\/vr-room.ch\/?p=11192"},"modified":"2018-08-24T07:45:58","modified_gmt":"2018-08-24T07:45:58","slug":"7-miracles-erste-vr-erfahrung-spielfilmlaenge","status":"publish","type":"post","link":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/","title":{"rendered":"7 Miracles: First feature-length VR experience"},"content":{"rendered":"<p>The <a href=\"http:\/\/vivestudios.com\/\">Vive Studios<\/a> haben jetzt die erste VR-Filmerfahrung in Spielfilml\u00e4nge angek\u00fcndigt. &#8222;7 Miracles&#8220;, so der Name des Films, entstand in Kooperation mit dem Virtual- und Augmented-Reality-Studio <a href=\"http:\/\/panogramma.com\/\">Panogramma<\/a>.<\/p>\n<p>&#8222;7 Miracles&#8220; feiert seine Premiere am 3. Oktober 2018 beim 26. Raindance Film Festival. Er ist dort f\u00fcr den &#8222;Grand Jury Price: Best Immersive Story&#8220; nominiert. Das umfangreiche Werk wird im Laufe des Jahres f\u00fcr VR-Headsets verf\u00fcgbar sein. &#8222;7 Miracles&#8220; ist ein mehrteiliger Episodenfilm, der die &#8222;Sieben Wunder Christi&#8220; nach der Vorlage des Johannesevangeliums in VR erlebbar macht. Dazu die Macher: &#8222;Das 360-Grad-Erlebnis verbindet das Publikum wie nie zuvor mit der Virtuellen Realit\u00e4t und macht die Geschichte des Films hautnah erlebbar.&#8220; Der Film basiert auf der neuesten Virtual-Reality-Technologie und wurde mit der Hilfe von Photogrammetrie und volumetrischer Videoerfassung erstellt.<\/p>\n<p>&#8222;Wir sind begeistert, mit 7 Miracles die Grenzen des Geschichtenerz\u00e4hlens in VR auszuloten,&#8220; sagt Joel Breton, GM der Vive Studios. &#8222;Unser grossartiges Filmproduktionsteam hat unerm\u00fcdlich daran gearbeitet, die Technologie f\u00fcr die filmische Virtuelle Realit\u00e4t zu entwickeln und die Zuschauer zur\u00fcck in die Vergangenheit zu bringen, um die Wunder Jesu selbst zu erleben.&#8220; Als Drehorte wurden Rom und Matera ausgew\u00e4hlt.<\/p>\n<p>&#8222;Die Arbeit an diesem Projekt war eine wunderbare Erfahrung f\u00fcr uns. Die neue filmische VR-Technologie hat meinem Team und mir die M\u00f6glichkeit gegeben, pers\u00f6nlichere und intimere Geschichten zu kreieren und zu erz\u00e4hlen. Ich bin sehr stolz auf unsere Arbeit,&#8220; so Enzo Sisti, Executive Producer. &#8222;7 Miracles&#8220; wurde von Rodrigo Cerqueira, Founding-CEO von Panogramma (&#8222;Jesus VR: The Story of Christ&#8220;), und Regisseur Marco Spagnoli (&#8222;Hollywood Invasion&#8220;, &#8222;Hollywood on Tiber&#8220;) inszeniert. Die Produktion \u00fcbernahmen Enzo Sisti (&#8222;Aquaman&#8220;, &#8222;Wonder Woman&#8220;, &#8222;Avengers: Age of Ultron&#8220;), Vive Studios&#8216; Joel Breton und Rodrigo Cerqueira.<\/p>\n<p>Source: Press release<\/p>","protected":false},"excerpt":{"rendered":"Die Vive Studios haben jetzt die erste VR-Filmerfahrung in Spielfilml\u00e4nge angek\u00fcndigt. &#8222;7 Miracles&#8220;, so der Name des Films,&hellip;","protected":false},"author":11,"featured_media":11193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-11192","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-entertainment","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Die Vive Studios haben jetzt die erste VR-Filmerfahrung in Spielfilml\u00e4nge angek\u00fcndigt. &#8222;7 Miracles&#8220;, so der Name des Films,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-24T07:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1850\" \/>\n\t<meta property=\"og:image:height\" content=\"1139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge\",\"datePublished\":\"2018-08-24T07:45:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/\"},\"wordCount\":289,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/7Miracles.jpg\",\"articleSection\":[\"Entertainment\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/\",\"name\":\"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/7Miracles.jpg\",\"datePublished\":\"2018-08-24T07:45:58+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/7Miracles.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/7Miracles.jpg\",\"width\":1850,\"height\":1139},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2018\\\/08\\\/24\\\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/","og_locale":"en_GB","og_type":"article","og_title":"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News","og_description":"Die Vive Studios haben jetzt die erste VR-Filmerfahrung in Spielfilml\u00e4nge angek\u00fcndigt. &#8222;7 Miracles&#8220;, so der Name des Films,&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-08-24T07:45:58+00:00","og_image":[{"width":1850,"height":1139,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge","datePublished":"2018-08-24T07:45:58+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/"},"wordCount":289,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg","articleSection":["Entertainment"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/","url":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/","name":"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg","datePublished":"2018-08-24T07:45:58+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/08\/7Miracles.jpg","width":1850,"height":1139},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2018\/08\/24\/7-miracles-erste-vr-erfahrung-spielfilmlaenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"7 Miracles: Erste VR-Erfahrung in Spielfilml\u00e4nge"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"https:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/11192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=11192"}],"version-history":[{"count":0,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/11192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/11193"}],"wp:attachment":[{"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=11192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=11192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=11192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}