{"id":7417,"date":"2017-09-25T06:39:56","date_gmt":"2017-09-25T06:39:56","guid":{"rendered":"http:\/\/vr-room.ch\/?p=7417"},"modified":"2017-09-13T15:42:32","modified_gmt":"2017-09-13T15:42:32","slug":"augmented-reality-in-der-zahnarztpraxis","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/it\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/","title":{"rendered":"La realt\u00e0 aumentata nello studio dentistico"},"content":{"rendered":"<h3 id=\"das-schweizer-startup-kapanu-zeigt-zahnarztpatienten-wie-ihr-laecheln-nach-der-geplanten-korrektur-aussehen-wird\">La start-up svizzera Kapanu mostra ai pazienti dentisti come apparir\u00e0 il loro sorriso dopo la correzione programmata.<\/h3>\n<p><!--more--><\/p>\n<p>La maggior parte delle persone concorda su una cosa: denti belli rendono pi\u00f9 attraenti. Per questo motivo si comincia gi\u00e0 con gli apparecchi per i bambini e la maggior parte delle persone vuole eliminare le discromie con lo sbiancamento. Chi soffre di denti scheggiati o usurati spesso opta per la ricostruzione estetica dei denti.<\/p>\n<p>Affinch\u00e9 i pazienti possano immaginare l'aspetto del loro nuovo sorriso, di solito viene prima realizzato un calco in gesso della dentatura. Un odontotecnico usa la cera per fissare le parti da aggiungere e poi produce un modello in plastica che il paziente pu\u00f2 provare a montare: una procedura lunga e dispendiosa. Ora l'AR dovrebbe contribuire a velocizzare il processo e a mostrare alle persone l'aspetto che avranno in seguito le loro protesi.<\/p>\n<h3 id=\"enginge-errechnet-das-aussehen-mit-gebiss\">Enginge calcola l'aspetto con la dentizione<\/h3>\n<p><a href=\"https:\/\/www.ethz.ch\/en\/news-and-events\/eth-news\/news\/2017\/09\/sweeter-smile-through-augmented-reality.html\">Kapanu<\/a>un'emanazione dell'Universit\u00e0 Tecnica di Zurigo, ha sviluppato un motore di realt\u00e0 aumentata in collaborazione con Disney Research. Questo motore potrebbe presto essere utilizzato negli studi dentistici di tutto il mondo. Il motore scansiona la dentatura del paziente con una tecnica gi\u00e0 utilizzata in molti studi. La vera innovazione si presenta solo dopo la scansione: in questo caso il motore AR calcola come apparir\u00e0 la dentatura del paziente dopo le correzioni previste o con le protesi.<\/p>\n<p>Un tablet PC funge da specchio a realt\u00e0 aumentata nello studio. I pazienti possono utilizzarlo per progettare le correzioni previste in base ai loro desideri e, ad esempio, determinare la distanza tra i denti o la forma dei denti. Se il paziente d\u00e0 l'ok, inizia la produzione della protesi desiderata.<\/p>\n<p>Kapanu ha presentato il concetto per la prima volta l'anno scorso all'International Dental Show di Colonia. Lo specchio AR \u00e8 stato apparentemente ben accolto dal settore. A giugno, la start-up \u00e8 stata premiata dall'associazione <a href=\"https:\/\/blog.ivoclarvivadent.com\/dentist\/en\/how-augmented-reality-facilitates-dental-treatments\">Ivoclar Vivadent AG<\/a> rilevato. L'azienda produce e distribuisce prodotti per dentisti e odontotecnici.<\/p>\n<p><iframe loading=\"lazy\" title=\"Kapanu | Realt\u00e0 aumentata per il futuro dell&#039;odontoiatria\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/cIEXAlN_QF4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Fonte: PCwelt \/ Youtube \/ Kapanu<\/p>","protected":false},"excerpt":{"rendered":"La start-up svizzera Kapanu mostra ai pazienti dentisti come apparir\u00e0 il loro sorriso dopo la correzione programmata.","protected":false},"author":12,"featured_media":7418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-7417","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Das Schweizer Startup Kapanu zeigt Zahnarztpatienten, wie ihr L\u00e4cheln nach der geplanten Korrektur aussehen wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-25T06:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Augmented Reality in der Zahnarztpraxis\",\"datePublished\":\"2017-09-25T06:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/\"},\"wordCount\":343,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Z\u00e4hne-VR.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/\",\"name\":\"Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Z\u00e4hne-VR.jpg\",\"datePublished\":\"2017-09-25T06:39:56+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Z\u00e4hne-VR.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Z\u00e4hne-VR.jpg\",\"width\":950,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/09\\\/25\\\/augmented-reality-in-der-zahnarztpraxis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Augmented Reality in der Zahnarztpraxis\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/","og_locale":"it_IT","og_type":"article","og_title":"Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News","og_description":"Das Schweizer Startup Kapanu zeigt Zahnarztpatienten, wie ihr L\u00e4cheln nach der geplanten Korrektur aussehen wird.","og_url":"https:\/\/vr-room.ch\/it\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-09-25T06:39:56+00:00","og_image":[{"width":950,"height":475,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Augmented Reality in der Zahnarztpraxis","datePublished":"2017-09-25T06:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/"},"wordCount":343,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg","articleSection":["Schweiz"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/","url":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/","name":"Augmented Reality in der Zahnarztpraxis - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg","datePublished":"2017-09-25T06:39:56+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/Z\u00e4hne-VR.jpg","width":950,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2017\/09\/25\/augmented-reality-in-der-zahnarztpraxis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Augmented Reality in der Zahnarztpraxis"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/7417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=7417"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/7417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/7418"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=7417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=7417"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=7417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}