{"id":20849,"date":"2022-10-02T08:24:59","date_gmt":"2022-10-02T08:24:59","guid":{"rendered":"https:\/\/vr-room.ch\/?p=20849"},"modified":"2022-09-30T09:01:57","modified_gmt":"2022-09-30T09:01:57","slug":"pro-senectute-will-im-metaverse-digitale-filialen-aufbauen","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/it\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/","title":{"rendered":"Pro Senectute vuole creare filiali digitali nel Metaverso"},"content":{"rendered":"<h3 id=\"viele-aeltere-menschen-tun-sich-schwer-mit-der-technik-trotzdem-hat-pro-senectute-beider-basel-im-metaverse-drei-parzellen-gekauft-die-groesste-fach-und-dienstleistungsorganisation-fuer-das-alter-i\">Molte persone anziane trovano difficile la tecnologia. Tuttavia, Pro Senectute beider Basel ha acquistato tre terreni nel Metaverse. La pi\u00f9 grande organizzazione di specialisti e servizi per gli anziani della Svizzera vuole dare il via libera all'Internet accessibile. Perch\u00e9 un'organizzazione per anziani sta acquistando un terreno virtuale?<\/h3>\n<div class=\"section-1\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _2yEhKy3b _33izxNL0 VRK7E5k9\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"section-2\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<p>Una filiale regionale della Svizzera nord-occidentale dell'importante organizzazione non profit svizzera (NPO) Pro Senectute si sta avventurando nel Metaverse. \"In particolare, ci siamo assicurati lotti di terreno su due piattaforme con l'obiettivo di creare una filiale di Pro Senectute nel Metaverse. Un lotto \u00e8 stato assicurato su Sandbox e due su Decentraland\", spiega Michael Harr, amministratore delegato di Pro Senectute beider Basel.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<h3 id=\"architekt-fuer-die-virtuelle-filiale-gesucht\">Cercasi architetto per la filiale virtuale<\/h3>\n<p>Secondo Harr, \"attualmente stiamo cercando architetti per progettare la filiale di Pro Senectute nel Metaverso\". In seguito, probabilmente verranno acquistati anche hardware come cuffie per la realt\u00e0 virtuale \"per consentire ai cittadini anziani di entrare nel Metaverso in corsi e per consigliarli durante il processo\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<h3 id=\"experte-keck-und-mutig\">Esperto: \"Audace e coraggioso<\/h3>\n<p>\u00c8 sorprendente che un'organizzazione di anziani si avventuri nel metaverso. \u00c8 forse la prima organizzazione non profit svizzera nella terra digitale di dopodomani? \"Non ho una panoramica completa, ma non conosco ancora molte ONG e ONP svizzere con una filiale nel metaverso. L'argomento \u00e8 ancora molto di nicchia\", afferma Philipp Semmler, Chief Innovation Officer dell'agenzia pubblicitaria Inhalt und Form di Zurigo, che sta creando l'unit\u00e0 metaverse Iundf Neo per l'azienda.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<p>Semmler ritiene che il passaggio di Pro Senectute a Internet immersivo sia \"tanto audace quanto coraggioso. Se non si fa nulla, non si impara nulla\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<h3 id=\"alte-schulen-und-juengere-frueh-abholen\">Educare i vecchi. E raccogliere precocemente i pi\u00f9 giovani<\/h3>\n<p>Per Michael Harr, entrare nel metaverso significa imparare: \"In primo luogo, le persone anziane, comprese quelle con disabilit\u00e0, possono potenzialmente sperimentare nel metaverso cose che non sarebbero in grado di fare nella vita reale. Inoltre, possiamo far familiarizzare gli anziani con la tecnologia\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<p>Il secondo tema di Harr: \"Con la presenza nel metaverso vogliamo attirare persone che nel prossimo futuro entreranno anche nel segmento di et\u00e0 di Pro Senectute\". Ci\u00f2 che \u00e8 importante per il manager di Pro Senectute: \"La presenza nel metaverso deve integrare le nostre attivit\u00e0 nel mondo reale in modo lungimirante, ma non deve assolutamente sostituirle\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<h3 id=\"landkosten-per-nft-verkauf-refinanzieren\">Rifinanziamento dei costi dei terreni attraverso la vendita di NFT<\/h3>\n<p>Secondo Harr, sono stati spesi 15.000 franchi per l'acquisto dei lotti su Sandbox e Decentraland. Questi costi saranno rifiniti attraverso la vendita di asset virtuali, i token non fungibili (NFT). Questi NFT sono creati sulla base delle fotografie di paesaggi dell'influencer svizzero Marcus H\u00e4ndel, alias Quintner, che gestisce l'account Instagram @visitswitzerland con oltre 800.000 follower.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<p>4444 di questi NFT saranno venduti a partire da ottobre al prezzo di 66 franchi svizzeri l'uno, il che, nella migliore delle ipotesi, porter\u00e0 ben 300.000 franchi svizzeri nelle casse del Metaverse di Pro Senectute beider Basel.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<h3 id=\"hohe-huerden-fuer-die-zwei-gewaehlten-plattformen\">Ostacoli elevati per le due piattaforme selezionate<\/h3>\n<p>Harr spiega perch\u00e9 non \u00e8 l'intera Pro Senectute svizzera a indossare l'elmetto dei dati per il viaggio nel metaverso, ma solo una propaggine regionale: \"Le organizzazioni cantonali di Pro Senectute sono tutte fondazioni indipendenti. Pro Senectute beider Basel vuole agire con lungimiranza e tenersi al passo con gli sviluppi tecnologici. Siamo sempre stati all'avanguardia nel mondo delle ONP\".<\/p>\n<p>Se l'esperto di Metaverse Semmler ha qualcosa da criticare sulla mossa di Pro Senectute beider Basel, \u00e8 un problema di tecnologia: \"Pro Senectute ha scelto due piattaforme ad alta soglia come Sandbox e Decentraland. La migliore esperienza di gioco si ottiene se ci si connette tramite un portafoglio personale di criptovalute\".<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"\">\n<div>\n<div class=\"GhzgLD8n\">\n<div class=\"paragraph-wrapper _2qEPPIZD _1Bo9lalQ\">\n<div class=\"_1eJ3lnN2\">\n<div class=\"_3izAStb3 _3mxNkRoj\">\n<div>\n<div class=\"paragraph text-paragraph _33izxNL0 VRK7E5k9\">\n<div>\n<p>Secondo Semmler, una piattaforma come Spatial sarebbe stata probabilmente pi\u00f9 facile da usare per gli utenti e pi\u00f9 economica da progettare e gestire per Pro Senectute come organizzazione, \"dato che il terreno virtuale non deve essere acquistato prima\". Tuttavia, Semmler vede pi\u00f9 aspetti positivi che preoccupazioni nell'operazione AVS: \"La cosa principale \u00e8 che l'organizzazione osa fare qualcosa\".<\/p>\n<p>Fonte: Handelszeitung<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Molte persone anziane hanno difficolt\u00e0 con la tecnologia. Nonostante questo, Pro Senectute beider Basel ha sviluppato tre...","protected":false},"author":12,"featured_media":20850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-20849","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Viele \u00e4ltere Menschen tun sich schwer mit der Technik. Trotzdem hat Pro Senectute beider Basel im Metaverse drei&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-02T08:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"517\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Pro Senectute will im Metaverse digitale Filialen aufbauen\",\"datePublished\":\"2022-10-02T08:24:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/\"},\"wordCount\":625,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/\",\"name\":\"Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png\",\"datePublished\":\"2022-10-02T08:24:59+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png\",\"width\":768,\"height\":517,\"caption\":\"Pro Senectute VR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2022\\\/10\\\/02\\\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro Senectute will im Metaverse digitale Filialen aufbauen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/","og_locale":"it_IT","og_type":"article","og_title":"Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News","og_description":"Viele \u00e4ltere Menschen tun sich schwer mit der Technik. Trotzdem hat Pro Senectute beider Basel im Metaverse drei&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2022-10-02T08:24:59+00:00","og_image":[{"width":768,"height":517,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Pro Senectute will im Metaverse digitale Filialen aufbauen","datePublished":"2022-10-02T08:24:59+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/"},"wordCount":625,"image":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png","articleSection":["Schweiz"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/","url":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/","name":"Pro Senectute will im Metaverse digitale Filialen aufbauen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png","datePublished":"2022-10-02T08:24:59+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/Screenshot-2022-09-26-at-10-25-27-Pro-Senectute-beider-Basel-kauft-Land-im-Metaverse.png","width":768,"height":517,"caption":"Pro Senectute VR"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2022\/10\/02\/pro-senectute-will-im-metaverse-digitale-filialen-aufbauen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Pro Senectute will im Metaverse digitale Filialen aufbauen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=20849"}],"version-history":[{"count":1,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20849\/revisions"}],"predecessor-version":[{"id":20851,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20849\/revisions\/20851"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/20850"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=20849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=20849"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=20849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}