{"id":20811,"date":"2022-09-21T14:28:02","date_gmt":"2022-09-21T14:28:02","guid":{"rendered":"https:\/\/vr-room.ch\/?p=20811"},"modified":"2022-09-13T14:35:14","modified_gmt":"2022-09-13T14:35:14","slug":"diese-schweizer-firmen-sind-leader-im-metaverse","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/it\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/","title":{"rendered":"Queste aziende svizzere sono leader nel metaverso"},"content":{"rendered":"<h3 id=\"erstmals-zeigt-eine-uebersicht-welche-firmen-und-institiutionen-bei-web-3-0-und-metaverse-fuehrend-sind\">Per la prima volta, una panoramica mostra quali aziende e istituzioni sono leader nel Web 3.0 e nel Metaverse.<\/h3>\n<p>Secondo Utpal Chakraborty di SwissCognitive, il Metaverso diventer\u00e0 il pi\u00f9 grande mercato virtuale nei prossimi cinque-dieci anni. Il Metaverso eliminer\u00e0 i confini fisici che noi umani dobbiamo affrontare. Grazie a un gemello digitale, si potr\u00e0 essere in pi\u00f9 luoghi contemporaneamente. Secondo Chakraborty, ci si pu\u00f2 aspettare una piattaforma commerciale globale completamente democratica e decentralizzata, indipendentemente dalle dimensioni e dal tipo di azienda.<\/p>\n<p>\"Con il Metaverse, vediamo uno schema simile all'introduzione del telefono cellulare nei primi anni 2000\", ha dichiarato Mark Forster, fondatore di Adello e Lab51 Inc. e presidente della taskforce Metaverse di IAB Svizzera. \"Il nostro recente sondaggio sul settore della pubblicit\u00e0 digitale in Svizzera ha rilevato che, sebbene il 71% degli intervistati ritenga che il Metaverse offra opportunit\u00e0 per il proprio business, solo il 25% sta lavorando a progetti o ha avviato progetti iniziali. Tuttavia, tendiamo a sopravvalutare la tecnologia nel breve termine e a sottovalutarla nel lungo termine\", ha dichiarato Forster in un comunicato.<\/p>\n<h3 id=\"schweiz-als-das-naechste-silicon-valley-fuer-krypto-und-blockchain\">La Svizzera come prossima Silicon Valley per cripto e blockchain<\/h3>\n<p>L'hype c'\u00e8, ma il metaverso vero e proprio non c'\u00e8 (ancora). \"Il metaverso si basa su diverse tecnologie che si trovano in diversi stadi di sviluppo e applicazione. Il tempo ci dir\u00e0 quando queste affascinanti tecnologie matureranno e culmineranno in quello che considereremo il metaverso vero e proprio\".<\/p>\n<p>Pur essendo un Paese piccolo, la Svizzera non manca di innovazione. In <a href=\"https:\/\/www.globenewswire.com\/news-release\/2022\/03\/23\/2408349\/0\/en\/DecentWorld-Investing-in-the-Metaverse-with-Swiss-level-Sustainability.html\" target=\"_blank\" rel=\"noopener\">un articolo di GlobeNewswire<\/a> si legge: \"Poich\u00e9 la Svizzera \u00e8 praticamente sinonimo di movimento tecnologico, viene spesso indicata come la prossima Silicon Valley per le criptovalute e la blockchain\". Secondo una dichiarazione di Adello, la Svizzera ospita molte aziende interessanti nello spazio del metaverso digitale. L'Ecosistema Metaverso Svizzero pubblicato da Adello mostra le aziende pi\u00f9 importanti che stanno plasmando il futuro del Web3 e del metaverso in Svizzera.<\/p>\n<p>Fonte: personale<\/p>","protected":false},"excerpt":{"rendered":"Per la prima volta, una panoramica mostra quali aziende e istituzioni sono leader nel Web 3.0 e nel Metaverse. Secondo...","protected":false},"author":12,"featured_media":20812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-20811","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/it\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Erstmals zeigt eine \u00dcbersicht, welche Firmen und Institiutionen bei Web 3.0 und Metaverse f\u00fchrend sind. Nach Ansicht von&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/it\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T14:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Diese Schweizer Firmen sind Leader im Metaverse\",\"datePublished\":\"2022-09-21T14:28:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/\"},\"wordCount\":339,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/\",\"name\":\"Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg\",\"datePublished\":\"2022-09-21T14:28:02+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg\",\"width\":1200,\"height\":1080,\"caption\":\"Metaverse Schweiz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2022\\\/09\\\/21\\\/diese-schweizer-firmen-sind-leader-im-metaverse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diese Schweizer Firmen sind Leader im Metaverse\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/it\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/","og_locale":"it_IT","og_type":"article","og_title":"Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News","og_description":"Erstmals zeigt eine \u00dcbersicht, welche Firmen und Institiutionen bei Web 3.0 und Metaverse f\u00fchrend sind. Nach Ansicht von&hellip;","og_url":"http:\/\/vr-room.ch\/it\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2022-09-21T14:28:02+00:00","og_image":[{"width":1200,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Diese Schweizer Firmen sind Leader im Metaverse","datePublished":"2022-09-21T14:28:02+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/"},"wordCount":339,"image":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg","articleSection":["Schweiz"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/","url":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/","name":"Diese Schweizer Firmen sind Leader im Metaverse - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg","datePublished":"2022-09-21T14:28:02+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/09\/f457d15e1875c2e584d55fef0193bb3e6e93be07.jpeg","width":1200,"height":1080,"caption":"Metaverse Schweiz"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2022\/09\/21\/diese-schweizer-firmen-sind-leader-im-metaverse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Diese Schweizer Firmen sind Leader im Metaverse"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=20811"}],"version-history":[{"count":2,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20811\/revisions"}],"predecessor-version":[{"id":20814,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/20811\/revisions\/20814"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/20812"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=20811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=20811"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=20811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}