{"id":16899,"date":"2020-05-09T10:12:15","date_gmt":"2020-05-09T10:12:15","guid":{"rendered":"https:\/\/vr-room.ch\/?p=16899"},"modified":"2020-05-04T19:30:25","modified_gmt":"2020-05-04T19:30:25","slug":"virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/it\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/","title":{"rendered":"La realt\u00e0 virtuale pu\u00f2 alleviare lo stress dell'isolamento"},"content":{"rendered":"<h3 id=\"in-zeit-der-isolation-zum-schutz-vor-dem-neuen-coronavirus-fehlen-vielen-menschen-ihre-sozialen-kontakte-und-der-umgang-mit-anderen-menschen-dies-kann-sich-negativ-auf-unsere-psychische-gesundheit-au\">In tempi di isolamento per proteggersi dal nuovo coronavirus, molte persone mancano di contatti sociali e di interazione con altre persone. Questo pu\u00f2 avere un impatto negativo sulla nostra salute mentale. Uno studio dimostra che la realt\u00e0 virtuale potrebbe aiutare a prevenire gli effetti negativi.<!--more--><\/h3>\n<p>Un recente studio del Virtual Reality Medical Institute di Bruxelles ha esaminato come possiamo proteggerci efficacemente dagli effetti psicologici dell'isolamento prolungato. I risultati sono stati pubblicati sulla rivista in lingua inglese \"<a href=\"https:\/\/www.liebertpub.com\/doi\/10.1089\/cyber.2020.29183.gri\" target=\"_blank\" rel=\"noopener noreferrer\">Cyberpsicologia, comportamento e social network<\/a>\" pubblicato.<\/p>\n<h3 id=\"virtuelle-realitaet-zum-schutz-der-psyche\">La realt\u00e0 virtuale per proteggere la psiche<\/h3>\n<p>L'articolo discute gli stress psicologici della pandemia di coronavirus e suggerisce come, ad esempio, la realt\u00e0 virtuale possa mitigare gli effetti psicologici dell'isolamento sociale. L'articolo include anche un link a un video tridimensionale a 360\u00b0 gratuito e suggerimenti su come utilizzarlo.<\/p>\n<p>\"Poich\u00e9 la nostra societ\u00e0 continua ad affrontare tempi difficili, diventa imperativo occuparsi del benessere mentale. \u00c8 incoraggiante vedere l'impatto positivo dell'uso pratico di tecnologie avanzate come la realt\u00e0 virtuale\", riporta nell'articolo la dottoressa Brenda K. Wiederhold del Virtual Reality Medical Institute di Bruxelles.<\/p>\n<h3 id=\"virtuelle-realitaet-kann-menschen-zusammenbringen\">La realt\u00e0 virtuale pu\u00f2 unire le persone<\/h3>\n<p>Sebbene in passato la realt\u00e0 virtuale sia stata in parte caratterizzata come isolante, sta diventando chiaro che gli spazi virtuali condivisi possono essere utilizzati come mezzo per riunire individui e famiglie. Questo \u00e8 particolarmente importante in tempi di isolamento per proteggersi dal coronavirus. Sono ora necessarie ulteriori ricerche per identificare ulteriori opportunit\u00e0 che possano arricchire la nostra esperienza umana condivisa\", aggiunge il dottor Wiederhold.<\/p>\n<p>Fonte: heilpraxisnet<\/p>","protected":false},"excerpt":{"rendered":"In tempi di isolamento per proteggersi dal nuovo coronavirus, molte persone mancano dei loro contatti sociali e...","protected":false},"author":12,"featured_media":16900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-16899","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-forschung","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/it\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"In Zeit der Isolation zum Schutz vor dem neuen Coronavirus fehlen vielen Menschen ihre sozialen Kontakte und der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/it\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-09T10:12:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern\",\"datePublished\":\"2020-05-09T10:12:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/\"},\"wordCount\":284,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg\",\"articleSection\":[\"Forschung\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/\",\"name\":\"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg\",\"datePublished\":\"2020-05-09T10:12:15+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg\",\"width\":1140,\"height\":570,\"caption\":\"Senior mature couple having fun with virtual reality glasses - Old people using new headset goggles trends technology - Joyful elderly lifestyle concept - Focus on center hands\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2020\\\/05\\\/09\\\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/it\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/","og_locale":"it_IT","og_type":"article","og_title":"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News","og_description":"In Zeit der Isolation zum Schutz vor dem neuen Coronavirus fehlen vielen Menschen ihre sozialen Kontakte und der&hellip;","og_url":"https:\/\/vr-room.ch\/it\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-05-09T10:12:15+00:00","og_image":[{"width":1140,"height":570,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nathalie","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern","datePublished":"2020-05-09T10:12:15+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/"},"wordCount":284,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg","articleSection":["Forschung"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/","url":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/","name":"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg","datePublished":"2020-05-09T10:12:15+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/05\/Corona-VirtuelleRealit\u00e4t-1140x570.jpeg","width":1140,"height":570,"caption":"Senior mature couple having fun with virtual reality glasses - Old people using new headset goggles trends technology - Joyful elderly lifestyle concept - Focus on center hands"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2020\/05\/09\/virtuelle-realitaet-kann-die-belastungen-der-isolation-lindern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Virtuelle Realit\u00e4t kann die Belastungen der Isolation lindern"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Notizie sulla realt\u00e0 virtuale in Svizzera","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/it\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/16899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/comments?post=16899"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/posts\/16899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media\/16900"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/media?parent=16899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/categories?post=16899"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/it\/wp-json\/wp\/v2\/tags?post=16899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}