{"id":9516,"date":"2018-02-20T14:39:57","date_gmt":"2018-02-20T14:39:57","guid":{"rendered":"http:\/\/vr-room.ch\/?p=9516"},"modified":"2018-02-20T14:41:21","modified_gmt":"2018-02-20T14:41:21","slug":"im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/","title":{"rendered":"Au mus\u00e9e des enfants de Baden, comme les aigles survolent les Dolomites"},"content":{"rendered":"<div class=\"container container--article\">\n<div class=\"wrapper\">\n<div id=\"sticky-wrapper\" class=\"main\">\n<div class=\"az-iso az-iso--articleIntro\">\n<div class=\"az-iso-component\">\n<div class=\"article-intro\">\n<div class=\"article-intro__lower\">\n<h3 id=\"eine-achterbahnfahrt-ein-sprung-aus-dem-flugzeug-die-halsbrecherische-abfahrt-eines-radfahrers-ein-von-der-hochschule-fuer-technik-rapperswil-hsr-entwickelter-simulator-ermoeglicht\" class=\"intro\">Un tour de montagnes russes, un saut d'avion, la descente vertigineuse d'un cycliste - un simulateur d\u00e9velopp\u00e9 par la Hochschule f\u00fcr Technik Rapperswil (HSR) permet de vivre virtuellement des films. Cette semaine, l'exp\u00e9rience s'invite au Kindermuseum de Baden.<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<p>Les visiteurs sont assis sur une plateforme en m\u00e9tal, attach\u00e9s \u00e0 une luge comme celles utilis\u00e9es sur les pistes de luge d'\u00e9t\u00e9. Tandis que les personnes pr\u00e9sentes peuvent suivre sur l'\u00e9cran ce qui se passe dans la RV, les utilisateurs vivent une formidable aventure.<\/p>\n<p>Les lunettes permettent une vue panoramique \u00e0 360 degr\u00e9s et, de la t\u00eate aux pieds, on se croit en route dans un avion \u00e0 h\u00e9lices pour un vol au-dessus de Rapperswil, looping et atterrissage sur le lac compris. La plateforme s'agite et se secoue et une brise souffle sur le visage depuis une machine \u00e0 vent. Voil\u00e0 ce que doit \u00eatre la libert\u00e9.<\/p>\n<h3 id=\"simulator-setzt-auch-filme-eins-zu-eins-um\">Le simulateur transpose aussi les films \u00e0 l'identique<\/h3>\n<p>La Haute \u00e9cole technique de Rapperswil (HSR) a combin\u00e9 la r\u00e9alit\u00e9 virtuelle avec un simulateur de mouvement, cr\u00e9ant ainsi un simulateur de vol totalement in\u00e9dit. Gr\u00e2ce \u00e0 six moteurs \u00e9lectriques, la plate-forme se d\u00e9place dans toutes les directions, exactement comme il convient \u00e0 la trajectoire choisie. Lorsque l'on fait un looping avec le planeur, on s'enfonce l\u00e9g\u00e8rement dans son si\u00e8ge. Le simulateur reproduit \u00e0 l'identique n'importe quel film trouv\u00e9 sur Internet.<\/p>\n<p>Cela est rendu possible par un logiciel programm\u00e9 de mani\u00e8re complexe. Alors qu'il est possible d'influer sur les commandes en vol, le passager assis sur son si\u00e8ge est dans ce cas totalement \u00e0 la merci de l'appareil. Le logiciel calcule la mani\u00e8re dont la cam\u00e9ra a \u00e9t\u00e9 d\u00e9plac\u00e9e et la transmet ensuite en temps r\u00e9el au mouvement du si\u00e8ge. \"Chaque film Youtube peut \u00eatre anim\u00e9 automatiquement. Le si\u00e8ge se d\u00e9place alors exactement comme la cam\u00e9ra s'est d\u00e9plac\u00e9e lors de l'enregistrement\", explique Guido Schuster, professeur d'\u00e9lectrotechnique en traitement num\u00e9rique du signal et de l'image \u00e0 l'Institut des syst\u00e8mes de communication, qui travaille avec son \u00e9quipe avec une joie et un enthousiasme palpables.<\/p>\n<h2 id=\"der-traum-vom-fliegen-wird-fuer-einige-zu-viel\">Le r\u00eave de voler devient trop lourd pour certains<\/h2>\n<p>Dans le cadre de l'exposition sp\u00e9ciale \"Le r\u00eave de voler\", qui se poursuit jusqu'\u00e0 la fin de l'ann\u00e9e, l'exp\u00e9rience VR est l'invit\u00e9e du mus\u00e9e des enfants de Baden cette semaine.<\/p>\n<p>\"Je me suis donc hiss\u00e9e dans la luge, j'ai attach\u00e9 ma ceinture, j'ai fait mettre les installations sur ma t\u00eate et je me suis install\u00e9e confortablement, pleine d'anticipation. Une minute plus tard, tremblante, avec des crampes d'estomac et la certitude que je n'\u00e9tais pas un aigle, j'avais, Dieu merci, retrouv\u00e9 la terre ferme\", raconte Rosmarie Mehlin, journaliste au Badner Tagblatt, qui poursuit : \"Des appels \u00e0 l'aide pointus de ma part avaient suscit\u00e9 la piti\u00e9 des dipl\u00f4m\u00e9s de la HSR, Jeffrey San Diego et Simon Locher, et la d\u00e9cision d'interrompre l'exercice. Ma peur de voler est minime - en revanche, mon manque de vertige est \u00e9norme. Et lorsque j'ai commenc\u00e9 \u00e0 voler au-dessus d'ab\u00eemes infinis en passant \u00e0 c\u00f4t\u00e9 de parois abruptes dans un silence d'aigle, mon pouls a grimp\u00e9 \u00e0 des hauteurs incommensurables\".<\/p>\n<p>En raison du poids des lunettes sp\u00e9ciales et des \u00e9couteurs, l'\u00e2ge minimum pour les enfants est de 10 ans. Pour les adultes, il n'y a pas de limite d'\u00e2ge sup\u00e9rieure. Cependant, il semble que les enfants supportent plus que certains adultes ; car il m'arriverait certainement la m\u00eame chose qu'\u00e0 la testeuse.<\/p>\n<p>Source : Badner Tagblatt \/ ZSZ<\/p>","protected":false},"excerpt":{"rendered":"Un tour de montagnes russes, un saut d'avion, la descente vertigineuse d'un cycliste - un concours organis\u00e9 par l'\u00c9cole...","protected":false},"author":12,"featured_media":9517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-9516","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Eine Achterbahnfahrt, ein Sprung aus dem Flugzeug, die halsbrecherische Abfahrt eines \u00adRadfahrers \u2013 ein von der Hochschule f\u00fcr&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-20T14:39:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-20T14:41:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen\",\"datePublished\":\"2018-02-20T14:39:57+00:00\",\"dateModified\":\"2018-02-20T14:41:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/\"},\"wordCount\":543,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Kindermuseum-VR.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/\",\"name\":\"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Kindermuseum-VR.jpg\",\"datePublished\":\"2018-02-20T14:39:57+00:00\",\"dateModified\":\"2018-02-20T14:41:21+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Kindermuseum-VR.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Kindermuseum-VR.jpg\",\"width\":1280,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/02\\\/20\\\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/","og_locale":"fr_FR","og_type":"article","og_title":"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News","og_description":"Eine Achterbahnfahrt, ein Sprung aus dem Flugzeug, die halsbrecherische Abfahrt eines \u00adRadfahrers \u2013 ein von der Hochschule f\u00fcr&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-02-20T14:39:57+00:00","article_modified_time":"2018-02-20T14:41:21+00:00","og_image":[{"width":1280,"height":719,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen","datePublished":"2018-02-20T14:39:57+00:00","dateModified":"2018-02-20T14:41:21+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/"},"wordCount":543,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/","url":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/","name":"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg","datePublished":"2018-02-20T14:39:57+00:00","dateModified":"2018-02-20T14:41:21+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/02\/Kindermuseum-VR.jpg","width":1280,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2018\/02\/20\/im-kindermuseum-baden-wie-die-adler-ueber-die-dolomiten-fliegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Im Kindermuseum Baden wie die Adler \u00fcber die Dolomiten fliegen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/9516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=9516"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/9516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/9517"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=9516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=9516"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=9516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}