{"id":8970,"date":"2017-12-29T09:40:21","date_gmt":"2017-12-29T09:40:21","guid":{"rendered":"http:\/\/vr-room.ch\/?p=8970"},"modified":"2017-12-29T09:40:21","modified_gmt":"2017-12-29T09:40:21","slug":"trainer-vr-virtuelle-modelleisenbahn","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/","title":{"rendered":"TrainerVR : construire des trains miniatures virtuels"},"content":{"rendered":"<p>Ceux qui ont toujours aim\u00e9 s'occuper de trains miniatures peuvent d\u00e9sormais le faire dans la r\u00e9alit\u00e9 virtuelle, car sur <a href=\"http:\/\/store.steampowered.com\/app\/763790\/TrainerVR\/\">Steam<\/a> &#8222;TrainerVR&#8220; f\u00fcr Oculus Rift und HTC Vive erh\u00e4ltlich ist.<\/p>\n<p>Die Beschreibung des Titels h\u00f6rt sich durchaus vielversprechend an: &#8222;TrainerVR ist ein einzigartiges und physik-basiertes VR-Zugbauspiel. In TrainerVR k\u00f6nnen sie von einfachen Gleisen bis hin zu einem ausgekl\u00fcgelten Schienennetz alles bauen, genau wie beim Holzspielzeug. Aber es geht noch dar\u00fcber hinaus. Wenn sie es gemocht haben, etwas mit blossen H\u00e4nden zu bauen, werden sie das Gleiche in unserer grenzenlosen VR-Welt erleben.&#8220;<\/p>\n<p>Les amateurs de mod\u00e9lisme classique sont donc transport\u00e9s dans la chambre d'enfant virtuelle, ce que l'on peut \u00e9galement observer dans la bande-annonce. Les circuits sont con\u00e7us individuellement et orn\u00e9s de diff\u00e9rents d\u00e9tails environnementaux. Et d\u00e8s que le mini-monde est termin\u00e9, on peut faire circuler autant de trains que l'on veut sur les rails. Le moteur physique devrait en tout cas donner des r\u00e9sultats r\u00e9alistes.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-8970-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=iCXDQ4-ArEY&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=iCXDQ4-ArEY\">https:\/\/www.youtube.com\/watch?v=iCXDQ4-ArEY<\/a><\/video><\/div>\n<p>Source : <a href=\"https:\/\/www.roadtovr.com\/trainervr-physics-based-vr-model-train-set-brings-back-simpler-times\/\">Route vers la VR<\/a><\/p>","protected":false},"excerpt":{"rendered":"Ceux qui ont toujours aim\u00e9 s'occuper de trains miniatures peuvent d\u00e9sormais le faire dans la r\u00e9alit\u00e9 virtuelle,...","protected":false},"author":11,"featured_media":8971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8970","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-games","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Wer sich schon immer gerne mit Modelleisenbahnen besch\u00e4ftigt hat, darf das jetzt auch in der virtuellen Realit\u00e4t tun,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-29T09:40:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1768\" \/>\n\t<meta property=\"og:image:height\" content=\"993\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"TrainerVR: Virtuelle Modelleisenbahnen bauen\",\"datePublished\":\"2017-12-29T09:40:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/\"},\"wordCount\":173,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/TrainerVR.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/\",\"name\":\"TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/TrainerVR.jpg\",\"datePublished\":\"2017-12-29T09:40:21+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/TrainerVR.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/TrainerVR.jpg\",\"width\":1768,\"height\":993},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2017\\\/12\\\/29\\\/trainer-vr-virtuelle-modelleisenbahn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TrainerVR: Virtuelle Modelleisenbahnen bauen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/","og_locale":"fr_FR","og_type":"article","og_title":"TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News","og_description":"Wer sich schon immer gerne mit Modelleisenbahnen besch\u00e4ftigt hat, darf das jetzt auch in der virtuellen Realit\u00e4t tun,&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-12-29T09:40:21+00:00","og_image":[{"width":1768,"height":993,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"TrainerVR: Virtuelle Modelleisenbahnen bauen","datePublished":"2017-12-29T09:40:21+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/"},"wordCount":173,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg","articleSection":["Games"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/","url":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/","name":"TrainerVR: Virtuelle Modelleisenbahnen bauen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg","datePublished":"2017-12-29T09:40:21+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/TrainerVR.jpg","width":1768,"height":993},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2017\/12\/29\/trainer-vr-virtuelle-modelleisenbahn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"TrainerVR: Virtuelle Modelleisenbahnen bauen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"http:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/8970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=8970"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/8970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/8971"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=8970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=8970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=8970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}