{"id":7282,"date":"2017-09-06T09:53:10","date_gmt":"2017-09-06T09:53:10","guid":{"rendered":"http:\/\/vr-room.ch\/?p=7282"},"modified":"2017-09-06T09:53:10","modified_gmt":"2017-09-06T09:53:10","slug":"vr-strategie-brass-tactics","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2017\/09\/06\/vr-strategie-brass-tactics\/","title":{"rendered":"Strat\u00e9gie VR par les d\u00e9veloppeurs d'Age of Empires 2"},"content":{"rendered":"<p>Hidden Path Entertainment und Oculus haben bekannt gegeben, dass die Ver\u00f6ffentlichung von &#8222;Brass Tactics&#8220; am 19. Oktober 2017 f\u00fcr Oculus Rift erfolgen wird. Das Echtzeit-Strategiespiel ist durchaus interessant, denn es stammt von den &#8222;Age of Empires 2&#8220;-Entwicklern.<\/p>\n<p><a href=\"https:\/\/de.wikipedia.org\/wiki\/Hidden_Path_Entertainment\">Hidden Path Entertainment<\/a> wurde im Jahr 2006 von Jim Garbarini, Michael Austin, Mark Terrano, Dave McCoy und Jeff Pobst in Bellevue gegr\u00fcndet. Bekannt wurde das Studio unter anderem durch das HD-Remake von &#8222;Age of Empires 2&#8220;.\u00a0 <a href=\"https:\/\/www.oculus.com\/blog\/brass-tactics-pre-orders-now-live-for-oculus-rift\/\">&#8222;Brass Tactics&#8220;<\/a> ist nach &#8222;Witchblood&#8220; und &#8222;Defense Grid 2&#8220; das dritte f\u00fcr VR konzipierte Spiel des Entwicklers<\/p>\n<p>&#8222;Brass Tactics&#8220; versetzt die Spieler in die Rolle eines Kommandanten, der seine aus Uhrwerk-Soldaten zusammengesetzten Armee auf einem mittelalterlichen Schlachtfeld gegen seine Widersacher antreten l\u00e4sst. Als Befehlshaber kann man Geb\u00e4ude auf der Karte platzieren und die Einheiten mit intuitiven Handbewegungen Befehle erteilen. Neben der Singleplayer-Kampagne bietet das Spiel zudem einen Versus- und Koop-Modus. Der Trailer zeigt Gameplay-Szenen und irgendwie sieht man darin ein klein wenig das Design von &#8222;Age of Empires 2&#8220; aufblitzen.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-7282-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=IOFPfsK3DLs&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=IOFPfsK3DLs\">https:\/\/www.youtube.com\/watch?v=IOFPfsK3DLs<\/a><\/video><\/div>\n<p>Source : communiqu\u00e9 de presse<\/p>","protected":false},"excerpt":{"rendered":"Hidden Path Entertainment und Oculus haben bekannt gegeben, dass die Ver\u00f6ffentlichung von &#8222;Brass Tactics&#8220; am 19. Oktober 2017&hellip;","protected":false},"author":11,"featured_media":7283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-7282","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2017\/09\/06\/vr-strategie-brass-tactics\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Hidden Path Entertainment und Oculus haben bekannt gegeben, dass die Ver\u00f6ffentlichung von &#8222;Brass Tactics&#8220; am 19. Oktober 2017&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2017\/09\/06\/vr-strategie-brass-tactics\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-06T09:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"VR-Strategie von Age of Empires 2-Entwicklern\",\"datePublished\":\"2017-09-06T09:53:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/\"},\"wordCount\":185,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BrassTactics.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/\",\"name\":\"VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BrassTactics.jpg\",\"datePublished\":\"2017-09-06T09:53:10+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BrassTactics.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/BrassTactics.jpg\",\"width\":780,\"height\":439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/09\\\/06\\\/vr-strategie-brass-tactics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR-Strategie von Age of Empires 2-Entwicklern\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2017\/09\/06\/vr-strategie-brass-tactics\/","og_locale":"fr_FR","og_type":"article","og_title":"VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News","og_description":"Hidden Path Entertainment und Oculus haben bekannt gegeben, dass die Ver\u00f6ffentlichung von &#8222;Brass Tactics&#8220; am 19. Oktober 2017&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2017\/09\/06\/vr-strategie-brass-tactics\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-09-06T09:53:10+00:00","og_image":[{"width":780,"height":439,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"VR-Strategie von Age of Empires 2-Entwicklern","datePublished":"2017-09-06T09:53:10+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/"},"wordCount":185,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg","articleSection":["Games"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/","url":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/","name":"VR-Strategie von Age of Empires 2-Entwicklern - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg","datePublished":"2017-09-06T09:53:10+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/09\/BrassTactics.jpg","width":780,"height":439},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/it\/2017\/09\/06\/vr-strategie-brass-tactics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR-Strategie von Age of Empires 2-Entwicklern"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"http:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/7282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=7282"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/7282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/7283"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=7282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=7282"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=7282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}