{"id":5254,"date":"2017-04-14T08:00:07","date_gmt":"2017-04-14T08:00:07","guid":{"rendered":"http:\/\/vr-room.ch\/?p=5254"},"modified":"2017-04-14T08:00:07","modified_gmt":"2017-04-14T08:00:07","slug":"rick-morty-schaffen-es-in-die-virtuelle-realitaet","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/","title":{"rendered":"Rick &amp; Morty passent \u00e0 la r\u00e9alit\u00e9 virtuelle"},"content":{"rendered":"<p>Mit dem &#8222;Job Simulator&#8220;\u00a0 hat das Entwickler-Studio Owlchemy Labs eines der ersten richtig erfolgreichen VR-Spiele abgeliefert. Die verr\u00fcckte Arbeitssimulation war und ist auf YouTube bzw. bei Let&#8217;s Plays \u00e4usserst beliebt, da allerlei abgedrehte und witzige Situationen entstehen k\u00f6nnen. Anfang Januar 2017 haben die Macher best\u00e4tigt, dass der &#8222;Job Simulator&#8220; einen Umsatz von mehr als drei Millionen US-Dollar generieren konnte. Jetzt folgt der n\u00e4chste Streich von Owlchemy Labs.<\/p>\n<p>&#8222;Rick and Morty: Virtual Rick-ality&#8220; wird bereits am 20. April 2017 f\u00fcr HTC Vive und Oculus Rift erscheinen. Das VR-Spiel basiert nat\u00fcrlich auf der beliebten TV-Zeichentrick-Serie &#8222;Rick and Morty&#8220;. In &#8222;Rick and Morty: Virtual Rick-ality&#8220; \u00fcbernimmt man als Spieler die Rolle eines Morty-Klons. Erkundet werden Ricks Garage, das Haus der Smiths und verschiedene Alien-Welten. Wie im kurzen Trailer ganz gut zu erkennen ist, werden die Gameplay-Mechaniken aus dem &#8222;Job Simulator&#8220; mit den Serieninhalten vermischt. Hoffentlich werden die Experimente und R\u00e4tsel gut umgesetzt. Auf <a href=\"http:\/\/store.steampowered.com\/app\/469610\/\">Steam<\/a> et dans le <a href=\"https:\/\/www.oculus.com\/experiences\/rift\/1098863863551663\/\">Boutique Oculus<\/a> sind bereits die Produktseiten zu &#8222;Rick and Morty: Virtual Rick-ality&#8220; verf\u00fcgbar.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-5254-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=g6frKRN2HzI&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=g6frKRN2HzI\">https:\/\/www.youtube.com\/watch?v=g6frKRN2HzI<\/a><\/video><\/div>\n<p>Source : VR-World<\/p>","protected":false},"excerpt":{"rendered":"Mit dem &#8222;Job Simulator&#8220;\u00a0 hat das Entwickler-Studio Owlchemy Labs eines der ersten richtig erfolgreichen VR-Spiele abgeliefert. Die verr\u00fcckte&hellip;","protected":false},"author":11,"featured_media":5255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5254","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-games","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Mit dem &#8222;Job Simulator&#8220;\u00a0 hat das Entwickler-Studio Owlchemy Labs eines der ersten richtig erfolgreichen VR-Spiele abgeliefert. Die verr\u00fcckte&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-14T08:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t\",\"datePublished\":\"2017-04-14T08:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/\"},\"wordCount\":199,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/RickMorty.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/\",\"name\":\"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/RickMorty.jpg\",\"datePublished\":\"2017-04-14T08:00:07+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/RickMorty.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/RickMorty.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2017\\\/04\\\/14\\\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/","og_locale":"fr_FR","og_type":"article","og_title":"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News","og_description":"Mit dem &#8222;Job Simulator&#8220;\u00a0 hat das Entwickler-Studio Owlchemy Labs eines der ersten richtig erfolgreichen VR-Spiele abgeliefert. Die verr\u00fcckte&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-04-14T08:00:07+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t","datePublished":"2017-04-14T08:00:07+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/"},"wordCount":199,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg","articleSection":["Games"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/","url":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/","name":"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg","datePublished":"2017-04-14T08:00:07+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/04\/RickMorty.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2017\/04\/14\/rick-morty-schaffen-es-in-die-virtuelle-realitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Rick &amp; Morty schaffen es in die virtuelle Realit\u00e4t"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"http:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/5254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=5254"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/5254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/5255"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=5254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=5254"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=5254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}