{"id":20534,"date":"2022-05-07T08:49:39","date_gmt":"2022-05-07T08:49:39","guid":{"rendered":"https:\/\/vr-room.ch\/?p=20534"},"modified":"2022-05-03T12:14:15","modified_gmt":"2022-05-03T12:14:15","slug":"asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/","title":{"rendered":"R\u00e9alit\u00e9 asynchrone : Des chercheurs de l'EPFZ arr\u00eatent le temps en r\u00e9alit\u00e9 virtuelle"},"content":{"rendered":"<p><strong>Deux chercheurs de l'EPF de Zurich manipulent le temps au poste de travail VR : pour favoriser la concentration, ils masquent les interruptions dans la r\u00e9alit\u00e9 via des lunettes VR et les enregistrent pour les voir plus tard.<br \/>\n<\/strong><\/p>\n<p>Des scientifiques de l'ETH Zurich pr\u00e9sentent dans leur travail de recherche le concept de r\u00e9alit\u00e9 asynchrone. Dans un environnement de travail immersif, le temps est suspendu afin de permettre un travail concentr\u00e9. Les \u00e9v\u00e9nements manqu\u00e9s dans la r\u00e9alit\u00e9 peuvent ensuite \u00eatre rattrap\u00e9s dans la r\u00e9alit\u00e9 virtuelle.<\/p>\n<h3 id=\"zeitmanipulation-fuer-konzentrierteres-arbeiten-in-vr\">Manipulation du temps pour un travail plus concentr\u00e9 en VR<\/h3>\n<p>Une \u00e9quipe de recherche de l'ETH Zurich se consacre aux bureaux immersifs du futur et d\u00e9veloppe un outil jusqu'ici unique qui montre quelles nouvelles possibilit\u00e9s le poste de travail XR pourrait apporter : Asynchronous Reality doit favoriser le travail immersif dans la r\u00e9alit\u00e9 virtuelle. Cela devrait \u00eatre possible gr\u00e2ce au \"Focus Mode\", qui permet d'arr\u00eater le temps dans le poste de travail virtuel.<\/p>\n<p>Les interactions de la r\u00e9alit\u00e9 ou des coll\u00e8gues qui travaillent avec vous via une interface AR sont masqu\u00e9es. Ce n'est que lorsque vous d\u00e9sactivez le mode Focus que le temps reprend son cours normal pour vous et que les \u00e9v\u00e9nements d\u00e9j\u00e0 pass\u00e9s se d\u00e9roulent dans votre espace de travail virtuel.<\/p>\n<p>Pour cr\u00e9er une r\u00e9alit\u00e9 asynchrone, le syst\u00e8me reconstruit des sc\u00e8nes volum\u00e9triques en temps r\u00e9el \u00e0 l'aide de cam\u00e9ras 3D de profondeur. Selon les chercheurs, il est capable de reconna\u00eetre les d\u00e9pendances causales des actions et de rejouer les situations de mani\u00e8re s\u00e9lective dans la perception des utilisateurs.<\/p>\n<h3 id=\"asynchrone-realitaet-im-arbeitsalltag-ein-beispiel-szenario\">La r\u00e9alit\u00e9 asynchrone dans le travail quotidien : un exemple de sc\u00e9nario<\/h3>\n<p>Dans une vid\u00e9o de neuf minutes, les chercheurs pr\u00e9sentent ce \u00e0 quoi pourrait ressembler un travail quotidien dans la r\u00e9alit\u00e9 asynchrone. L'exemple de sc\u00e9nario montre un programmeur travaillant avec sa coll\u00e8gue dans un environnement de travail immersif sur un jeu VR et la conception en 3D d'une figurine d\u00e9velopp\u00e9e \u00e0 partir de ce jeu.<\/p>\n<p>Le bureau est \u00e9quip\u00e9 de cam\u00e9ras et les personnes et les objets sont diffus\u00e9s dans l'environnement virtuel via des scans 3D en temps r\u00e9el. Apr\u00e8s des r\u00e9unions dans la r\u00e9alit\u00e9 et un environnement de travail virtuel partag\u00e9, le programmeur passe en mode Focus. Pour \u00e9liminer les distractions, les lunettes VR diffusent un bruit et le syst\u00e8me n'affiche plus que les objets scann\u00e9s \u00e0 proximit\u00e9 imm\u00e9diate, comme la souris, le clavier ou le bureau.<\/p>\n<h3 id=\"vergangene-geschehnisse-werden-als-hologramme-abgespielt\">Les \u00e9v\u00e9nements pass\u00e9s sont rejou\u00e9s sous forme d'hologrammes<\/h3>\n<p>Si une coll\u00e8gue passe la porte, elle est certes scann\u00e9e par les cam\u00e9ras. Mais le programmeur n'en a pas conscience dans un premier temps. Le syst\u00e8me enregistre l'ensemble du processus et les modifications dans la pi\u00e8ce, qui peuvent par exemple \u00eatre dues \u00e0 l'introduction d'un nouvel objet.<\/p>\n<p>Ces nouveaux objets sont d'abord rendus sous forme de silhouettes scintillantes. Ainsi, le programmeur ne les remarque que lorsqu'il se retourne de sa propre initiative. Il ne re\u00e7oit pas non plus de notification.<\/p>\n<p>Lorsqu'il voit le nouvel objet et qu'il souhaite l'examiner, il appuie dessus dans la r\u00e9alit\u00e9 virtuelle. Le syst\u00e8me reproduit pour lui l'\u00e9v\u00e9nement enregistr\u00e9 comme un bref hologramme. Il voit comment sa coll\u00e8gue apporte l'objet, le pose sur la table et entend ce qu'elle lui dit.<\/p>\n<h3 id=\"asynchronous-reality-erkennt-kausale-zusammenhaenge\">La r\u00e9alit\u00e9 asynchrone reconna\u00eet les relations de cause \u00e0 effet<\/h3>\n<p>Si, pendant le mode Focus, plusieurs \u00e9v\u00e9nements modifient les pr\u00e9c\u00e9dents, comme l'ajout ou le retrait de nouveaux objets, le syst\u00e8me reconna\u00eet les liens de cause \u00e0 effet. Il cr\u00e9e une ligne de temps et marque automatiquement les \u00e9v\u00e9nements li\u00e9s.<\/p>\n<p>Ainsi, si le programmeur joue d'abord l'\u00e9v\u00e9nement qui s'est produit en dernier apr\u00e8s avoir termin\u00e9 le mode Focus, le syst\u00e8me lui montre d'abord les \u00e9v\u00e9nements n\u00e9cessaires \u00e0 la compr\u00e9hension de l'ensemble du processus. Vous trouverez d'autres exemples et d\u00e9tails sur le prototype du bureau de la r\u00e9alit\u00e9 asynchrone dans le <a href=\"https:\/\/siplab.org\/papers\/chi2022-asynchronous_reality.pdf\" target=\"_blank\" rel=\"noopener\">Document de recherche<\/a> des scientifiques.<\/p>\n<p><iframe loading=\"lazy\" title=\"Sc\u00e9nario complet : une journ\u00e9e de travail avec une r\u00e9alit\u00e9 asynchrone\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/maEDwbLtTBY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Source : Mixed \/ Youtube<\/p>","protected":false},"excerpt":{"rendered":"Deux chercheurs de l'EPF de Zurich manipulent le temps au poste de travail VR : pour favoriser la concentration, ils masquent les interruptions...","protected":false},"author":12,"featured_media":20535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-20534","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Zwei Forscher der ETH Z\u00fcrich manipulieren die Zeit am VR-Arbeitsplatz: Um die Konzentration zu f\u00f6rdern, blenden sie Unterbrechungen&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-07T08:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an\",\"datePublished\":\"2022-05-07T08:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/\"},\"wordCount\":606,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/FRcl6SvX0AI5OIL-1200x600-1.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/\",\"name\":\"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/FRcl6SvX0AI5OIL-1200x600-1.jpg\",\"datePublished\":\"2022-05-07T08:49:39+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/FRcl6SvX0AI5OIL-1200x600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/FRcl6SvX0AI5OIL-1200x600-1.jpg\",\"width\":1200,\"height\":600,\"caption\":\"ETH VR Forschung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2022\\\/05\\\/07\\\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/","og_locale":"fr_FR","og_type":"article","og_title":"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News","og_description":"Zwei Forscher der ETH Z\u00fcrich manipulieren die Zeit am VR-Arbeitsplatz: Um die Konzentration zu f\u00f6rdern, blenden sie Unterbrechungen&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2022-05-07T08:49:39+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an","datePublished":"2022-05-07T08:49:39+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/"},"wordCount":606,"image":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/","url":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/","name":"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg","datePublished":"2022-05-07T08:49:39+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2022\/05\/FRcl6SvX0AI5OIL-1200x600-1.jpg","width":1200,"height":600,"caption":"ETH VR Forschung"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2022\/05\/07\/asynchrone-realitaet-eth-forscher-halten-zeit-in-der-virtual-reality-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Asynchrone Realit\u00e4t: ETH Forscher halten Zeit in der Virtual Reality an"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/20534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=20534"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/20534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/20535"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=20534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=20534"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=20534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}