{"id":19469,"date":"2021-05-21T10:08:11","date_gmt":"2021-05-21T10:08:11","guid":{"rendered":"https:\/\/vr-room.ch\/?p=19469"},"modified":"2021-05-19T17:20:25","modified_gmt":"2021-05-19T17:20:25","slug":"immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/","title":{"rendered":"Commercialisation de biens immobiliers avec VR sur le lac des Quatre-Cantons"},"content":{"rendered":"<div class=\"headline__inner\">\n<h3 id=\"fuer-immobilienmakler-willy-mischler-ist-ein-traum-wahr-geworden-sein-einzigartiges-homeoffice-hat-er-sich-auf-dem-vierwaldstaettersee-eingerichtet-bald-moechte-er-auch-mit-vr-seine-kunden-begeister\" class=\"headline__lead\">Pour l'agent immobilier Willy Mischler, un r\u00eave est devenu r\u00e9alit\u00e9. Il a am\u00e9nag\u00e9 son bureau \u00e0 domicile unique en son genre sur le lac des Quatre-Cantons. Bient\u00f4t, il souhaite \u00e9galement enthousiasmer ses clients avec la RV.<\/h3>\n<\/div>\n<p><!--more--><\/p>\n<p class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Parmi ses atouts professionnels, il y a une forte capacit\u00e9 d'imagination et de pens\u00e9e logique. \"Je peux me projeter mentalement dans un appartement qui n'existe pas encore. Si n\u00e9cessaire, nous retravaillons les plans avec les architectes avant de les mettre sur le march\u00e9\", explique l'agent immobilier Willy Mischler dans un portrait publi\u00e9 par la Luzerner Zeitung.  Ce conseiller immobilier extraverti est \u00e0 l'aise dans le secteur de la propri\u00e9t\u00e9 immobili\u00e8re. Sa soci\u00e9t\u00e9 d\u00e9veloppe, \u00e9value et commercialise des b\u00e2timents.<\/p>\n<h3 id=\"id-doc-1f5dq5d9h0\" class=\"subtitle articlecomponent\" data-team-subtitle=\"\" data-nzz-article-component=\"\"><span id=\"buero-boot-kam-von-holland-nach-brunnen\"><span class=\"\"><strong>Un bateau-bureau est venu de Hollande \u00e0 Brunnen<\/strong><\/span><\/span><\/h3>\n<p id=\"id-doc-1f5dq5d9j0\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Il y a deux ans, un autre projet de Mischler a pris son envol : son bateau-bureau. Ceci apr\u00e8s que Mischler ait pu s'assurer l'une des rares grandes places de bateau \u00e0 Hergiswil. Avec l'architecte naval hollandais Oliver van Meer et un chantier naval \u00e0 Harlingen, aux Pays-Bas, il a trouv\u00e9 les constructeurs de bateaux ad\u00e9quats pour son projet.<\/p>\n<p id=\"id-doc-1f5drmgqn1\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Le r\u00e9sultat est impressionnant : Le bateau a une longueur de 14,5 m\u00e8tres, une largeur de 4,5 m\u00e8tres et une hauteur de 4,6 m\u00e8tres.  Le pont est \u00e9quip\u00e9 de panneaux photovolta\u00efques et offre suffisamment de place pour les amateurs de soleil. Le bateau est autoris\u00e9 \u00e0 accueillir douze personnes.<\/p>\n<h3 id=\"id-doc-1f5dq5d9l0\" class=\"subtitle articlecomponent\" data-team-subtitle=\"\" data-nzz-article-component=\"\"><span id=\"virtual-reality-auf-dem-see\"><span class=\"\"><strong>R\u00e9alit\u00e9 virtuelle sur le lac<\/strong><\/span><\/span><\/h3>\n<p id=\"id-doc-1f5dq5d9m0\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Mischler n'a pas construit l'objet flottant - sa vitesse maximale est de 15 kilom\u00e8tres \u00e0 l'heure - uniquement pour lui-m\u00eame. \"Cette pi\u00e8ce unique est en premier lieu mon bureau \u00e0 domicile et doit contribuer \u00e0 l'exp\u00e9rience client. Par exemple, si possible, tous les contrats de vente seront d\u00e9sormais authentifi\u00e9s sur le lac. Nous voulons ainsi rester dans les m\u00e9moires de mani\u00e8re positive\". Cette plate-forme flottante est id\u00e9ale pour les \u00e9v\u00e9nements clients, le r\u00e9seautage, la commercialisation et l'utilisation priv\u00e9e. Un autre objectif serait de proposer la commercialisation avec la r\u00e9alit\u00e9 virtuelle (VR) depuis le bateau-bureau. Les personnes int\u00e9ress\u00e9es par un achat pourront \u00e0 l'avenir visiter les biens immobiliers exclusifs en 3D depuis le bateau, en toute saison et par tous les temps, gr\u00e2ce \u00e0 des lunettes VR.<\/p>\n<p data-team-paragraph=\"\" data-nzz-article-component=\"\"><span dir=\"ltr\">D\u00e9sireux de vendre <\/span><span dir=\"ltr\">Propri\u00e9taire <\/span><span dir=\"ltr\">ou potentiels <\/span><span dir=\"ltr\">Acheteur<\/span><span dir=\"ltr\">villas, maisons ou appartements de prestige avec vue sur le lac <\/span><span dir=\"ltr\">seront <\/span><span dir=\"ltr\">de la m\u00eame mani\u00e8re <\/span><span dir=\"ltr\">est abord\u00e9e. <\/span><span dir=\"ltr\">Vous b\u00e9n\u00e9ficiez <\/span><span dir=\"ltr\">de la possibilit\u00e9 tr\u00e8s discr\u00e8te d'acheter un bien immobilier <\/span><span dir=\"ltr\">ou un projet de nouvelle construction en r\u00e9alit\u00e9 virtuelle sur <\/span><span dir=\"ltr\">d\u00e9couvrir la p\u00e9niche-bureau.<\/span><\/p>\n<h3 id=\"vorteil-1-privatsphaere\"><span dir=\"ltr\">Avantage 1 - Intimit\u00e9<\/span><\/h3>\n<p data-team-paragraph=\"\" data-nzz-article-component=\"\"><span dir=\"ltr\">La visite des RV peut \u00eatre effectu\u00e9e \u00e0 tout moment.<\/span><span dir=\"ltr\">&#8211;<\/span><span dir=\"ltr\">Les travaux peuvent \u00eatre r\u00e9alis\u00e9s sans d\u00e9ranger les clients exclusifs. <\/span><span dir=\"ltr\">Les personnes int\u00e9ress\u00e9es ne sont contact\u00e9es qu'en cas d'intention d'achat s\u00e9rieuse et de <\/span><span dir=\"ltr\">une fois la preuve de financement fournie, \u00e9galement r\u00e9elle <\/span><span dir=\"ltr\">guid\u00e9 \u00e0 travers l'immeuble.<\/span><\/p>\n<h3 id=\"vorteil-2-wetterunabhaengigkeit\"><span dir=\"ltr\">Avantage 2 - Ind\u00e9pendance vis-\u00e0-vis de la m\u00e9t\u00e9o<\/span><\/h3>\n<p data-team-paragraph=\"\" data-nzz-article-component=\"\"><span dir=\"ltr\">La visite VR montre toujours l'objet dans son int\u00e9gralit\u00e9. <\/span><span dir=\"ltr\">meilleure lumi\u00e8re - de jour ou dans l'obscurit\u00e9, m\u00eame si <\/span><span dir=\"ltr\">la pluie, la neige ou le brouillard qui masque le panorama alpin.<\/span><span dir=\"ltr\">de l'ext\u00e9rieur. Lors de la visite avec les lunettes VR, le client se tient debout. <\/span><span dir=\"ltr\">toujours par un soleil radieux sur le balcon de la <\/span><span dir=\"ltr\">propri\u00e9t\u00e9 et profite de la vue sur le lac et les <\/span><span dir=\"ltr\">Commodit\u00e9s du bateau-bureau EDELWEISS.<\/span><\/p>\n<h3 id=\"vorteil-3-neubauprojekte\"><span dir=\"ltr\">Avantage 3 - Projets de nouvelles constructions<\/span><\/h3>\n<p data-team-paragraph=\"\" data-nzz-article-component=\"\"><span dir=\"ltr\">Des projets de nouvelles constructions, comme par exemple \"Am Steinbach\" \u00e0 <\/span><span dir=\"ltr\">Hergiswil am See ou un projet non encore abouti \u00e0 <\/span><span dir=\"ltr\">Beckenried\/NW peuvent \u00eatre visit\u00e9s depuis le bateau-bureau. <\/span><span dir=\"ltr\">ou achet\u00e9s. Car lors de la visite de la RV, ils voient <\/span><span dir=\"ltr\">le produit fini et visitent leur nouvelle maison <\/span><span dir=\"ltr\">Ind\u00e9pendant des conditions m\u00e9t\u00e9orologiques, propre et sans danger.<\/span><\/p>\n<p id=\"id-doc-1f5dq5d9r0\" class=\"articlecomponent text\" data-team-paragraph=\"\" data-nzz-article-component=\"\">Source : Luzerner Zeitung \/ mischler-immobilien<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"Pour l'agent immobilier Willy Mischler, un r\u00eave est devenu r\u00e9alit\u00e9. Il a am\u00e9nag\u00e9 son bureau \u00e0 domicile unique en son genre sur le lac des Quatre-Cantons....","protected":false},"author":12,"featured_media":19470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-19469","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr Immobilienmakler Willy Mischler ist ein Traum wahr geworden. Sein einzigartiges Homeoffice hat er sich auf dem Vierwaldst\u00e4ttersee&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T10:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png\" \/>\n\t<meta property=\"og:image:width\" content=\"796\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee\",\"datePublished\":\"2021-05-21T10:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/\"},\"wordCount\":532,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/\",\"name\":\"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png\",\"datePublished\":\"2021-05-21T10:08:11+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png\",\"width\":796,\"height\":594,\"caption\":\"Boot AR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2021\\\/05\\\/21\\\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/","og_locale":"fr_FR","og_type":"article","og_title":"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News","og_description":"F\u00fcr Immobilienmakler Willy Mischler ist ein Traum wahr geworden. Sein einzigartiges Homeoffice hat er sich auf dem Vierwaldst\u00e4ttersee&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2021-05-21T10:08:11+00:00","og_image":[{"width":796,"height":594,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee","datePublished":"2021-05-21T10:08:11+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/"},"wordCount":532,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/","url":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/","name":"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png","datePublished":"2021-05-21T10:08:11+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/05\/Screenshot_2021-05-19-Vierwaldst\u00e4ttersee-Willy-Mischler-hat-sein-Homeoffice-nun-auf-dem-Wasser.png","width":796,"height":594,"caption":"Boot AR"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2021\/05\/21\/immobilienvermarktung-mit-vr-auf-dem-vierwaldstaettersee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Immobilienvermarktung mit VR auf dem Vierwaldst\u00e4ttersee"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=19469"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/19470"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=19469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=19469"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=19469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}