{"id":19135,"date":"2021-04-07T10:14:48","date_gmt":"2021-04-07T10:14:48","guid":{"rendered":"https:\/\/vr-room.ch\/?p=19135"},"modified":"2021-03-31T18:50:49","modified_gmt":"2021-03-31T18:50:49","slug":"pflanzen-shoppen-mit-ar-unterstuetzung","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/","title":{"rendered":"Acheter des plantes avec l'aide de la RA"},"content":{"rendered":"<div class=\"node__content \">\n<div class=\"clearfix text-formatted field field--name-np8-lead field--type-text-long field--label-hidden field__item\">\n<div class=\"rte lg--up--three-quarters mt3 font-size--sm line-height--4 wd--font-size--m wd--line-height--4\">\n<h3 id=\"wie-eine-wohnung-mit-einer-neuen-pflanzen-aussehen-wuerde-das-kann-man-ganz-einfach-ueberpruefen-das-auf-pflanzen-spezialisierte-unternehmen-feey-bietet-naemlich-eine-loesung-mit-augmented-reality\">Wie eine Wohnung mit einer neuen Pflanzen aussehen w\u00fcrde? Das kann man ganz einfach \u00fcberpr\u00fcfen. Das auf Pflanzen spezialisierte Unternehmen feey bietet n\u00e4mlich eine L\u00f6sung mit Augmented Reality.<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-node--np8-main-media field-name-np8-main-media field-type-file field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item\">\n<div class=\"rte lg--up--three-quarters mt3 font-size--sm line-height--4 wd--font-size--m wd--line-height--4\">\n<div class=\"rte__video-wrapper\">Anfassen liegt nicht drin. Aber dank Augmented Reality kannst man live und in Farbe schauen, wie die Pflanzen von <a href=\"https:\/\/feey.ch\/collections\/alle\/ar-pflanzen\">feey<\/a> bei sich zuhause aussehen w\u00fcrden. Man braucht also weder r\u00e4umliches Vorstellungsverm\u00f6gen noch musst man ausmessen, ob da noch genug Platz ist. Was Ikea kann k\u00f6nnen die Schweizer auch. Feey geh\u00f6rt zu den ersten Schweizer Online-Shop mit webbasierter Augmented Reality.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<div id=\"2762B08B-2E27-F9B4-71DF-98DE5F6548DA\" class=\"story story_body\">\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\"> M\u00f6glich macht&#8217;s die AR-Technologie von <a href=\"https:\/\/bitforge.ch\/\">Bitforge<\/a>. Um die Anwendung zu nutzen, m\u00fcssten Kundinnen und Kunden keine App herunterladen. Die Handy-Kamera und ein Klick auf den Link auf der Feey-Website gen\u00fcgen, um die ausgew\u00e4hlte Pflanze ins Haus zu holen. <\/span><\/p>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">\u00abAugmented Reality hat das Potenzial, den Onlinehandel nachhaltig zu ver\u00e4ndern. Gerade die Tatsache, dass dank Web-AR keine App-Entwicklung n\u00f6tig ist, kommt einer technischen Revolution gleich, von der insbesondere KMU profitieren\u00bb, verlautete Robin Waibel, Managing Partner bei Bitforge. <\/span><\/p>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">Um die AR-Anwendung popul\u00e4r zu machen, startete Feey schon im vergangenen Jahr einen Wettbewerb. Dabei konnten Kundinnen und Kunden eine Riesenpflanze irgendwo in ihrer Umgebung platzieren und ein Bild davon bei Feey hochladen. Die Einreicher der kreativsten Bilder gewann laut dem Pflanzenshop eine Grosspflanze. <\/span><\/p>\n<h3 id=\"ar-goes-shopping\">AR goes Shopping<\/h3>\n<p>Bitforge startete vergangenes Jahr gar einen ganzen AR-Commerce-Dienst. Der Dienst namens \u00abGenie AR\u00bb wurde bisher nicht nur von feey, sondern auch von Coop Bau\u2009+\u2009Hobby und dem Schweizer Armaturen-Hersteller KWC eingesetzt.Bei <a href=\"https:\/\/www.bauundhobby.ch\/aktionen\/weihnachtsbaeume#arservice\">Coop Bau + Hobby<\/a> k\u00f6nnen Kunden sehen, ob der Weihnachtsbaum ins Wohnzimmer passt. Es ist ganz einfach: Man w\u00e4hlt eine Tanne aus, scannt mit dem Smartphone den QR-Code und klickt auf \u00abIm Raum platzieren\u00bb und tada: Weihnachten kann kommen. <a href=\"https:\/\/www.kwc.ch\/de\/de\/produkte\/ar-landing-page.html\">KWC<\/a> nutzt Genie AR sowohl als Showroom auf seiner Website als auch als Pr\u00e4sentationstool f\u00fcr das internationale Sales-Team. Die Anwendung funktioniert ebenfalls \u00fcber einen QR-Code, den man scannt.<\/p>\n<p>Quelle: Netzwoche \/ feey<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"\u00c0 quoi ressemblerait un appartement avec une nouvelle plante ? C'est tr\u00e8s facile \u00e0 v\u00e9rifier. Le sur les plantes...","protected":false},"author":12,"featured_media":19136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-19135","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/fr\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Wie eine Wohnung mit einer neuen Pflanzen aussehen w\u00fcrde? Das kann man ganz einfach \u00fcberpr\u00fcfen. Das auf Pflanzen&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/fr\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-07T10:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Pflanzen shoppen mit AR Unterst\u00fctzung\",\"datePublished\":\"2021-04-07T10:14:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/\"},\"wordCount\":337,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/screenshot_20201027-114007_chrome.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/\",\"name\":\"Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/screenshot_20201027-114007_chrome.jpg\",\"datePublished\":\"2021-04-07T10:14:48+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/screenshot_20201027-114007_chrome.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/screenshot_20201027-114007_chrome.jpg\",\"width\":700,\"height\":394,\"caption\":\"feey ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/2021\\\/04\\\/07\\\/pflanzen-shoppen-mit-ar-unterstuetzung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pflanzen shoppen mit AR Unterst\u00fctzung\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/fr\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/","og_locale":"fr_FR","og_type":"article","og_title":"Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News","og_description":"Wie eine Wohnung mit einer neuen Pflanzen aussehen w\u00fcrde? Das kann man ganz einfach \u00fcberpr\u00fcfen. Das auf Pflanzen&hellip;","og_url":"http:\/\/vr-room.ch\/fr\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2021-04-07T10:14:48+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Pflanzen shoppen mit AR Unterst\u00fctzung","datePublished":"2021-04-07T10:14:48+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/"},"wordCount":337,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/","url":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/","name":"Pflanzen shoppen mit AR Unterst\u00fctzung - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg","datePublished":"2021-04-07T10:14:48+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2021\/03\/screenshot_20201027-114007_chrome.jpg","width":700,"height":394,"caption":"feey ar"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/en\/2021\/04\/07\/pflanzen-shoppen-mit-ar-unterstuetzung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Pflanzen shoppen mit AR Unterst\u00fctzung"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=19135"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/19135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/19136"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=19135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=19135"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=19135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}