{"id":17970,"date":"2020-09-29T08:41:22","date_gmt":"2020-09-29T08:41:22","guid":{"rendered":"https:\/\/vr-room.ch\/?p=17970"},"modified":"2020-09-25T08:48:32","modified_gmt":"2020-09-25T08:48:32","slug":"eintauchen-ins-universum-von-alexander-von-humboldt","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/","title":{"rendered":"Plong\u00e9e dans l'univers d'Alexander von Humboldt"},"content":{"rendered":"<h3 id=\"zu-ehren-des-250-geburtstags-des-universalforschers-hat-der-verein-wissenschaft-fuer-alle-eine-ausstellung-erschaffen-die-an-verschiedenen-standorten-besucht-werden-kann-spannende\">En l'honneur du 250e anniversaire de la naissance de l'explorateur universel, l'association \"Science pour tous\" a cr\u00e9\u00e9 une exposition qui peut \u00eatre visit\u00e9e \u00e0 diff\u00e9rents endroits. Des d\u00e9couvertes passionnantes sur la vie et les recherches de Humboldt \u00e9veillent l'int\u00e9r\u00eat pour la science. L'exposition est interactive et la r\u00e9alit\u00e9 virtuelle ne peut \u00e9videmment pas manquer.<!--more--><\/h3>\n<div class=\"et_pb_module et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light et_had_animation\">\n<div class=\"et_pb_text_inner\">\n<p>L'exposition mobile interactive vise \u00e0 stimuler l'int\u00e9r\u00eat et l'enthousiasme pour les sciences naturelles et autres sciences, en particulier chez les \u00e9coliers, mais aussi aupr\u00e8s du grand public. Au cours de ses voyages aventureux autour du monde, Humboldt a fait diverses d\u00e9couvertes, a d\u00e9couvert de nouvelles r\u00e9gions qu'il a consign\u00e9es sur des cartes et a consign\u00e9 dans de nombreux volumes les r\u00e9sultats de ses mesures et de ses observations dans la nature. Humboldt avait visit\u00e9 la Suisse pour pr\u00e9parer son voyage autour du monde et \u00e9tait un fervent admirateur des Alpes.<\/p>\n<p>Le concept d'exposition interactif cr\u00e9e un lien avec l'\u00e9ducation et la recherche d'aujourd'hui et vise \u00e0 \u00e9veiller l'esprit de d\u00e9couverte chez les jeunes. Les nouvelles technologies, comme la r\u00e9alit\u00e9 virtuelle, ne sont \u00e9videmment pas absentes pour intercepter les plus jeunes visiteurs. Gr\u00e2ce aux lunettes, les visiteurs peuvent s'immerger encore plus profond\u00e9ment dans l'univers de Humboldt.<\/p>\n<p>Sur la <a href=\"https:\/\/weltvernetzer.ch\/orte-und-daten-ausstellung\/\">Site web<\/a> vous, quand l'exposition itin\u00e9rante s'arr\u00eate o\u00f9.<\/p>\n<p>Source : weltvernetzer \/ zentralplus<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"En l'honneur du 250e anniversaire de la naissance de l'explorateur universel, l'association \"Science pour tous\" a cr\u00e9\u00e9 une exposition qui rappelle...","protected":false},"author":12,"featured_media":17971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-17970","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Zu Ehren des 250. Geburtstags des Universalforschers hat der Verein \u00abWissenschaft f\u00fcr alle\u00bb eine Ausstellung erschaffen, die\u00a0 an&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-29T08:41:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Eintauchen ins Universum von Alexander von Humboldt\",\"datePublished\":\"2020-09-29T08:41:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/\"},\"wordCount\":202,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/DSC04057.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/\",\"name\":\"Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/DSC04057.jpg\",\"datePublished\":\"2020-09-29T08:41:22+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/DSC04057.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/DSC04057.jpg\",\"width\":2362,\"height\":1772,\"caption\":\"Humboldt, der Weltvernetzer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2020\\\/09\\\/29\\\/eintauchen-ins-universum-von-alexander-von-humboldt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eintauchen ins Universum von Alexander von Humboldt\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/","og_locale":"fr_FR","og_type":"article","og_title":"Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News","og_description":"Zu Ehren des 250. Geburtstags des Universalforschers hat der Verein \u00abWissenschaft f\u00fcr alle\u00bb eine Ausstellung erschaffen, die\u00a0 an&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2020-09-29T08:41:22+00:00","og_image":[{"width":2362,"height":1772,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Eintauchen ins Universum von Alexander von Humboldt","datePublished":"2020-09-29T08:41:22+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/"},"wordCount":202,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/","url":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/","name":"Eintauchen ins Universum von Alexander von Humboldt - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg","datePublished":"2020-09-29T08:41:22+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2020\/09\/DSC04057.jpg","width":2362,"height":1772,"caption":"Humboldt, der Weltvernetzer"},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2020\/09\/29\/eintauchen-ins-universum-von-alexander-von-humboldt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Eintauchen ins Universum von Alexander von Humboldt"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/17970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=17970"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/17970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/17971"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=17970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=17970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=17970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}