{"id":10916,"date":"2018-07-25T07:54:14","date_gmt":"2018-07-25T07:54:14","guid":{"rendered":"http:\/\/vr-room.ch\/?p=10916"},"modified":"2018-07-25T07:54:14","modified_gmt":"2018-07-25T07:54:14","slug":"vr-mystery-game-torn-termin","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2018\/07\/25\/vr-mystery-game-torn-termin\/","title":{"rendered":"Le jeu de myst\u00e8re VR Torn a une date butoir"},"content":{"rendered":"<p>Wie jetzt bekannt gegeben wurde, wird Aspyr Media das d\u00fcstere Sci-Fi-Mystery-Game &#8222;Torn&#8220; am 28. August 2018 f\u00fcr PlayStation VR, HTC Vive und Oculus Rift auf den Markt bringen. Die Handlung des Titels klingt spannend.<\/p>\n<p>&#8222;Torn&#8220; findet in der Villa des ber\u00fchmten Physikers Dr. Lawrence Talbot statt, der vor 64 Jahren verschwunden ist. Die mysteri\u00f6se Villa ist voller seltsamer Apparaturen, die in die W\u00e4nde und den Boden eingebaut sind. Es gilt herauszufinden, was sie tun und was mit der Person geschehen, die sie gebaut hat. Das verspricht zahlreiche R\u00e4tsel und Puzzles.<\/p>\n<p>&#8222;Talbots Herrenhaus voller R\u00e4tsel und Machenschaften eines wahnsinnigen, k\u00f6rperlosen Physikers ist das perfekte virtuelle Touristenziel f\u00fcr Fans klassischer Science-Fiction wie The Twilight Zone und Black Mirror,&#8220; heisst es seitens des Herstellers. &#8222;Torn&#8220; kann \u00fcber <a href=\"https:\/\/store.steampowered.com\/app\/557520\/Torn\/\">Steam<\/a>, le <a href=\"https:\/\/www.oculus.com\/experiences\/rift\/1981676341851640\/\">Boutique Oculus<\/a> et le <a href=\"https:\/\/store.playstation.com\">PlayStation Store<\/a> peuvent \u00eatre achet\u00e9s. Sur <a href=\"https:\/\/www.facebook.com\/aspyrmedia\/photos\/a.1621581501253168.1073741838.109613065783360\/1647569628654355\/?type=3&amp;theater\">Facebook<\/a> on peut \u00e9galement voir quelques captures d'\u00e9cran \u00e0 360 degr\u00e9s.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-10916-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=1qL6CdUgFnA&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=1qL6CdUgFnA\">https:\/\/www.youtube.com\/watch?v=1qL6CdUgFnA<\/a><\/video><\/div>\n<p>Source : VR-World<\/p>","protected":false},"excerpt":{"rendered":"Wie jetzt bekannt gegeben wurde, wird Aspyr Media das d\u00fcstere Sci-Fi-Mystery-Game &#8222;Torn&#8220; am 28. August 2018 f\u00fcr PlayStation&hellip;","protected":false},"author":11,"featured_media":10917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-10916","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-games","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2018\/07\/25\/vr-mystery-game-torn-termin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Wie jetzt bekannt gegeben wurde, wird Aspyr Media das d\u00fcstere Sci-Fi-Mystery-Game &#8222;Torn&#8220; am 28. August 2018 f\u00fcr PlayStation&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2018\/07\/25\/vr-mystery-game-torn-termin\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-25T07:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"VR-Mystery-Game Torn hat Termin\",\"datePublished\":\"2018-07-25T07:54:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/\"},\"wordCount\":169,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Torn.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/\",\"name\":\"VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Torn.jpg\",\"datePublished\":\"2018-07-25T07:54:14+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Torn.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Torn.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/it\\\/2018\\\/07\\\/25\\\/vr-mystery-game-torn-termin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR-Mystery-Game Torn hat Termin\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2018\/07\/25\/vr-mystery-game-torn-termin\/","og_locale":"fr_FR","og_type":"article","og_title":"VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News","og_description":"Wie jetzt bekannt gegeben wurde, wird Aspyr Media das d\u00fcstere Sci-Fi-Mystery-Game &#8222;Torn&#8220; am 28. August 2018 f\u00fcr PlayStation&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2018\/07\/25\/vr-mystery-game-torn-termin\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-07-25T07:54:14+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Michael","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"VR-Mystery-Game Torn hat Termin","datePublished":"2018-07-25T07:54:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/"},"wordCount":169,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg","articleSection":["Games"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/","url":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/","name":"VR-Mystery-Game Torn hat Termin - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg","datePublished":"2018-07-25T07:54:14+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/Torn.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/it\/2018\/07\/25\/vr-mystery-game-torn-termin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR-Mystery-Game Torn hat Termin"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"http:\/\/vr-room.ch\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/10916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=10916"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/10916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/10917"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=10916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=10916"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=10916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}