{"id":10686,"date":"2018-07-13T06:08:40","date_gmt":"2018-07-13T06:08:40","guid":{"rendered":"http:\/\/vr-room.ch\/?p=10686"},"modified":"2018-07-09T11:27:56","modified_gmt":"2018-07-09T11:27:56","slug":"serious-games-so-macht-lernen-spass","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/fr\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/","title":{"rendered":"Serious Games - apprendre en s'amusant"},"content":{"rendered":"<h3 id=\"entscheidungstraeger-in-unternehmen-erkennen-langsam-aber-sicher-das-potenzial-von-serious-applied-games-spiele-die-nicht-nur-spass-machen-sondern-auch-wissen-vermitteln-erf\">Entscheidungstr\u00e4ger in Unternehmen \u00aderkennen langsam aber sicher das Potenzial von Serious\u00a0&amp; Applied Games. Spiele, die nicht nur Spass \u00admachen, sondern auch Wissen vermitteln, erfreuen sich zunehmender Beliebtheit &#8211; auch in der Schweiz.<\/h3>\n<p><!--more--><\/p>\n<p>Auch der Bundesrat findet das Gamen toll:\u00a0Er schrieb im M\u00e4rz in einem Bericht, dass die Spiele f\u00fcr p\u00e4dagogische und therapeutische Zwecke oder zu Trainingszwecken eingesetzt werden k\u00f6nnten \u2013 insbesondere im Milit\u00e4r.<\/p>\n<p>Spiele k\u00f6nnen demnach nicht nur Spass machen, sondern auch informativ und bildend sein. Die Fachwelt kennt daf\u00fcr den Begriff &#8222;Serious Games&#8220; oder &#8222;Serious &amp; Applied Games&#8220;, wie sie die Z\u00fcrcher Hochschule der K\u00fcnste (ZHdK) nennt. Diese besch\u00e4ftigt sich in der gleichnamigen Fachrichtung mit der Funktions- und Wirkungsweise von Spielen im kulturellen oder wissenschaftlichen Kontext.\u00a0Vor allem die Pharmaindustrie, Energie- und Elektrizit\u00e4tswerke, Medienunternehmen und Universit\u00e4ten w\u00fcrden sich f\u00fcr Serious Games und die Themen Mitwirkung und Gamification interessieren.<\/p>\n<h3 id=\"was-ein-gutes-serious-game-auszeichnet\"><span class=\"char char_$ID\/[No_character_style]\">Was ein gutes Serious Game auszeichnet<\/span><\/h3>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">&#8222;Von einem &#8218;guten&#8216; Serious Game f\u00fchlt man sich weder gelangweilt noch \u00fcberfordert&#8220;, sagt Philomena Schwab, Mitgr\u00fcnderin des Schweizer Game-Unternehmens <a href=\"https:\/\/strayfawnstudio.com\">Stray Fawn Studio<\/a>. Serious Games entwickelt in der Schweiz etwa das Brugger Unternehmen <a href=\"https:\/\/www.koboldgames.ch\">Koboldgames<\/a>. &#8222;Ein gutes Serious Game sollte Spass machen, motivationssteigernd sein und einen Wissenstransfer gew\u00e4hrleisten&#8220;, sagt Mitgr\u00fcnderin Yasemin G\u00fcnay. &#8222;Spiel und Lernen sind dabei ineinander verwoben und sollten einen Flow bilden.&#8220;\u00a0Bei Auftragsarbeiten sei aber nicht der Spieler der Auftraggeber. Man d\u00fcrfe darum trotz Anweisungen der Kunden die W\u00fcnsche der Zielgruppe nie aus den Augen verlieren. &#8222;Bei einem Serious Game handelt es sich oft um ein massgeschneidertes Produkt&#8220;, erkl\u00e4rt G\u00fcnay weiter.\u00a0<\/span><\/p>\n<h3 id=\"gamer-in-der-teppichetage\" class=\"para para_Zwischentitel\"><span class=\"char char_$ID\/[No_character_style]\">Gamer in der Teppichetage<\/span><\/h3>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">&#8222;Wir nehmen ein steigendes Interesse wahr, Games als Medium in allt\u00e4glichen Situationen einzusetzen&#8220;, sagt G\u00fcnay. Das habe wohl auch damit zu tun, dass immer mehr Entscheidungstr\u00e4ger in Unternehmen mit Games aufgewachsen und darum dem Medium gegen\u00fcber aufgeschlossen seien. Ausserdem w\u00fcrden es Firmen zunehmend verstehen, ihre Marken mithilfe von Games innovativ zu pr\u00e4sentieren. In der Gesellschaft gebe es zwar immer noch Vorurteile gegen Gamer, aber auch das \u00e4ndere sich. <\/span><\/p>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">Studien zeigen, dass mittlerweile sogar mehr Frauen als M\u00e4nner gamen &#8211; und dies online mit dem Smartphone. Denkt man nur an Candy Crush und diese Geschichten. So ist zum Beispiel auch die Agentur <a href=\"https:\/\/www.responsive.ag\">Responsive AG<\/a> \u00fcberzeugt, dass Konsumenten mit VR Erlebnissen am einfachsten lernen.\u00a0<\/span>Patrik Marty, Managing Partner von Responsive ist \u00fcberzeugt: \u201eDurch die totale Immersion, also das Eintauchen in diese hoch detaillierte 360\u00b0 Welt, bleibt das Erlebte stark in Erinnerung. Wir versuchen stets m\u00f6glichst viele Sinne anzusprechen und den Spass mit Interaktionen zu erh\u00f6hen, um die Botschaft des Kunden m\u00f6glichst effektiv zu kommunizieren. Die VR ist das beste Instrument, um Personen, ob jung oder alt, zu involvieren. So ist die Responsive AG auch\u00a0eine von\u00a0wenigen Firmen in der Schweiz, die sich haupts\u00e4chlich der Entwicklung von hoch involvierenden online und VR Promotionen widmen.<\/p>\n<h3 id=\"aller-anfang-ist-schwer\" class=\"para para_Zwischentitel\"><span class=\"char char_$ID\/[No_character_style]\">Aller Anfang ist schwer<\/span><\/h3>\n<p class=\"para para_$ID\/NormalParagraphStyle\"><span class=\"char char_$ID\/[No_character_style]\">&#8222;F\u00fcr uns l\u00e4uft es im Moment recht gut&#8220;, antwortet G\u00fcnay auf die Frage, wie schwierig es sei, in der Schweiz mit Serious Games seinen Lebensunterhalt zu finanzieren. Es sei aber sehr zeitintensiv, sich einen Kundenstamm aufzubauen. &#8222;Es braucht ein gutes Bewusstsein \u00fcber potenzielle Kunden, und wie man diese mit Marketing erreichen kann.&#8220; Und sehr viel Leidenschaft. Ausserdem helfe es, sich gleich zu Beginn Unterst\u00fctzung zu holen. Pro Helvetia etwa investiere viel in die hiesige Game-Szene, und MMOS erhalte Unterst\u00fctzung von der Universit\u00e4t Genf.<\/span><\/p>\n<p class=\"para para_$ID\/NormalParagraphStyle\">Quelle: Netzwoche \/ Medienmitteilung Responsive<\/p>\n","protected":false},"excerpt":{"rendered":"Les d\u00e9cideurs en entreprise reconnaissent lentement mais s\u00fbrement le potentiel des Serious &amp; Applied Games. Des jeux qui ne sont pas seulement amusants...","protected":false},"author":12,"featured_media":10687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-10686","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/fr\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Entscheidungstr\u00e4ger in Unternehmen \u00aderkennen langsam aber sicher das Potenzial von Serious\u00a0&amp; Applied Games. Spiele, die nicht nur Spass&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/fr\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-13T06:08:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Serious Games \u2013 so macht Lernen Spass\",\"datePublished\":\"2018-07-13T06:08:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/\"},\"wordCount\":591,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/serious-games.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/\",\"name\":\"Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/serious-games.jpg\",\"datePublished\":\"2018-07-13T06:08:40+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/serious-games.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/serious-games.jpg\",\"width\":1536,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/2018\\\/07\\\/13\\\/serious-games-so-macht-lernen-spass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serious Games \u2013 so macht Lernen Spass\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/fr\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/","og_locale":"fr_FR","og_type":"article","og_title":"Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News","og_description":"Entscheidungstr\u00e4ger in Unternehmen \u00aderkennen langsam aber sicher das Potenzial von Serious\u00a0&amp; Applied Games. Spiele, die nicht nur Spass&hellip;","og_url":"https:\/\/vr-room.ch\/fr\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2018-07-13T06:08:40+00:00","og_image":[{"width":1536,"height":864,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathalie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Serious Games \u2013 so macht Lernen Spass","datePublished":"2018-07-13T06:08:40+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/"},"wordCount":591,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg","articleSection":["Schweiz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/","url":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/","name":"Serious Games \u2013 so macht Lernen Spass - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg","datePublished":"2018-07-13T06:08:40+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2018\/07\/serious-games.jpg","width":1536,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/2018\/07\/13\/serious-games-so-macht-lernen-spass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Serious Games \u2013 so macht Lernen Spass"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Nouvelles de la r\u00e9alit\u00e9 virtuelle suisse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/fr\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/10686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/comments?post=10686"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/posts\/10686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media\/10687"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/media?parent=10686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/categories?post=10686"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/fr\/wp-json\/wp\/v2\/tags?post=10686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}