{"id":8687,"date":"2017-12-05T06:34:07","date_gmt":"2017-12-05T06:34:07","guid":{"rendered":"http:\/\/vr-room.ch\/?p=8687"},"modified":"2017-12-01T11:55:50","modified_gmt":"2017-12-01T11:55:50","slug":"kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/","title":{"rendered":"Kremer Museum: An art museum in virtual reality"},"content":{"rendered":"<h3 id=\"der-niederlaendische-kunstsammler-george-kremer-liess-vom-architekten-johan-van-lierop-ein-museum-fuer-vr-entwerfen-darin-duerfen-user-eine-sammlung-von-74-alten-hollaendischen-und-flaemischen-meiste\">Dutch art collector George Kremer commissioned architect Johan van Lierop to design a museum for VR. Inside, users can admire a collection of 74 old Dutch and Flemish masterpieces.<\/h3>\n<p><!--more--><\/p>\n<p>How do you get more people to visit a museum? Dutch art collector George Kremer knows how: With VR, of course. The initial plan was to build a real museum, but the decision was made in favour of the virtual solution because the advantages simply outweighed the disadvantages. Visitors can now marvel at the first virtual Kremer Museum at any time and from anywhere in the world.<\/p>\n<h3 id=\"wenn-vater-und-sohn-gemeinsam-hand-anlegen\">When father and son work together<\/h3>\n<p>George Kremer's son was also an important co-developer. Jo\u00ebl, a former Google employee, contributed his technical expertise to the project. His father, on the other hand, contributed the collection, which has been built up over 20 years and contains a total of 74 old Dutch and Flemish masterpieces. It's marvellous how two generations can work together like this.<\/p>\n<p>According to the architect Johan van Lierop, who designed the museum building, it was also a liberating experience for him to be able to build such an object without regard to physics and legal regulations.<\/p>\n<p>A completely new way to experience art. You can get a brief insight in the video clip:<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=lvrB3nvs7xU&#038;feature=youtu.be<\/p>\n<p>Source: VRNerds<\/p>","protected":false},"excerpt":{"rendered":"The Dutch art collector George Kremer had the architect Johan van Lierop design a museum for VR. In it may...","protected":false},"author":12,"featured_media":8688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8687","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-kunst","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Der niederl\u00e4ndische Kunstsammler George Kremer liess vom Architekten Johan van Lierop ein Museum f\u00fcr VR entwerfen. Darin d\u00fcrfen&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-05T06:34:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t\",\"datePublished\":\"2017-12-05T06:34:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/\"},\"wordCount\":238,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg\",\"articleSection\":[\"Kunst\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/\",\"name\":\"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg\",\"datePublished\":\"2017-12-05T06:34:07+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg\",\"width\":1024,\"height\":716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/en\\\/2017\\\/12\\\/05\\\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/","og_locale":"en_GB","og_type":"article","og_title":"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News","og_description":"Der niederl\u00e4ndische Kunstsammler George Kremer liess vom Architekten Johan van Lierop ein Museum f\u00fcr VR entwerfen. Darin d\u00fcrfen&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-12-05T06:34:07+00:00","og_image":[{"width":1024,"height":716,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t","datePublished":"2017-12-05T06:34:07+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/"},"wordCount":238,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg","articleSection":["Kunst"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/","url":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/","name":"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg","datePublished":"2017-12-05T06:34:07+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/12\/xkremer-museum-htc-vive-1024x716.jpg.pagespeed.ic_.rleylRsvg2.jpg","width":1024,"height":716},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/en\/2017\/12\/05\/kremer-museum-ein-kunstmuseum-in-der-virtuellen-realitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Kremer Museum: Ein Kunstmuseum in der virtuellen Realit\u00e4t"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=8687"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/8688"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=8687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=8687"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=8687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}