{"id":8002,"date":"2017-10-20T07:33:28","date_gmt":"2017-10-20T07:33:28","guid":{"rendered":"http:\/\/vr-room.ch\/?p=8002"},"modified":"2017-10-20T07:33:28","modified_gmt":"2017-10-20T07:33:28","slug":"vr-spiel-playerunknowns-battlegrounds","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/en\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/","title":{"rendered":"VR game like PlayerUnknown's Battlegrounds"},"content":{"rendered":"<p><a href=\"http:\/\/store.steampowered.com\/app\/578080\/PLAYERUNKNOWNS_BATTLEGROUNDS\/\">&#8222;PlayerUnknown&#8217;s Battlegrounds&#8220;<\/a> is currently enjoying huge success on the PC, breaking one record after another. So it's hardly surprising that other developers are also taking the <a href=\"https:\/\/en.wikipedia.org\/wiki\/Battle_royale_game\">&#8222;Battle Royale&#8220;-Genre<\/a> take up. It even goes into virtual reality.<\/p>\n<p>Oneiric Entertainment hat jetzt quasi eine VR-Version von &#8222;PlayerUnknown&#8217;s Battlegrounds&#8220; angek\u00fcndigt. Dabei handelt es sich um <a href=\"https:\/\/www.reddit.com\/r\/Vive\/comments\/77evc2\/you_asked_for_a_battle_royale_vr_game_youre\/\">&#8222;Virtual Battlegrounds&#8220;<\/a>which will be playable with HTC Vive and Oculus Rift next year (presumably as an early access beta version).<\/p>\n<p>Das erste Gameplay-Video, das \u00fcbrigens aus einem sehr fr\u00fchen Stadium der Entwicklung stammt, zeigt, dass &#8222;Virtual Battlegrounds&#8220; eigentlich alles hat, was in ein &#8222;Battle Royale&#8220;-Spiel geh\u00f6rt. Da VR-Headsets allerdings noch nicht so verbreitet sind, werden zun\u00e4chst nur 16 Spieler unterst\u00fctzt, so der Creative Director Sean Pinnock, doch sp\u00e4ter k\u00f6nnten es mehr werden.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-8002-1\" width=\"640\" height=\"360\" loop preload=\"metadata\" controls=\"controls\"><source type=\"video\/youtube\" src=\"https:\/\/www.youtube.com\/watch?v=tfNh0JAtSjo&#038;_=1\" \/><a href=\"https:\/\/www.youtube.com\/watch?v=tfNh0JAtSjo\">https:\/\/www.youtube.com\/watch?v=tfNh0JAtSjo<\/a><\/video><\/div>\n<p>Source: <a href=\"https:\/\/www.gamespot.com\/articles\/theres-a-pubg-style-vr-game-in-the-works\/1100-6454225\/\">Gamespot<\/a><\/p>","protected":false},"excerpt":{"rendered":"&#8222;PlayerUnknown&#8217;s Battlegrounds&#8220; feiert auf dem PC momentan einen riesigen Erfolg und bricht einen Rekord nach dem anderen. Da&hellip;","protected":false},"author":11,"featured_media":8004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-8002","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-virtual-reality-games","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR-Spiel wie PlayerUnknown&#039;s Battlegrounds - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vr-room.ch\/en\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR-Spiel wie PlayerUnknown&#039;s Battlegrounds - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"&#8222;PlayerUnknown&#8217;s Battlegrounds&#8220; feiert auf dem PC momentan einen riesigen Erfolg und bricht einen Rekord nach dem anderen. Da&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vr-room.ch\/en\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-20T07:33:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"headline\":\"VR-Spiel wie PlayerUnknown&#8217;s Battlegrounds\",\"datePublished\":\"2017-10-20T07:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/\"},\"wordCount\":159,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VirtualBattlegrounds.jpg\",\"articleSection\":[\"Games\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/\",\"name\":\"VR-Spiel wie PlayerUnknown's Battlegrounds - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VirtualBattlegrounds.jpg\",\"datePublished\":\"2017-10-20T07:33:28+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VirtualBattlegrounds.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/VirtualBattlegrounds.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/10\\\/20\\\/vr-spiel-playerunknowns-battlegrounds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR-Spiel wie PlayerUnknown&#8217;s Battlegrounds\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/4022b4e1fba06681ac263b25c0f1e3d2\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_11_1558711168-96x96.jpg\",\"caption\":\"Michael\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR-Spiel wie PlayerUnknown's Battlegrounds - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vr-room.ch\/en\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/","og_locale":"en_GB","og_type":"article","og_title":"VR-Spiel wie PlayerUnknown's Battlegrounds - Schweizer Virtual Reality News","og_description":"&#8222;PlayerUnknown&#8217;s Battlegrounds&#8220; feiert auf dem PC momentan einen riesigen Erfolg und bricht einen Rekord nach dem anderen. Da&hellip;","og_url":"https:\/\/vr-room.ch\/en\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-10-20T07:33:28+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michael","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#article","isPartOf":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/"},"author":{"name":"Michael","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"headline":"VR-Spiel wie PlayerUnknown&#8217;s Battlegrounds","datePublished":"2017-10-20T07:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/"},"wordCount":159,"commentCount":0,"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg","articleSection":["Games"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/","url":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/","name":"VR-Spiel wie PlayerUnknown's Battlegrounds - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#primaryimage"},"image":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg","datePublished":"2017-10-20T07:33:28+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2"},"breadcrumb":{"@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/10\/VirtualBattlegrounds.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/vr-room.ch\/fr\/2017\/10\/20\/vr-spiel-playerunknowns-battlegrounds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR-Spiel wie PlayerUnknown&#8217;s Battlegrounds"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/4022b4e1fba06681ac263b25c0f1e3d2","name":"Michael","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2019\/05\/avatar_user_11_1558711168-96x96.jpg","caption":"Michael"},"url":"http:\/\/vr-room.ch\/en\/author\/michael\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=8002"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/8002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/8004"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=8002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=8002"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=8002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}