{"id":5705,"date":"2017-06-15T07:25:41","date_gmt":"2017-06-15T07:25:41","guid":{"rendered":"http:\/\/vr-room.ch\/?p=5705"},"modified":"2017-06-06T07:45:07","modified_gmt":"2017-06-06T07:45:07","slug":"vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/en\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/","title":{"rendered":"VR app shows kids how to stay safe in road traffic"},"content":{"rendered":"<p>According to the University of South Wales (USW), the <a href=\"http:\/\/www.bbc.com\/news\/uk-wales-south-east-wales-39892030\">BBC<\/a> a highly engaging VR app - comparable to Pok\u00e9mon Go, which aims to teach school children about the dangers of road traffic in a safe environment. With the app on their tablet, the little ones learn where, how and when it is safe to cross a road. If they do it well, they win points.<\/p>\n<p>A preliminary study has shown that children learn better in a first-person perspective than with flat image or video material. The university has received \u00a367,500 from the Road Safety Trust for the project.  It will be a few months before the launch. The roll-out is planned for next January.<\/p>\n<p>Source: BBC, Flicker<\/p>","protected":false},"excerpt":{"rendered":"The University of South Wales (USW) is developing a highly involving VR app - comparable to Pok\u00e9mon Go, according to the BBC....","protected":false},"author":12,"featured_media":5706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-5705","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/en\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Die University of South Wales (USW) entwickelt gem\u00e4ss BBC eine hoch involvierende VR-Applikation \u2013 vergleichbar mit Pok\u00e9mon Go,&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/en\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-15T07:25:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen\",\"datePublished\":\"2017-06-15T07:25:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/\"},\"wordCount\":124,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Verkehr-VR-App-scaled.jpg\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/\",\"name\":\"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Verkehr-VR-App-scaled.jpg\",\"datePublished\":\"2017-06-15T07:25:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Verkehr-VR-App-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Verkehr-VR-App-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/fr\\\/2017\\\/06\\\/15\\\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/en\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/","og_locale":"en_GB","og_type":"article","og_title":"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News","og_description":"Die University of South Wales (USW) entwickelt gem\u00e4ss BBC eine hoch involvierende VR-Applikation \u2013 vergleichbar mit Pok\u00e9mon Go,&hellip;","og_url":"http:\/\/vr-room.ch\/en\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2017-06-15T07:25:41+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg","type":"image\/jpeg"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen","datePublished":"2017-06-15T07:25:41+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/"},"wordCount":124,"commentCount":0,"image":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg","articleSection":["Schweiz"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/","url":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/","name":"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg","datePublished":"2017-06-15T07:25:41+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/05\/Verkehr-VR-App-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/fr\/2017\/06\/15\/vr-app-zeigt-kids-wie-sie-sich-im-strassenverkehr-sicher-bewegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"VR App zeigt Kids, wie sie sich im Strassenverkehr sicher bewegen"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/5705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=5705"}],"version-history":[{"count":0,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/5705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/5706"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=5705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=5705"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=5705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}