{"id":21211,"date":"2023-03-27T16:33:22","date_gmt":"2023-03-27T16:33:22","guid":{"rendered":"https:\/\/vr-room.ch\/?p=21211"},"modified":"2023-03-15T16:43:12","modified_gmt":"2023-03-15T16:43:12","slug":"im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig","status":"publish","type":"post","link":"http:\/\/vr-room.ch\/en\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/","title":{"rendered":"The teddy bear comes to life at the Spielzeug Welten Museum in Basel"},"content":{"rendered":"<h3 id=\"im-spielzeug-welten-museum-in-basel-werden-ausstellungsstuecke-virtuell-lebendig-die-sonderausstellung-mirt-dem-namen-spielen-macht-sinn-laeuft-bis-ende-oktober\" class=\"id-StoryElement-paragraph\">At <a href=\"https:\/\/www.spielzeug-welten-museum-basel.ch\/de\/?gclid=Cj0KCQjw2cWgBhDYARIsALggUhqKEJsftEWCs19QSxUw9dXcC7Pq99DrIAMUZ0201M1srkoKW52pkdAaAr1uEALw_wcB\">Toy Worlds Museum<\/a> in Basel, exhibits come to life virtually. The special exhibition entitled \"Playing makes sense\" runs until the end of October.<\/h3>\n<div class=\"id-StoryElement-beepWrap\">\n<div id=\"trf_ad_desktop_news_fixed_after_count_3_92135238_content_2_idx_11\" class=\"Content_2 trf-center-container trf-declaration-container\" data-google-query-id=\"CMPAiqau3v0CFayFgwcdloELyQ\">\n<div id=\"google_ads_iframe_\/307308315,5176\/idan.merkur.de\/travel_3__container__\">\n<div class=\"content_element\">\n<div class=\"mod_text\">\n<p>The Toy Worlds Museum Basel is celebrating its 25th anniversary this year. To mark the occasion, the doll's houses, bears and shops are being brought to life with innovative technology: In an augmented reality, a digitally enriched reality, animated figures provide completely new insights into the museum's toy worlds. The anniversary exhibition, which opens on 18 March with a vernissage for young and old, is dedicated entirely to play: Children have always played and will always play - an average of 15,000 hours by the age of six. And that's a good thing: Through play, we learn numerous skills that we need in order to lead an independent life later on. So playing is more than just fun. Playing makes sense.<\/p>\n<\/div>\n<\/div>\n<div class=\"content_element\">\n<div class=\"mod_text\">\n<h3 id=\"animierte-erzaehltour-geschichten-aus-der-spielzeugwelt\"><b>Animated storytelling tour: Stories from the world of toys<\/b><\/h3>\n<p>A teddy bear tells the story of its adventurous origins, a Basel flour soup steams in the cooking pot of the doll's house and even the Titanic sails past: the unique collection of the Toy Worlds Museum Basel comes to life. Visitors use a tablet to see how the museum objects on display develop a life of their own. Together with virtual figures, they playfully provide new insights into a wide variety of topics.<\/p>\n<p>The additional children's track lets zeppelins fly through the room, tennis balls bounce through the air and notes dance towards you from the gramophone.<\/p>\n<h3 id=\"begleitprogramm\"><b>Accompanying programme<\/b><\/h3>\n<p>The highlight is the big party to celebrate the 25th birthday of the Toy Worlds Museum Basel on 27 August 2023, which will include various games, a wide range of craft activities and a photo box, as well as a competition: Anyone who turns up to the party in a costume that matches the museum can take part. The 25 most imaginative costumes will be honoured.<\/p>\n<p><a title=\"Opens internal link in current window\" href=\"https:\/\/www.spielzeug-welten-museum-basel.ch\/de\/veranstaltungen\/anlaesse\/programm-zur-sonderausstellung-spielen-macht-sinn\/\">Link to the accompanying programme<\/a><\/p>\n<p>The exhibition and even AR Tour are trilingual: German, English, French<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Source: Toy Museum<\/p>","protected":false},"excerpt":{"rendered":"In the Toy World Museum in Basel, exhibits come to life virtually. The special exhibition called \"Playing makes sense\" runs...","protected":false},"author":12,"featured_media":21212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-21211","post","type-post","status-publish","format-standard","has-post-thumbnail","category-virtual-reality-schweiz","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vr-room.ch\/en\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News\" \/>\n<meta property=\"og:description\" content=\"Im Spielzeug Welten-Museum in Basel werden Ausstellungsst\u00fccke virtuell lebendig. Die Sonderausstellung mirt dem Namen \u00abSpielen macht Sinn\u00bb l\u00e4uft&hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vr-room.ch\/en\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/\" \/>\n<meta property=\"og:site_name\" content=\"Schweizer Virtual Reality News\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T16:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1623\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathalie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathalie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/\"},\"author\":{\"name\":\"Nathalie\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"headline\":\"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig\",\"datePublished\":\"2023-03-27T16:33:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/\"},\"wordCount\":323,\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png\",\"articleSection\":[\"Schweiz\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/\",\"name\":\"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png\",\"datePublished\":\"2023-03-27T16:33:22+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png\",\"width\":1623,\"height\":687,\"caption\":\"spielzeug\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/it\\\/2023\\\/03\\\/27\\\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/\",\"name\":\"Schweizer Virtual Reality News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/#\\\/schema\\\/person\\\/1a03b3a6ced429fb4831f60fa2b37599\",\"name\":\"Nathalie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"url\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/vr-room.ch\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/avatar_user_12_1484159890-96x96.jpg\",\"caption\":\"Nathalie\"},\"url\":\"http:\\\/\\\/vr-room.ch\\\/en\\\/author\\\/nathalie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vr-room.ch\/en\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/","og_locale":"en_GB","og_type":"article","og_title":"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News","og_description":"Im Spielzeug Welten-Museum in Basel werden Ausstellungsst\u00fccke virtuell lebendig. Die Sonderausstellung mirt dem Namen \u00abSpielen macht Sinn\u00bb l\u00e4uft&hellip;","og_url":"http:\/\/vr-room.ch\/en\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/","og_site_name":"Schweizer Virtual Reality News","article_published_time":"2023-03-27T16:33:22+00:00","og_image":[{"width":1623,"height":687,"url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png","type":"image\/png"}],"author":"Nathalie","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nathalie","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#article","isPartOf":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/"},"author":{"name":"Nathalie","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"headline":"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig","datePublished":"2023-03-27T16:33:22+00:00","mainEntityOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/"},"wordCount":323,"image":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png","articleSection":["Schweiz"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/","url":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/","name":"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig - Schweizer Virtual Reality News","isPartOf":{"@id":"http:\/\/vr-room.ch\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#primaryimage"},"image":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#primaryimage"},"thumbnailUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png","datePublished":"2023-03-27T16:33:22+00:00","author":{"@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599"},"breadcrumb":{"@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#primaryimage","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-15-at-17-39-12-Spielen-macht-Sinn.png","width":1623,"height":687,"caption":"spielzeug"},{"@type":"BreadcrumbList","@id":"http:\/\/vr-room.ch\/it\/2023\/03\/27\/im-spielzeug-welten-museum-in-basel-wird-der-teddybaeren-lebendig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/vr-room.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Im Spielzeug Welten-Museum in Basel wird der Teddyb\u00e4ren lebendig"}]},{"@type":"WebSite","@id":"http:\/\/vr-room.ch\/en\/#website","url":"http:\/\/vr-room.ch\/en\/","name":"Swiss Virtual Reality News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/vr-room.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"http:\/\/vr-room.ch\/en\/#\/schema\/person\/1a03b3a6ced429fb4831f60fa2b37599","name":"Nathalie","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","url":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","contentUrl":"https:\/\/vr-room.ch\/wp-content\/uploads\/2017\/01\/avatar_user_12_1484159890-96x96.jpg","caption":"Nathalie"},"url":"http:\/\/vr-room.ch\/en\/author\/nathalie\/"}]}},"_links":{"self":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/21211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/comments?post=21211"}],"version-history":[{"count":1,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/21211\/revisions"}],"predecessor-version":[{"id":21213,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/posts\/21211\/revisions\/21213"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media\/21212"}],"wp:attachment":[{"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/media?parent=21211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/categories?post=21211"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vr-room.ch\/en\/wp-json\/wp\/v2\/tags?post=21211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}